{"id":165445,"date":"2026-05-12T09:31:55","date_gmt":"2026-05-12T09:31:55","guid":{"rendered":"https:\/\/coinpoker.com\/ru\/help\/%d1%87%d0%b0%d1%81%d1%82%d0%be-%d0%b7%d0%b0%d0%b4%d0%b0%d0%b2%d0%b0%d0%b5%d0%bc%d1%8b%d0%b5-%d0%b2%d0%be%d0%bf%d1%80%d0%be%d1%81%d1%8b-%d0%be-%d0%b4%d0%b5%d0%bf%d0%be%d0%b7%d0%b8%d1%82%d0%b0%d1%85\/"},"modified":"2026-05-12T10:43:05","modified_gmt":"2026-05-12T10:43:05","slug":"deposits-faq","status":"publish","type":"help","link":"https:\/\/coinpoker.com\/ru\/help\/deposits-faq\/","title":{"rendered":"\u0427\u0430\u0441\u0442\u043e \u0437\u0430\u0434\u0430\u0432\u0430\u0435\u043c\u044b\u0435 \u0432\u043e\u043f\u0440\u043e\u0441\u044b \u043e \u0434\u0435\u043f\u043e\u0437\u0438\u0442\u0430\u0445"},"content":{"rendered":"\n<div id=\"coinpoker-accordion-block_6835f3aea29c271827d7a2b38fefef1d\" class=\"coinpoker-accordion\" role=\"region\" aria-label=\"Accordion content\">\n        <div class=\"cp-accordion\" id=\"accordion-6a03d8aee349a\">\n                    <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8aee349a-collapse-1\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8aee349a-collapse-1\"\n                        id=\"accordion-6a03d8aee349a-heading-1\">\n                    <div class=\"cp-accordion-heading-text\">\u041a\u0430\u043a \u0432\u043d\u0435\u0441\u0442\u0438 \u0434\u0435\u043f\u043e\u0437\u0438\u0442 \u043d\u0430 \u0441\u0432\u043e\u0439 \u0441\u0447\u0435\u0442 \u0432 CoinPoker?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8aee349a-collapse-1\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8aee349a-heading-1\"\n                     data-cp-parent=\"#accordion-6a03d8aee349a\">\n                    <div class=\"cp-accordion-body\">\n                        <p>\u0412\u043e\u0442 \u043a\u0430\u043a \u0432\u043d\u0435\u0441\u0442\u0438 \u0434\u0435\u043f\u043e\u0437\u0438\u0442 \u043d\u0430 CoinPoker:<\/p>\n<ul>\n<li>\u0417\u0430\u0439\u0434\u0438\u0442\u0435 \u0432 \u0441\u0432\u043e\u0439 \u043a\u043e\u0448\u0435\u043b\u0435\u043a.<\/li>\n<li>\u041d\u0430\u0436\u043c\u0438\u0442\u0435 \u00ab\u041f\u043e\u043f\u043e\u043b\u043d\u0438\u0442\u044c \u0441\u0447\u0435\u0442\u00bb.<\/li>\n<li>\u0412\u044b\u0431\u0435\u0440\u0438\u0442\u0435 \u043a\u0440\u0438\u043f\u0442\u043e\u0432\u0430\u043b\u044e\u0442\u0443, \u0431\u0430\u043d\u043a\u043e\u0432\u0441\u043a\u0443\u044e \u043a\u0430\u0440\u0442\u0443 \u0438\u043b\u0438 Luxon Pay.<\/li>\n<li>\u0412\u044b\u0431\u0435\u0440\u0438\u0442\u0435 \u0431\u043e\u043d\u0443\u0441 \u0438 \u0432\u0432\u0435\u0434\u0438\u0442\u0435 \u0441\u0443\u043c\u043c\u0443, \u043a\u043e\u0442\u043e\u0440\u0443\u044e \u0445\u043e\u0442\u0438\u0442\u0435 \u0432\u043d\u0435\u0441\u0442\u0438.<\/li>\n<li>\u041f\u0440\u043e\u0432\u0435\u0440\u044c\u0442\u0435 \u0434\u0430\u043d\u043d\u044b\u0435.<\/li>\n<li>\u0415\u0441\u043b\u0438 \u0432\u044b \u0438\u0441\u043f\u043e\u043b\u044c\u0437\u0443\u0435\u0442\u0435 \u043a\u0440\u0438\u043f\u0442\u043e\u0432\u0430\u043b\u044e\u0442\u0443, \u043e\u0442\u043f\u0440\u0430\u0432\u044c\u0442\u0435 \u0441\u0443\u043c\u043c\u0443 \u0434\u0435\u043f\u043e\u0437\u0438\u0442\u0430 \u043d\u0430 \u0430\u0434\u0440\u0435\u0441, \u0443\u043a\u0430\u0437\u0430\u043d\u043d\u044b\u0439 \u043d\u0430 \u044d\u043a\u0440\u0430\u043d\u0435. \u0415\u0441\u043b\u0438 \u0432\u044b \u043e\u043f\u043b\u0430\u0447\u0438\u0432\u0430\u0435\u0442\u0435 \u0431\u0430\u043d\u043a\u043e\u0432\u0441\u043a\u043e\u0439 \u043a\u0430\u0440\u0442\u043e\u0439 \u0438\u043b\u0438 \u0447\u0435\u0440\u0435\u0437 Luxon Pay, \u0432\u044b\u0431\u0435\u0440\u0438\u0442\u0435 \u00ab\u041f\u0435\u0440\u0435\u0439\u0442\u0438 \u043a \u0431\u0435\u0437\u043e\u043f\u0430\u0441\u043d\u043e\u0439 \u043e\u043f\u043b\u0430\u0442\u0435\u00bb \u0438 \u0432\u044b\u043f\u043e\u043b\u043d\u0438\u0442\u0435 \u0432\u0441\u0435 \u043d\u0435\u043e\u0431\u0445\u043e\u0434\u0438\u043c\u044b\u0435 \u0434\u0435\u0439\u0441\u0442\u0432\u0438\u044f.<\/li>\n<\/ul>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8aee349a-collapse-2\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8aee349a-collapse-2\"\n                        id=\"accordion-6a03d8aee349a-heading-2\">\n                    <div class=\"cp-accordion-heading-text\">\u041a\u0430\u043a\u0438\u0435 \u0441\u043f\u043e\u0441\u043e\u0431\u044b \u043e\u043f\u043b\u0430\u0442\u044b \u0434\u043e\u0441\u0442\u0443\u043f\u043d\u044b \u0434\u043b\u044f \u043f\u043e\u043f\u043e\u043b\u043d\u0435\u043d\u0438\u044f \u0441\u0447\u0435\u0442\u0430?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8aee349a-collapse-2\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8aee349a-heading-2\"\n                     data-cp-parent=\"#accordion-6a03d8aee349a\">\n                    <div class=\"cp-accordion-body\">\n                        <p>\u0412\u044b \u043c\u043e\u0436\u0435\u0442\u0435 \u043f\u043e\u043f\u043e\u043b\u043d\u0438\u0442\u044c \u0441\u0447\u0435\u0442 \u043d\u0430 CoinPoker \u0441 \u043f\u043e\u043c\u043e\u0449\u044c\u044e \u043b\u044e\u0431\u043e\u0433\u043e \u0438\u0437 \u0441\u043b\u0435\u0434\u0443\u044e\u0449\u0438\u0445 \u0441\u043f\u043e\u0441\u043e\u0431\u043e\u0432 \u043e\u043f\u043b\u0430\u0442\u044b:<\/p>\n<ul>\n<li>\u041a\u0440\u0438\u043f\u0442\u043e\u0432\u0430\u043b\u044e\u0442\u044b<\/li>\n<li>\u041a\u0440\u0435\u0434\u0438\u0442\u043d\u0430\u044f \u043a\u0430\u0440\u0442\u0430 \u0438\u043b\u0438 \u0434\u0435\u0431\u0435\u0442\u043e\u0432\u0430\u044f \u043a\u0430\u0440\u0442\u0430<\/li>\n<li>Luxon Pay<\/li>\n<\/ul>\n<p>\u0415\u0441\u043b\u0438 \u0432\u0430\u043c \u043f\u043e\u0442\u0440\u0435\u0431\u0443\u0435\u0442\u0441\u044f \u0434\u043e\u043f\u043e\u043b\u043d\u0438\u0442\u0435\u043b\u044c\u043d\u0430\u044f \u043f\u043e\u043c\u043e\u0449\u044c, \u043f\u043e\u0436\u0430\u043b\u0443\u0439\u0441\u0442\u0430, \u043e\u0431\u0440\u0430\u0449\u0430\u0439\u0442\u0435\u0441\u044c \u043f\u043e \u0430\u0434\u0440\u0435\u0441\u0443 support@coinpoker.com.<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                <\/div>\n<\/div>\n\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_redirections_enabled":"","_seopress_redirections_type":"","_seopress_redirections_value":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","editor_notices":[],"_cpsm_do_not_sync":false,"_cpsm_partial_sync":false,"footnotes":""},"topic-category":[435],"class_list":["post-165445","help","type-help","status-publish","hentry","topic-category-deposits"],"acf":{"card_image":null,"help_view":["post_login"],"in_app_mode_link":""},"_links":{"self":[{"href":"https:\/\/coinpoker.com\/ru\/wp-json\/wp\/v2\/help\/165445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coinpoker.com\/ru\/wp-json\/wp\/v2\/help"}],"about":[{"href":"https:\/\/coinpoker.com\/ru\/wp-json\/wp\/v2\/types\/help"}],"version-history":[{"count":1,"href":"https:\/\/coinpoker.com\/ru\/wp-json\/wp\/v2\/help\/165445\/revisions"}],"predecessor-version":[{"id":165446,"href":"https:\/\/coinpoker.com\/ru\/wp-json\/wp\/v2\/help\/165445\/revisions\/165446"}],"wp:attachment":[{"href":"https:\/\/coinpoker.com\/ru\/wp-json\/wp\/v2\/media?parent=165445"}],"wp:term":[{"taxonomy":"topic-category","embeddable":true,"href":"https:\/\/coinpoker.com\/ru\/wp-json\/wp\/v2\/topic-category?post=165445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}