{"id":165302,"date":"2026-05-11T15:13:38","date_gmt":"2026-05-11T15:13:38","guid":{"rendered":"https:\/\/coinpoker.com\/pt\/?post_type=help&#038;p=165302"},"modified":"2026-05-12T11:13:55","modified_gmt":"2026-05-12T11:13:55","slug":"gameplay-technical-faq","status":"publish","type":"help","link":"https:\/\/coinpoker.com\/pt\/help\/gameplay-technical-faq\/","title":{"rendered":"Perguntas frequentes t\u00e9cnicas sobre a jogabilidade"},"content":{"rendered":"\n<div id=\"coinpoker-accordion-block_1db4a6eeb9e36931467d3fa704dd4fdd\" class=\"coinpoker-accordion\" role=\"region\" aria-label=\"Accordion content\">\n        <div class=\"cp-accordion\" id=\"accordion-6a03d8a160dff\">\n                    <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8a160dff-collapse-1\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8a160dff-collapse-1\"\n                        id=\"accordion-6a03d8a160dff-heading-1\">\n                    <div class=\"cp-accordion-heading-text\">Fico sem conex\u00e3o enquanto jogo. O que devo fazer?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8a160dff-collapse-1\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8a160dff-heading-1\"\n                     data-cp-parent=\"#accordion-6a03d8a160dff\">\n                    <div class=\"cp-accordion-body\">\n                        <p>Jogar poker online depende da qualidade e da velocidade da sua conex\u00e3o \u00e0 Internet. Recomendamos que voc\u00ea utilize uma conex\u00e3o de internet est\u00e1vel para desfrutar da melhor experi\u00eancia de jogo na CoinPoker. Por favor, certifique-se de verificar os pontos mencionados abaixo:<\/p>\n<ul>\n<li>Recomendamos uma conex\u00e3o de internet est\u00e1vel de pelo menos 256 Kbps ou mais, com pouca ou nenhuma perda de pacotes e baixa lat\u00eancia em rela\u00e7\u00e3o aos nossos servidores.<\/li>\n<li>Recomendamos que voc\u00ea troque de conex\u00e3o de internet. Por exemplo, se voc\u00ea estiver usando dados m\u00f3veis, mude para o Wi-Fi.<\/li>\n<li>Se voc\u00ea estiver usando Wi-Fi, pedimos que reinicie o roteador.<\/li>\n<li>Se voc\u00ea estiver usando dados m\u00f3veis, pedimos que ative o modo avi\u00e3o e, em seguida, desative-o.<\/li>\n<\/ul>\n<p>Observa\u00e7\u00e3o: Caso voc\u00ea ainda esteja enfrentando esse problema, envie-nos um v\u00eddeo do problema para support@coinpoker.com. Vamos verificar isso imediatamente com a equipe t\u00e9cnica.<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8a160dff-collapse-2\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8a160dff-collapse-2\"\n                        id=\"accordion-6a03d8a160dff-heading-2\">\n                    <div class=\"cp-accordion-heading-text\">N\u00e3o consigo abrir nenhuma mesa. Como fa\u00e7o para resolver isso?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8a160dff-collapse-2\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8a160dff-heading-2\"\n                     data-cp-parent=\"#accordion-6a03d8a160dff\">\n                    <div class=\"cp-accordion-body\">\n                        <p><span style=\"font-weight: 400\">Isso pode ocorrer devido aos motivos abaixo mencionados:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">A sua localiza\u00e7\u00e3o n\u00e3o permite jogar na CoinPoker.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Voc\u00ea est\u00e1 jogando usando um software de terceiros proibido.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Voc\u00ea est\u00e1 tentando abrir mais de 5 mesas no app m\u00f3vel.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">H\u00e1 um bloqueador de janelas pop-up.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">H\u00e1 um problema de estabilidade da conex\u00e3o com a internet ao acessar qualquer mesa.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">Se voc\u00ea estiver jogando pela plataforma do navegador m\u00f3vel, recomendamos que limpe o cache e os cookies do navegador e\/ou o cache do aplicativo e, em seguida, fa\u00e7a login novamente.<\/span><\/p>\n<p><span style=\"font-weight: 400\"><strong>Observa\u00e7\u00e3o<\/strong>: Caso todos os pontos acima tenham sido verificados e voc\u00ea ainda esteja enfrentando problemas, envie-nos uma captura de tela ou um v\u00eddeo para support@coinpoker.com.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Vamos verificar isso com a equipe t\u00e9cnica.<\/span><\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8a160dff-collapse-3\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8a160dff-collapse-3\"\n                        id=\"accordion-6a03d8a160dff-heading-3\">\n                    <div class=\"cp-accordion-heading-text\">Em quantas mesas posso jogar ao mesmo tempo?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8a160dff-collapse-3\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8a160dff-heading-3\"\n                     data-cp-parent=\"#accordion-6a03d8a160dff\">\n                    <div class=\"cp-accordion-body\">\n                        <ul>\n<li><span style=\"font-weight: 400\">No navegador, voc\u00ea pode jogar em 5 mesas ao mesmo tempo.<\/span><\/li>\n<li><span style=\"font-weight: 400\">No app para desktop, n\u00e3o h\u00e1 restri\u00e7\u00f5es.<\/span><\/li>\n<li><span style=\"font-weight: 400\">No app para Android, voc\u00ea pode jogar em 5 mesas ao mesmo tempo.<\/span><\/li>\n<li><span style=\"font-weight: 400\">No app para iOS, voc\u00ea pode jogar em 5 mesas ao mesmo tempo.<\/span><\/li>\n<\/ul>\n                    <\/div>\n                <\/div>\n            <\/div>\n                <\/div>\n<\/div>\n\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_redirections_enabled":"","_seopress_redirections_type":"301","_seopress_redirections_value":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","editor_notices":[],"_cpsm_do_not_sync":false,"_cpsm_partial_sync":false,"footnotes":""},"topic-category":[438],"class_list":["post-165302","help","type-help","status-publish","hentry","topic-category-gameplay-technical"],"acf":{"card_image":"","help_view":"","in_app_mode_link":""},"_links":{"self":[{"href":"https:\/\/coinpoker.com\/pt\/wp-json\/wp\/v2\/help\/165302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coinpoker.com\/pt\/wp-json\/wp\/v2\/help"}],"about":[{"href":"https:\/\/coinpoker.com\/pt\/wp-json\/wp\/v2\/types\/help"}],"version-history":[{"count":1,"href":"https:\/\/coinpoker.com\/pt\/wp-json\/wp\/v2\/help\/165302\/revisions"}],"predecessor-version":[{"id":165304,"href":"https:\/\/coinpoker.com\/pt\/wp-json\/wp\/v2\/help\/165302\/revisions\/165304"}],"wp:attachment":[{"href":"https:\/\/coinpoker.com\/pt\/wp-json\/wp\/v2\/media?parent=165302"}],"wp:term":[{"taxonomy":"topic-category","embeddable":true,"href":"https:\/\/coinpoker.com\/pt\/wp-json\/wp\/v2\/topic-category?post=165302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}