{"id":165299,"date":"2026-05-11T15:20:10","date_gmt":"2026-05-11T15:20:10","guid":{"rendered":"https:\/\/coinpoker.com\/pt\/?post_type=help&#038;p=165299"},"modified":"2026-05-12T11:13:05","modified_gmt":"2026-05-12T11:13:05","slug":"deposits-faq","status":"publish","type":"help","link":"https:\/\/coinpoker.com\/pt\/help\/deposits-faq\/","title":{"rendered":"Perguntas frequentes sobre dep\u00f3sitos"},"content":{"rendered":"\n<div id=\"coinpoker-accordion-block_e76fe0cb765757fb3d23ff3e8a08491e\" class=\"coinpoker-accordion\" role=\"region\" aria-label=\"Accordion content\">\n        <div class=\"cp-accordion\" id=\"accordion-6a03d8a2d1dc7\">\n                    <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8a2d1dc7-collapse-1\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8a2d1dc7-collapse-1\"\n                        id=\"accordion-6a03d8a2d1dc7-heading-1\">\n                    <div class=\"cp-accordion-heading-text\">Como fa\u00e7o para depositar fundos na minha conta do CoinPoker?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8a2d1dc7-collapse-1\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8a2d1dc7-heading-1\"\n                     data-cp-parent=\"#accordion-6a03d8a2d1dc7\">\n                    <div class=\"cp-accordion-body\">\n                        <p>Veja como voc\u00ea pode fazer um dep\u00f3sito na CoinPoker:<\/p>\n<ul>\n<li>Acesse sua carteira.<\/li>\n<li>Clique em Dep\u00f3sito<\/li>\n<li>Escolha entre criptomoedas, cart\u00e3o de d\u00e9bito ou Luxon Pay.<\/li>\n<li>Escolha um b\u00f4nus e insira o valor que deseja depositar.<\/li>\n<li>Verifique os detalhes.<\/li>\n<li>Para criptomoedas, envie o valor do dep\u00f3sito para o endere\u00e7o exibido na tela. Para pagamento com cart\u00e3o banc\u00e1rio ou Luxon Pay, selecione Continuar para o pagamento seguro e siga as etapas.<\/li>\n<\/ul>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8a2d1dc7-collapse-2\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8a2d1dc7-collapse-2\"\n                        id=\"accordion-6a03d8a2d1dc7-heading-2\">\n                    <div class=\"cp-accordion-heading-text\">Quais s\u00e3o as formas de pagamento dispon\u00edveis para fazer um dep\u00f3sito?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8a2d1dc7-collapse-2\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8a2d1dc7-heading-2\"\n                     data-cp-parent=\"#accordion-6a03d8a2d1dc7\">\n                    <div class=\"cp-accordion-body\">\n                        <p>Voc\u00ea pode fazer dep\u00f3sitos na CoinPoker usando qualquer um dos seguintes m\u00e9todos de pagamento:<\/p>\n<ul>\n<li>Criptomoedas<\/li>\n<li>Cart\u00e3o de cr\u00e9dito ou cart\u00e3o de d\u00e9bito<\/li>\n<li>Luxon Pay<\/li>\n<\/ul>\n<p>Caso precise de mais ajuda, entre em contato com support@coinpoker.com.<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                <\/div>\n<\/div>\n\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_redirections_enabled":"","_seopress_redirections_type":"301","_seopress_redirections_value":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","editor_notices":[],"_cpsm_do_not_sync":false,"_cpsm_partial_sync":false,"footnotes":""},"topic-category":[436],"class_list":["post-165299","help","type-help","status-publish","hentry","topic-category-deposits"],"acf":{"card_image":"","help_view":["post_login"],"in_app_mode_link":""},"_links":{"self":[{"href":"https:\/\/coinpoker.com\/pt\/wp-json\/wp\/v2\/help\/165299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coinpoker.com\/pt\/wp-json\/wp\/v2\/help"}],"about":[{"href":"https:\/\/coinpoker.com\/pt\/wp-json\/wp\/v2\/types\/help"}],"version-history":[{"count":1,"href":"https:\/\/coinpoker.com\/pt\/wp-json\/wp\/v2\/help\/165299\/revisions"}],"predecessor-version":[{"id":165308,"href":"https:\/\/coinpoker.com\/pt\/wp-json\/wp\/v2\/help\/165299\/revisions\/165308"}],"wp:attachment":[{"href":"https:\/\/coinpoker.com\/pt\/wp-json\/wp\/v2\/media?parent=165299"}],"wp:term":[{"taxonomy":"topic-category","embeddable":true,"href":"https:\/\/coinpoker.com\/pt\/wp-json\/wp\/v2\/topic-category?post=165299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}