{"id":165189,"date":"2026-03-30T08:19:51","date_gmt":"2026-03-30T08:19:51","guid":{"rendered":"https:\/\/coinpoker.com\/es\/promotions\/heads-up-cash-game-world-championship\/"},"modified":"2026-05-06T08:22:50","modified_gmt":"2026-05-06T08:22:50","slug":"heads-up-cgwc","status":"publish","type":"promotion","link":"https:\/\/coinpoker.com\/es\/promotions\/cgwc\/heads-up\/","title":{"rendered":"Heads Up Cash Game World Championship"},"content":{"rendered":"\n<section\n        id=\"banner-block-block_6b57f7dd50d8f08df24eb9fbaa8a2bbe\"\n        class=\"home-banner home-banner-block position-relative banner-with-description common-hero-banner mb-md-60 mb-40\"\n        role=\"banner\"\n        aria-labelledby=\"banner-block-block_6b57f7dd50d8f08df24eb9fbaa8a2bbe-heading\">\n            <img loading=\"lazy\" width=\"3840\" height=\"1880\" src=\"https:\/\/coinpoker.com\/es\/wp-content\/uploads\/sites\/23\/2026\/03\/heads-up-banner-image-desktop_no_text-3840x1880-1.webp\" class=\"banner-image-desktop position-absolute top-0 start-0 w-100 h-100 d-none d-lg-block banner-image-position-center\" alt=\"CoinPoker &lt;br \/&gt;\r\nHeads Up Cash Game &lt;br \/&gt;\r\nWorld Championship \" decoding=\"async\" srcset=\"https:\/\/coinpoker.com\/es\/wp-content\/uploads\/sites\/23\/2026\/03\/heads-up-banner-image-desktop_no_text-3840x1880-1.webp 3840w, https:\/\/coinpoker.com\/es\/wp-content\/uploads\/sites\/23\/2026\/03\/heads-up-banner-image-desktop_no_text-3840x1880-1-300x147.webp 300w, https:\/\/coinpoker.com\/es\/wp-content\/uploads\/sites\/23\/2026\/03\/heads-up-banner-image-desktop_no_text-3840x1880-1-1024x501.webp 1024w, https:\/\/coinpoker.com\/es\/wp-content\/uploads\/sites\/23\/2026\/03\/heads-up-banner-image-desktop_no_text-3840x1880-1-130x63.webp 130w\" sizes=\"auto, (max-width: 3840px) 100vw, 3840px\" \/>    \n            <img loading=\"lazy\" width=\"1128\" height=\"2120\" src=\"https:\/\/coinpoker.com\/es\/wp-content\/uploads\/sites\/23\/2026\/03\/2_heads-up-responsive-mobile-image-1128x2120-1.webp\" class=\"banner-image-mobile position-absolute top-0 start-0 w-100 h-100 d-block d-lg-none\" alt=\"CoinPoker &lt;br \/&gt;\r\nHeads Up Cash Game &lt;br \/&gt;\r\nWorld Championship \" decoding=\"async\" srcset=\"https:\/\/coinpoker.com\/es\/wp-content\/uploads\/sites\/23\/2026\/03\/2_heads-up-responsive-mobile-image-1128x2120-1.webp 1128w, https:\/\/coinpoker.com\/es\/wp-content\/uploads\/sites\/23\/2026\/03\/2_heads-up-responsive-mobile-image-1128x2120-1-160x300.webp 160w, https:\/\/coinpoker.com\/es\/wp-content\/uploads\/sites\/23\/2026\/03\/2_heads-up-responsive-mobile-image-1128x2120-1-545x1024.webp 545w\" sizes=\"auto, (max-width: 1128px) 100vw, 1128px\" \/>        <div class=\"container burger position-relative block-banner-container\">\n        <div class=\"row\">\n            <div class=\"col-xl home-banner-content\">\n                                    <h1 id=\"banner-block-block_6b57f7dd50d8f08df24eb9fbaa8a2bbe-heading\"\n                        class=\"banner-heading banner-heading--medium\">\n                        CoinPoker <br \/>\r\nHeads Up Cash Game <br \/>\r\nWorld Championship                     <\/h1>\n                \n                \n                <div class=\"banner-bottom-content-wrapper\">\n                                            <ul class=\"home-banner-list mt-20 mb-40 text-white\" role=\"list\"\n                            aria-label=\"Key features\">\n                                                            <li class=\"wp-block-media-text\" role=\"listitem\">\n                                                                            <figure class=\"wp-block-media-text__media\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"50\" height=\"50\"\n                                                 src=\"https:\/\/coinpoker.com\/es\/wp-content\/uploads\/sites\/23\/2025\/07\/White.png\" alt=\"bullet point decoration\"\n                                                 class=\"size-full\">\n                                        <\/figure>\n                                    \n                                                                            <div class=\"wp-block-media-text__content\">\n                                            <p>\ud83d\udc51 SeaLlama (NLHE)<\/p>\n                                        <\/div>\n                                                                    <\/li>\n                                                            <li class=\"wp-block-media-text\" role=\"listitem\">\n                                                                            <figure class=\"wp-block-media-text__media\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"50\" height=\"50\"\n                                                 src=\"https:\/\/coinpoker.com\/es\/wp-content\/uploads\/sites\/23\/2025\/07\/White.png\" alt=\"bullet point decoration\"\n                                                 class=\"size-full\">\n                                        <\/figure>\n                                    \n                                                                            <div class=\"wp-block-media-text__content\">\n                                            <p>\ud83d\udc51 Yodogoki (PLO)<\/p>\n                                        <\/div>\n                                                                    <\/li>\n                                                    <\/ul>\n                    \n                                    <\/div>\n            <\/div>\n            <div class=\"col-xl\" aria-hidden=\"true\"><\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n<section class=\"last-updated-info-section\">\n    <div class=\"container\">\n        <p class=\"last-updated-info\">Last Updated: 6 mayo 2026<\/p>\n    <\/div>\n<\/section>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center has-large-font-size\">Nuestros ganadores del HU CGWC<\/h2>\n\n\n\n<p class=\"has-text-align-center\">El primer Campeonato Mundial de Cash Games Heads-Up ha llegado a su fin y ya se han coronado los campeones.<\/p>\n\n\n\n<p class=\"has-text-align-center\">La fase de grupos en ambos formatos estuvo muy re\u00f1ida, sobre todo en los cuadros de PLO, donde menos de 20 puntos marcaron la diferencia entre qui\u00e9n pasaba a las semifinales y qui\u00e9n no.<\/p>\n\n\n\n<p class=\"has-text-align-center\">En las semifinales y las finales, los que a la postre se proclamaron campeones en ambas modalidades demostraron su val\u00eda al terminar muy por delante de sus rivales.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Damos las gracias a todos los que han participado en este singular Campeonato Mundial de Cash Game y han ofrecido un espect\u00e1culo \u00e9pico a los aficionados.<\/p>\n\n\n\n<section class=\"two-column-section mb-30 mb-lg-30 pb-30 pb-lg-30\" id=\"title-two-column-block_fccc440f331f5d3829c1a159242e5ffd\">\n    <div class=\"container\">\n        <div class=\"row justify-content-center\">\n            \n                                <div class=\"col-12 col-md-6 d-flex\">\n                        <div class=\"card card-content mb-25 w-100\"\n                             role=\"article\"\n                             aria-labelledby=\"box-title-title-two-column-block_fccc440f331f5d3829c1a159242e5ffd-1\">\n                                                                                                                    <div class=\"mb-0\"><figure class=\"wp-block-image size-large\" style=\"margin-bottom: 9px;margin-top: -15px\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-32092 size-large\" src=\"https:\/\/coinpoker.com\/es\/wp-content\/uploads\/2026\/05\/nlh-hu-cgwc-winners.webp\" alt=\"\" width=\"455\" height=\"255\" \/><\/figure>\n<h3 class=\"wp-block-heading has-medium-font-size\" style=\"text-align: center;border-bottom: 2px solid #0F1014;padding-bottom: 10px;margin-bottom: 10px\">Cuadro del Texas Hold&#8217;em<\/h3>\n<p style=\"text-align: center\">La categor\u00eda de Texas Hold\u2019em la gan\u00f3 <strong>SeaLlama<\/strong>, un rostro temible y conocido en las mesas del Campeonato Mundial de Cash Games. Se llevar\u00e1 291 594 d\u00f3lares en ganancias por los partidos, adem\u00e1s del premio de 100 000 d\u00f3lares para el campe\u00f3n, que incluye un Rolex.<\/p>\n<p style=\"text-align: center\">En segundo lugar, con un premio de 50 000 d\u00f3lares, se sit\u00faa <strong>KraciFisk<\/strong>, seguido de <strong>Jungleman<\/strong>, en tercer lugar, con un premio de 30 000 d\u00f3lares.<\/p>\n<p style=\"text-align: center\"><strong>Los 3 mejores jugadores por ganancias en los partidos<\/strong>:<\/p>\n<p style=\"text-align: center\"><table id=\"tablepress-523\" class=\"tablepress tablepress-id-523 coinpoker-table table csop-table\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Jugador<\/th><th class=\"column-2\">Ganancias totales<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr class=\"row-2\">\n\t<td class=\"column-1\">SeaLlama<\/td><td class=\"column-2\">$291,594.55<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">Jungleman<\/td><td class=\"column-2\">$241,675.08<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">PR0DIGY<\/td><td class=\"column-2\">$115,556.30<\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/p>\n<\/div>\n                                                    <\/div>\n                    <\/div>\n                                    <div class=\"col-12 col-md-6 d-flex\">\n                        <div class=\"card card-content mb-25 w-100\"\n                             role=\"article\"\n                             aria-labelledby=\"box-title-title-two-column-block_fccc440f331f5d3829c1a159242e5ffd-2\">\n                                                                                                                    <div class=\"mb-0\"><figure class=\"wp-block-image size-large\" style=\"margin-bottom: 9px;margin-top: -15px\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-32092 size-large\" src=\"https:\/\/coinpoker.com\/es\/wp-content\/uploads\/2026\/05\/plo-hu-cgwc-winners.webp\" alt=\"\" width=\"455\" height=\"255\" \/><\/figure>\n<h3 class=\"wp-block-heading has-medium-font-size\" style=\"text-align: center;border-bottom: 2px solid #0F1014;padding-bottom: 10px;margin-bottom: 10px\">Cuadro del Pot Limit Omaha<\/h3>\n<p style=\"text-align: center\">El cuadro de la PLO lo gan\u00f3 de forma contundente <strong>Yodogoki<\/strong>, un conocido habitual de CoinPoker que se llevar\u00e1 188 354 d\u00f3lares en ganancias por el torneo y el premio de 100 000 d\u00f3lares para el campe\u00f3n, que incluye un reloj Rolex de alta gama.<\/p>\n<p style=\"text-align: center\">Otro jugador al que hemos visto competir en las apuestas online m\u00e1s altas, <strong>GucciNIKE<\/strong>, qued\u00f3 en segundo lugar y se llevar\u00e1 el premio en met\u00e1lico de 30 000 d\u00f3lares.<\/p>\n<p style=\"text-align: center\"><strong>Los 3 mejores jugadores por ganancias en los partidos<\/strong>:<\/p>\n<p style=\"text-align: center\"><table id=\"tablepress-524\" class=\"tablepress tablepress-id-524 coinpoker-table table csop-table\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Jugador<\/th><th class=\"column-2\">Ganancias totales<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr class=\"row-2\">\n\t<td class=\"column-1\">Yodogoki<\/td><td class=\"column-2\">$188,354.05<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">DogeCoinMaximaliste<\/td><td class=\"column-2\">$146,491.45<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">GucciNIKE<\/td><td class=\"column-2\">$69,174.27<\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/p>\n<\/div>\n                                                    <\/div>\n                    <\/div>\n                        <\/div>\n    <\/div>\n<\/section>\n\n\n\n<br>\n\n\n\n<br>\n\n\n\n<section class=\"tournament-tabs-wrapper px-0\" data-block-instance=\"tournament-tabs-6a03cea34e813\">\n    <div class=\"container\">\n        <nav id=\"navbar-example2\" class=\"sticky-navs mb-3\">\n            <ul class=\"nav nav-pills cp-line-navbar\">\n                                    <li class=\"nav-item\">\n                        <a class=\"nav-link active\" href=\"#aboutContent\">\n                            El Heads Up CGWC                        <\/a>\n                    <\/li>\n                                    \n                \n                                    <li class=\"nav-item\">\n                        <a class=\"nav-link\" href=\"#leaderboardContent\">\n                            Escenarios del evento                        <\/a>\n                    <\/li>\n                \n                                    <li class=\"nav-item\">\n                        <a class=\"nav-link\" href=\"#content_1\">\n                            Los Premios                        <\/a>\n                    <\/li>\n                \n                \n                \n                \n                \n                            <\/ul>\n        <\/nav>\n        <div class=\"tournaments-tab-content-wrapper\">\n                            <div id=\"aboutContent\">\n                    <div class=\"pt-10 pt-lg-50 pb-10 pb-lg-30 section-with-bottom-border\">\n                        <div class=\"row\">\n                            <div class=\"col-12 col-lg-8\">\n                                <h2 class=\"h3\">\n                                    El Heads Up CGWC                                <\/h2>\n                                                                    <p>La competici\u00f3n de partidas de dinero real m\u00e1s prestigiosa del mundo volvi\u00f3 el 6 de abril con entradas de 10 000 d\u00f3lares y sin comisi\u00f3n.<\/p>\n<p>CoinPoker organiza cada a\u00f1o varios <a href=\"https:\/\/coinpoker.com\/es\/promotions\/cgwc\/\">Cash Game World Championships<\/a>, que atraen a los mejores entre los mejores. Siempre elegimos diferentes formatos y apuestas, y las partidas nunca tienen rake. Pero esta vez hubo un giro inesperado.<\/p>\n<p>Esta fue la primera serie de partidas de cash uno contra uno en CoinPoker.<\/p>\n<p>Ocho jugadores participaron en el torneo <a href=\"https:\/\/coinpoker.com\/es\/games\/texas-holdem\/\">de Texas Hold\u2019em<\/a>, y otros ocho se enfrentaron en el torneo <a href=\"https:\/\/coinpoker.com\/es\/games\/plo\/\">de Pot Limit Omaha<\/a>.<\/p>\n<p>Tras la <strong>fase de grupos<\/strong> y <strong>las semifinales<\/strong>, la <strong>gran final<\/strong> coron\u00f3 a los mejores jugadores del mundo en partidas uno contra uno online.<\/p>\n<h3 class=\"wp-block-heading has-large-font-size\">Descripci\u00f3n General de la Serie<\/h3>\n<div style=\"padding: 2px;border-radius: 9px;background: linear-gradient(to right, #35394A 75%, #35394A 100%)\">\n<div style=\"background: #101116;border-radius: 7px;padding: 10px 20px;align-items: center;gap: 10px\">\u25ab\ufe0f <strong>Fecha del Evento:<\/strong>\u00a0Del 6 de abril al 3 de mayo de 2026<br \/>\n\u25ab\ufe0f <strong>Formatos:<\/strong>\u00a0No Limit Texas Hold\u2019em and Pot Limit Omaha<br \/>\n\u25ab\ufe0f <strong>Competidores:<\/strong> 12 jugadores en NLHE, 8 jugadores en PLO<br \/>\n\u25ab\ufe0f <strong>Stakes<\/strong>: 50$\/100$<br \/>\n\u25ab\ufe0f <strong>Buy-In:<\/strong>\u00a0100 BB (10.000$) con recarga autom\u00e1tica obligatoria<br \/>\n\u25ab\ufe0f <strong>Rake:<\/strong>\u00a0100% sin rake<br \/>\n\u25ab\ufe0f <strong>Ante:<\/strong>\u00a0Sin ante<\/div>\n<\/div>\n<p>\u00a0<\/p>\n<p>Con\u00e9ctate al Heads Up CGWC cuando quieras, directamente desde la aplicaci\u00f3n de escritorio de CoinPoker.<\/p>\n<p>Selecciona la pesta\u00f1a \u00abCGWC\u00bb para ver un resumen de la competici\u00f3n, las partidas en curso y la clasificaci\u00f3n.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-183365\" src=\"https:\/\/coinpoker.com\/es\/wp-content\/uploads\/2026\/03\/cgwc-matches-apr6.webp\" alt=\"\" width=\"1450\" height=\"1025\" \/><\/p>\n<h4 class=\"wp-block-heading has-large-font-size\">Cambio De Niveles De Ciegas y Formatos De Poker<\/h4>\n<p>En el Heads Up Cash Game World Championship, los jugadores pueden acordar algunos cambios.<\/p>\n<ol>\n<li><strong>Stakes<\/strong>: El m\u00ednimo de la serie es $50\/$100, pero los jugadores pueden optar por niveles de ciegas m\u00e1s altos.<\/li>\n<li><strong>Formatos de Poker<\/strong>: En las partidas de Pot Limit Omaha, los participantes pueden elegir entre PLO5 o PLO6.<\/li>\n<\/ol>\n<p>Los cambios deben ser aceptados por ambas partes y no se aplican a los partidas futuros.<\/p>\n                                                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            \n            \n                            <div id=\"leaderboardContent\" class=\"\">\n                    <div class=\"pt-10 pt-lg-50 pb-10 pb-lg-30 section-with-bottom-border\">\n                        <h2 class=\"h3\">\n                            Escenarios del evento                        <\/h2>\n                                                    <p>El Campeonato Mundial de Cash Games Heads-Up se dividi\u00f3 en tres fases.<\/p>\n<h3 class=\"wp-block-heading has-large-font-size\">Fase de Grupos: del 6 al 19 de abril<\/h3>\n<p><strong>En el evento de Pot Limit Omaha<\/strong>, los jugadores se enfrentaron a todos los rivales de su grupo de cuatro durante 1.250 manos. Los dos mejores jugadores de cada grupo pasaron a las semifinales.<\/p>\n<p><strong>En el torneo de Texas Hold&#8217;em<\/strong>, los jugadores se enfrentaron a todos sus rivales durante 1.875 manos en su grupo de tres jugadores. El mejor clasificado de cada grupo pas\u00f3 a las semifinales.<\/p>\n<p>En la fase de grupos se utiliz\u00f3 un sistema de puntos para determinar los ganadores.<\/p>\n<ul>\n<li><strong>Victorias en Partidas<\/strong>: Los jugadores recib\u00edan 50 puntos por cada partido ganado.<\/li>\n<li><strong>Puntuaci\u00f3n EV BB<\/strong>: Los jugadores pod\u00edan ganar o perder entre 0 y 150 puntos en cada partido.<br \/>\n10 EV BB equivalen a 1 punto, redondeado al n\u00famero entero m\u00e1s cercano.<\/li>\n<\/ul>\n<p>Los jugadores pod\u00edan ganar un m\u00e1ximo de 200 puntos en un solo partido: 150 puntos del EV BB (15 buy-ins) m\u00e1s 50 puntos por la victoria.<\/p>\n<p>Consulta los T\u00e9rminos y condiciones para obtener m\u00e1s informaci\u00f3n sobre los puntos de la fase de grupos.<\/p>\n<h3 class=\"wp-block-heading has-large-font-size\">Semifinales: del 20 al 26 de abril<\/h3>\n<p>El jugador que obtuvo la mayor puntuaci\u00f3n total en la fase de grupos se gan\u00f3 el derecho a elegir a su rival para el partido de semifinales.<\/p>\n<p>Cada partida de semifinales dur\u00f3 2000 manos, tras lo cual dos jugadores pasaron a la gran final.<\/p>\n<h3 class=\"wp-block-heading has-large-font-size\">Partido por el 3.\u00ba y 4.\u00ba puesto: del 27 de abril al 1 de mayo<\/h3>\n<p>Del 27 de abril al 3 de mayo se disput\u00f3 un partido entre los perdedores de las semifinales de Texas Hold\u2019em.<\/p>\n<p>Los participantes deb\u00edan jugar 1.000 manos para optar al premio de 30.000 d\u00f3lares del tercer puesto.<\/p>\n<h3 class=\"wp-block-heading has-large-font-size\">Gran final: del 27 de abril al 3 de mayo<\/h3>\n<p>Una legendaria final de 2.000 manos coron\u00f3 a los campeones mundiales de partidas de cash heads-up de 2026.<\/p>\n<p>Retransmitimos todo el viaje en <a href=\"https:\/\/www.youtube.com\/@CoinPoker_TV\">YouTube<\/a>. Si quieres ver a los mejores jugadores de partidas con dinero real del mundo, ah\u00ed es donde tienes que estar.<\/p>\n                                            <\/div>\n                <\/div>\n            \n                            <div id=\"content_1\">\n                    <div class=\"pt-10 pt-lg-50 pb-10 pb-lg-30 section-with-bottom-border\">\n                        <div class=\"row align-items-center\">\n                            <div class=\"col-12\">\n                                <h2 class=\"h3\">\n                                    Los Premios                                <\/h2>\n                                                                    <div><p><strong>Evento de No Limit Hold&#8217;em<\/strong>:<\/p>\n<p>\ud83e\udd47 &#8211; $100,000: Incluye un reloj Rolex y un premio en met\u00e1lico<br \/>\n\ud83e\udd48 &#8211; Premio en met\u00e1lico de 50 000 d\u00f3lares<br \/>\n\ud83e\udd49 &#8211; Premio en met\u00e1lico de 30 000 d\u00f3lares<\/p>\n<p><strong>Evento de Pot Limit Omaha<\/strong>:<\/p>\n<p>\ud83e\udd47 &#8211; $100,000: Incluye un reloj Rolex y un premio en met\u00e1lico<br \/>\n\ud83e\udd48 &#8211; Premio en met\u00e1lico de 30 000 d\u00f3lares<\/p>\n<p>Cada jugador aport\u00f3 10 000 d\u00f3lares, y CoinPoker igual\u00f3 el 50 % de cada aportaci\u00f3n y lo a\u00f1adi\u00f3 al bote de premios.<\/p>\n<\/div>\n                                                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            \n            \n            \n            \n            \n                    <\/div>\n    <\/div>\n<\/section>\n<script>\n    (function () {\n        const blockInstanceId = 'tournament-tabs-6a03cea34e813';\n        const sectionElement = document.querySelector(`section[data-block-instance=\"${blockInstanceId}\"]`);\n        if (!sectionElement) {\n            return;\n        }\n\n        function getSections(links) {\n            return Array.from(links)\n                .map(link => sectionElement.querySelector(link.getAttribute('href')))\n                .filter(section => section !== null);\n        }\n\n        function activateLink(sections, links) {\n            const yPosition = window.scrollY;\n\n            for (let i = sections.length - 1; i >= 0; i--) {\n                const section = sections[i];\n\n                if (yPosition >= section.offsetTop - 130) {\n                    links.forEach(link => link.classList.remove('active'));\n                    const activeLink = sectionElement.querySelector(`a[href=\"#${section.id}\"]`);\n                    if (activeLink) activeLink.classList.add('active');\n                    return;\n                }\n            }\n        }\n\n        function onScrollHandler() {\n            activateLink(sections, links);\n        }\n\n        function onClickHandler(e) {\n            const target = e.target;\n            if (target.tagName !== 'A') return;\n\n            const href = target.getAttribute('href');\n            if (!href || href.charAt(0) !== '#') return;\n\n            if (!sectionElement.contains(target)) return;\n\n            e.preventDefault();\n\n            const targetElement = sectionElement.querySelector(href);\n            if (targetElement) {\n                const offset = 126;\n                const targetPosition = targetElement.offsetTop - offset;\n\n                window.scrollTo({\n                    top: targetPosition,\n                    behavior: 'smooth'\n                });\n\n                setTimeout(() => {\n                    const targetId = href.substring(1);\n                    history.pushState(null, null, `#${targetId}`);\n                }, 100);\n            }\n        }\n\n        const navbar = sectionElement.querySelector('#navbar-example2');\n        const links = navbar ? Array.from(navbar.querySelectorAll('.cp-line-navbar > li > a')) : [];\n        const sections = getSections(links);\n        const hashLinks = Array.from(sectionElement.querySelectorAll('a[href^=\"#\"]:not([href=\"#\"])'));\n\n        const stickyClass = 'tab-bar-sticky';\n        let stickyNavOffset = 0;\n        if (navbar) {\n            stickyNavOffset = navbar.getBoundingClientRect().top + window.scrollY;\n        }\n\n        function checkStickyNav() {\n            if (!navbar) {\n                return;\n            }\n            if (window.scrollY >= stickyNavOffset - 56) {\n                navbar.classList.add(stickyClass);\n            } else {\n                navbar.classList.remove(stickyClass);\n            }\n        }\n\n        sectionElement.querySelectorAll('.terms-link-toggle').forEach(function (termsLink) {\n            termsLink.addEventListener('click', function (e) {\n                e.preventDefault();\n                const tabPane = termsLink.closest('.tab-pane');\n                const termsContent = tabPane ? tabPane.querySelector('.terms-content-sub') : null;\n                if (!termsContent) {\n                    return;\n                }\n                const isHidden = termsContent.style.display === 'none' || window.getComputedStyle(termsContent).display === 'none';\n                termsContent.style.display = isHidden ? 'block' : 'none';\n                termsLink.classList.toggle('open');\n            });\n        });\n\n        checkStickyNav();\n\n        if (links.length === 0) {\n            window.addEventListener('scroll', checkStickyNav);\n            return;\n        }\n\n        const scrollHandler = function () {\n            onScrollHandler();\n            checkStickyNav();\n        };\n        window.addEventListener('scroll', scrollHandler);\n\n        hashLinks.forEach(link => {\n            const clickHandler = function (e) {\n                onClickHandler(e);\n            };\n            link.addEventListener('click', clickHandler);\n        });\n\n        activateLink(sections, links);\n    })();\n<\/script>\n\n\n\n<div id=\"coinpoker-accordion-block_c7f0fc90fb230d9e25c22a95ce694592\" class=\"coinpoker-accordion\" role=\"region\" aria-label=\"Accordion content\">\n            <div class=\"cp-accordion-title\">\n            <h2 class=\"wp-block-heading has-large-font-size\">Preguntas frecuentes<\/h2>\n        <\/div>\n        <div class=\"cp-accordion\" id=\"accordion-6a03cea34f231\">\n                    <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03cea34f231-collapse-1\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03cea34f231-collapse-1\"\n                        id=\"accordion-6a03cea34f231-heading-1\">\n                    <div class=\"cp-accordion-heading-text\">\u00bfQu\u00e9 es el Heads Up Cash Game World Championship?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03cea34f231-collapse-1\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03cea34f231-heading-1\"\n                     data-cp-parent=\"#accordion-6a03cea34f231\">\n                    <div class=\"cp-accordion-body\">\n                        <p>Una serie de partidas de cash heads-up en CoinPoker en la que participan los mejores jugadores del mundo y se reparten enormes premios en dinero real.<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03cea34f231-collapse-2\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03cea34f231-collapse-2\"\n                        id=\"accordion-6a03cea34f231-heading-2\">\n                    <div class=\"cp-accordion-heading-text\">\u00bfCu\u00e1ndo se celebra el Heads Up Cash Game World Championship?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03cea34f231-collapse-2\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03cea34f231-heading-2\"\n                     data-cp-parent=\"#accordion-6a03cea34f231\">\n                    <div class=\"cp-accordion-body\">\n                        <p>El evento tuvo lugar del 6 de abril al 3 de mayo de 2026.<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03cea34f231-collapse-3\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03cea34f231-collapse-3\"\n                        id=\"accordion-6a03cea34f231-heading-3\">\n                    <div class=\"cp-accordion-heading-text\">\u00bfQu\u00e9 formato de poker se utiliza en el Heads Up CGWC?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03cea34f231-collapse-3\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03cea34f231-heading-3\"\n                     data-cp-parent=\"#accordion-6a03cea34f231\">\n                    <div class=\"cp-accordion-body\">\n                        <p>La serie cont\u00f3 con partidas tanto de NL10K como de PLO10K. Los jugadores de PLO tambi\u00e9n podr\u00edan optar por jugar al Pot Limit Omaha de 5\/6 cartas en sus partidas.<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03cea34f231-collapse-4\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03cea34f231-collapse-4\"\n                        id=\"accordion-6a03cea34f231-heading-4\">\n                    <div class=\"cp-accordion-heading-text\">\u00bfCu\u00e1les son las apuestas de las partidas del Heads Up Cash Game World Championship?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03cea34f231-collapse-4\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03cea34f231-heading-4\"\n                     data-cp-parent=\"#accordion-6a03cea34f231\">\n                    <div class=\"cp-accordion-body\">\n                        <p>Las apuestas m\u00ednimas para las partidas de Heads Up CGWC se fijaron en 50 $\/100 $. No obstante, si ambos jugadores de una partida est\u00e1n de acuerdo, estas apuestas podr\u00edan superarse el m\u00ednimo de 50 $\/100 $.<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03cea34f231-collapse-5\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03cea34f231-collapse-5\"\n                        id=\"accordion-6a03cea34f231-heading-5\">\n                    <div class=\"cp-accordion-heading-text\">\u00bfQu\u00e9 es EV BB y por qu\u00e9 se utiliza en el Campeonato Mundial de Cash Games?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03cea34f231-collapse-5\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03cea34f231-heading-5\"\n                     data-cp-parent=\"#accordion-6a03cea34f231\">\n                    <div class=\"cp-accordion-body\">\n                        <p>El EV (valor esperado) en BB (ciegas grandes) mide la rentabilidad de las jugadas, en lugar de los d\u00f3lares ganados o perdidos.<\/p>\n<p>El uso de una tasa de victorias basada en el valor esperado es una forma de medir con mayor precisi\u00f3n el resultado de las partidas del Campeonato Mundial de Cash Games. Si los partidas se juzgaran en funci\u00f3n del dinero ganado o perdido, eso significar\u00eda que algunos jugadores podr\u00edan ganar torneos por suerte, en lugar de por habilidad.<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03cea34f231-collapse-6\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03cea34f231-collapse-6\"\n                        id=\"accordion-6a03cea34f231-heading-6\">\n                    <div class=\"cp-accordion-heading-text\">\u00bfHay rake en el Heads Up CGWC?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03cea34f231-collapse-6\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03cea34f231-heading-6\"\n                     data-cp-parent=\"#accordion-6a03cea34f231\">\n                    <div class=\"cp-accordion-body\">\n                        <p>No, todas las partidas del Campeonato Mundial de Cash Games Heads Up se disputaron sin comisi\u00f3n alguna. Los jugadores no pagaron ninguna cuota por participar en las partidas con dinero real.<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03cea34f231-collapse-7\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03cea34f231-collapse-7\"\n                        id=\"accordion-6a03cea34f231-heading-7\">\n                    <div class=\"cp-accordion-heading-text\">\u00bfD\u00f3nde puedo ver el Heads Up CGWC?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03cea34f231-collapse-7\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03cea34f231-heading-7\"\n                     data-cp-parent=\"#accordion-6a03cea34f231\">\n                    <div class=\"cp-accordion-body\">\n                        <p>Sigue la retransmisi\u00f3n en directo y los momentos m\u00e1s destacados en los canales de YouTube, Twitch y X (Twitter) de CoinPoker.<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                <\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<section class=\"pb-40 pb-md-160\" id=\"seo-section-block_bf250e580133d7612e711aa5b3006566\">\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-12\">\n                            <\/div>\n\n                            <div class=\"seo-content\">\n                    <h2 class=\"wp-block-heading has-large-font-size\">Atenci\u00f3n: T\u00e9rminos y condiciones de CGWC<\/h2>\n<p>El Heads Up Cash Game World Championship de CoinPoker (tambi\u00e9n conocido como Heads Up CGWC) es una serie de partidas de cash compuesta por una serie de enfrentamientos uno contra uno.<\/p>\n<p>Este evento se celebra del 6 de abril al 3 de mayo y contar\u00e1 con dos torneos paralelos (uno de Texas Hold\u2019em y otro de Pot Limit Omaha), ambos con sus propias fases (fase de grupos, semifinales y gran final).<\/p>\n<p>A continuaci\u00f3n se detallan las normas relativas al Heads Up CGWC, las distintas fases de cada evento, la participaci\u00f3n y la programaci\u00f3n.<\/p>\n<h3 class=\"wp-block-heading has-medium-font-size\">1. Gameplay<\/h3>\n<ul>\n<li>Los participantes en el Heads Up Cash Game World Championship pueden optar por inscribirse en el grupo de Texas Hold\u2019em (NLH), en el de Pot Limit Omaha (PLO) o en ambos.<\/li>\n<li>Las apuestas m\u00ednimas para el Heads Up CGWC son de 50$\/100$ (buy-in de 10.000$), con una recarga autom\u00e1tica obligatoria a 100 BB activa durante las partidas.<\/li>\n<li>Se espera que los jugadores jueguen en un m\u00ednimo de dos mesas a la vez, pero, si ambas partes est\u00e1n de acuerdo, se permite jugar en una sola mesa.<\/li>\n<li>En cada partida habr\u00e1 un n\u00famero determinado de manos que los jugadores deber\u00e1n completar.<\/li>\n<li>Las partidas de Pot Limit Omaha (PLO) tendr\u00e1n un formato predeterminado obligatorio de Pot Limit Omaha de 4 cartas. No obstante, dos jugadores pueden decidir, de com\u00fan acuerdo, alternar entre el Pot Limit Omaha de 4 cartas y el Pot Limit Omaha de 5 cartas (PLO5) o el Pot Limit Omaha de 6 cartas (PLO6) en su mesa.<\/li>\n<li>Todas las partidas tendr\u00e1n ciegas obligatorias de 50$ y 100$. No obstante, dos jugadores pueden acordar aumentar o reducir las apuestas en cualquier momento, siendo 50$\/100$ las apuestas m\u00ednimas predeterminadas.<\/li>\n<li>El limping est\u00e1 prohibido en este evento de Heads Up Cash Game World Championship (CGWC). Las manos que se hayan retirado involuntariamente no se tendr\u00e1n en cuenta en los resultados de EV BB ni en el recuento total de manos. Las infracciones intencionadas o reiteradas pueden dar lugar a la descalificaci\u00f3n.<\/li>\n<\/ul>\n<h3 class=\"wp-block-heading has-medium-font-size\">2. La Fase de Grupos<\/h3>\n<ul>\n<li>La fase de grupos del Heads Up Cash Game World Championship se celebrar\u00e1 del 6 al 19 de abril.<\/li>\n<li>Los grupos de la fase de grupos se determinar\u00e1n mediante un sorteo aleatorio. Al mismo tiempo, hay que elegir un avatar de entre los que ofrece CoinPoker.<\/li>\n<li>Dependiendo del n\u00famero de participantes, los jugadores se enfrentar\u00e1n entre s\u00ed en un total de entre 1.250 y 1.875 manos en cada partida. El n\u00famero exacto se dar\u00e1 a conocer antes de que comience la fase de grupos.<\/li>\n<li>Dependiendo del n\u00famero de participantes, un n\u00famero diferente de jugadores pasar\u00e1 a las semifinales:<br \/>\n&#8211; Si hay 8 participantes en la fase de grupos, se formar\u00e1n 2 grupos de 4, y los 2 mejores de cada grupo pasar\u00e1n a las semifinales.<br \/>\n&#8211; Si hay 12 participantes en la fase de grupos, se formar\u00e1n 4 grupos de 3, y un jugador de cada grupo pasar\u00e1 a las semifinales.<br \/>\n&#8211; Si hay 16 participantes en la fase de grupos, se formar\u00e1n 4 grupos de 4, y un jugador de cada grupo pasar\u00e1 a las semifinales.<\/li>\n<li>Para determinar los ganadores de la fase de grupos, CoinPoker utilizar\u00e1 un sistema de puntos que se describe en la siguiente secci\u00f3n.<\/li>\n<\/ul>\n<h4 class=\"wp-block-heading has-medium-font-size\">2.1. El Sistema de Puntuaci\u00f3n de la Fase de Grupos<\/h4>\n<ul>\n<li>Ganar un partida en la fase de grupos otorga 50 puntos al ganador.<\/li>\n<li>Los jugadores pueden ganar o perder entre 0 y 150 puntos por partida en funci\u00f3n de su puntuaci\u00f3n EV BB.<\/li>\n<li>10 puntos de ventaja en el marcador equivalen a 1 punto en la fase de grupos.<\/li>\n<li>El m\u00e1ximo que un jugador puede ganar en un solo partida de la fase de grupos es de 200 puntos (50 puntos por ganar el partida, m\u00e1s 150 puntos de la puntuaci\u00f3n EV BB).<\/li>\n<li>Si dos jugadores que lideran su grupo empatan a puntos, se inicia una eliminatoria. El primero en obtener unas ganancias de 100 BB o m\u00e1s (sin tener en cuenta el valor esperado) rompe el empate y gana.<\/li>\n<li>Si un jugador no se presenta a un partida, todos los miembros del grupo recibir\u00e1n 50 puntos como si hubieran ganado su partida contra dicho jugador; su rival en ese partida tambi\u00e9n recibir\u00e1 la totalidad de los puntos proporcionales a los EV BB ganados, mientras que los dem\u00e1s jugadores obtendr\u00e1n la mitad de esa cantidad.<\/li>\n<\/ul>\n<h3 class=\"wp-block-heading has-medium-font-size\">3. Las Semifinales<\/h3>\n<ul>\n<li>La fase de semifinales se disputar\u00e1 del 20 al 26 de abril, tras la fase de grupos.<\/li>\n<li>El jugador que haya sumado el mayor n\u00famero de puntos al t\u00e9rmino de la fase de grupos podr\u00e1 elegir a su rival para el partida de semifinales.<\/li>\n<li>Las partidas de semifinales tendr\u00e1n una duraci\u00f3n de 2000 manos.<\/li>\n<li>Dos jugadores pasar\u00e1n de las semifinales a la gran final.<\/li>\n<\/ul>\n<h3 class=\"wp-block-heading has-medium-font-size\">4. Partido por el tercer y cuarto puesto<\/h3>\n<ul>\n<li>En el torneo de Texas Hold&#8217;em, se disputar\u00e1 un enfrentamiento entre los perdedores de las semifinales entre el 27 de abril y el 1 de mayo, con un premio de 30 000 d\u00f3lares para el tercer clasificado.<\/li>\n<li>El partido por el tercer y cuarto puesto requiere que se jueguen 1.000 manos.<\/li>\n<\/ul>\n<h3 class=\"wp-block-heading has-medium-font-size\">5. La Gran Final<\/h3>\n<ul>\n<li>La fase de la gran final se celebrar\u00e1 del 27 de abril al 3 de mayo, tras las semifinales.<\/li>\n<li>Para que se celebren las finales, es necesario que se jueguen 2.000 manos.<\/li>\n<\/ul>\n<h3 class=\"wp-block-heading has-medium-font-size\">6. Participaci\u00f3n<\/h3>\n<ul>\n<li>Hay un n\u00famero limitado de plazas disponibles para los jugadores en el Heads Up CGWC. La admisi\u00f3n de los participantes al evento quedar\u00e1 a la entera discreci\u00f3n de CoinPoker.<\/li>\n<li>En funci\u00f3n del n\u00famero total de jugadores que participen en el evento, es posible que se celebre un partida para determinar qui\u00e9nes ocupan el tercer y el cuarto puesto.<\/li>\n<li>Adem\u00e1s de la entrada de 10 000 d\u00f3lares, cada jugador deber\u00e1 depositar 10.000 d\u00f3lares en una cuenta de garant\u00eda bloqueada como garant\u00eda de participaci\u00f3n. En caso de abandonar el torneo antes de tiempo, el premio garantizado de 10.000 $ se perder\u00e1 y se repartir\u00e1 entre los jugadores del grupo del participante que haya abandonado, en una proporci\u00f3n basada en el n\u00famero de manos que queden por jugar.<\/li>\n<li>Se espera que los jugadores colaboren con el equipo de marketing de CoinPoker respondiendo a preguntas ocasionales sobre sus partidas o manos, y el ganador del evento deber\u00e1 participar en una entrevista por mensaje de texto, audio o v\u00eddeo.<\/li>\n<li>Antes de que comience la fase de grupos, los jugadores deben elegir un avatar que a\u00fan no haya sido elegido por otro jugador.<\/li>\n<li>Una vez elegidos, los avatares no se podr\u00e1n cambiar mientras dure el evento Heads Up CGWC.<\/li>\n<\/ul>\n<h3 class=\"wp-block-heading has-medium-font-size\">7. Programaci\u00f3n<\/h3>\n<ul>\n<li>Se espera que los jugadores coordinen sus partidas de Heads Up del CGWC de forma privada. Un empleado de CoinPoker actuar\u00e1 como mediador en estas conversaciones.<\/li>\n<li>Si no se llega a un acuerdo sobre la hora, CoinPoker programar\u00e1 el partida de Heads Up de la CGWC, teniendo en cuenta la disponibilidad de ambos jugadores y haciendo todo lo posible por satisfacerla.<\/li>\n<li>Si alguno de los jugadores no se presenta a disputar el partida a la hora prevista, se considerar\u00e1 que ha abandonado.<\/li>\n<li>La retirada de un partida puede afectar a los puntos durante la fase de grupos y tambi\u00e9n a la garant\u00eda de participaci\u00f3n del jugador, tal y como se describe en la secci\u00f3n Participaci\u00f3n.<\/li>\n<\/ul>\n<h3 class=\"wp-block-heading has-medium-font-size\">8. General<\/h3>\n<ul>\n<li>La participaci\u00f3n en esta promoci\u00f3n implica la plena aceptaci\u00f3n y comprensi\u00f3n de estos T\u00e9rminos y Condiciones.<\/li>\n<li>Esta promoci\u00f3n est\u00e1 sujeta a los T\u00e9rminos y Condiciones generales de CoinPoker.<\/li>\n<li>Se espera que todos los participantes en el Heads Up CGWC demuestren un alto nivel de deportividad y \u00e9tica en el juego. CoinPoker supervisar\u00e1 todas las partidas para detectar posibles incumplimientos del esp\u00edritu de estas condiciones o de las Condiciones de servicio de CoinPoker.<\/li>\n<li>Todas las decisiones tomadas por CoinPoker respecto a la elegibilidad, c\u00e1lculos, disputas, acciones de cumplimiento o interpretaci\u00f3n de estos T\u00e9rminos son definitivas y vinculantes.<\/li>\n<\/ul>\n                <\/div>\n                    <\/div>\n    <\/div>\n<\/section>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuestros ganadores del HU CGWC El primer Campeonato Mundial de Cash Games Heads-Up ha llegado a su fin y ya se han coronado los campeones. La fase de grupos en ambos formatos estuvo muy re\u00f1ida, sobre todo en los cuadros de PLO, donde menos de 20 puntos marcaron la diferencia entre qui\u00e9n pasaba a las <a href=\"https:\/\/coinpoker.com\/es\/promotions\/cgwc\/heads-up\/\" class=\"more-link\">&#8230;<span class=\"screen-reader-text\">  Heads Up Cash Game World Championship<\/span><\/a><\/p>\n","protected":false},"featured_media":165196,"template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"Heads Up Cash Game World Championship (CGWC) en CoinPoker","_seopress_titles_desc":"El Heads Up Cash Game World Championship de CoinPoker ofrece relojes Rolex y premios en met\u00e1lico para los especialistas en partidas heads-up de Hold\u2019em y Pot Limit Omaha.","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_redirections_enabled":"","_seopress_redirections_type":"301","_seopress_redirections_value":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","editor_notices":[],"_cpsm_do_not_sync":false,"_cpsm_partial_sync":false,"footnotes":""},"class_list":["post-165189","promotion","type-promotion","status-publish","has-post-thumbnail","hentry"],"acf":{"card_image":165195,"promotions_price":"","promotions_price_text":""},"_links":{"self":[{"href":"https:\/\/coinpoker.com\/es\/wp-json\/wp\/v2\/promotion\/165189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coinpoker.com\/es\/wp-json\/wp\/v2\/promotion"}],"about":[{"href":"https:\/\/coinpoker.com\/es\/wp-json\/wp\/v2\/types\/promotion"}],"version-history":[{"count":8,"href":"https:\/\/coinpoker.com\/es\/wp-json\/wp\/v2\/promotion\/165189\/revisions"}],"predecessor-version":[{"id":165508,"href":"https:\/\/coinpoker.com\/es\/wp-json\/wp\/v2\/promotion\/165189\/revisions\/165508"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coinpoker.com\/es\/wp-json\/wp\/v2\/media\/165196"}],"wp:attachment":[{"href":"https:\/\/coinpoker.com\/es\/wp-json\/wp\/v2\/media?parent=165189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}