{"id":165557,"date":"2026-05-12T12:47:36","date_gmt":"2026-05-12T12:47:36","guid":{"rendered":"https:\/\/coinpoker.com\/es\/help\/preguntas-frecuentes-sobre-la-cuenta-de-coinpoker\/"},"modified":"2026-05-12T13:00:47","modified_gmt":"2026-05-12T13:00:47","slug":"coinpoker-account-faq","status":"publish","type":"help","link":"https:\/\/coinpoker.com\/es\/help\/coinpoker-account-faq\/","title":{"rendered":"Preguntas Frecuentes Sobre la Cuenta de CoinPoker"},"content":{"rendered":"\n<div id=\"coinpoker-accordion-block_1c02e6b3f7764454aaab702fd04a4ff6\" class=\"coinpoker-accordion\" role=\"region\" aria-label=\"Accordion content\">\n        <div class=\"cp-accordion\" id=\"accordion-6a03ce460cec0\">\n                    <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03ce460cec0-collapse-1\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03ce460cec0-collapse-1\"\n                        id=\"accordion-6a03ce460cec0-heading-1\">\n                    <div class=\"cp-accordion-heading-text\">\u00bfC\u00f3mo puedo ponerme en contacto con CoinPoker?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03ce460cec0-collapse-1\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03ce460cec0-heading-1\"\n                     data-cp-parent=\"#accordion-6a03ce460cec0\">\n                    <div class=\"cp-accordion-body\">\n                        <p>Puedes ponerte en contacto con nosotros directamente por correo electr\u00f3nico en support@coinpoker.com, a cualquier hora del d\u00eda.<\/p>\n<p>Para cualquier cuesti\u00f3n relacionada con la seguridad, env\u00edenos un correo electr\u00f3nico a security@coinpoker.com.<\/p>\n<p>Para obtener m\u00e1s informaci\u00f3n sobre CoinPoker, visita nuestro sitio web <a href=\"https:\/\/coinpoker.com\/es\/\">www.CoinPoker.com<\/a>.<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03ce460cec0-collapse-2\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03ce460cec0-collapse-2\"\n                        id=\"accordion-6a03ce460cec0-heading-2\">\n                    <div class=\"cp-accordion-heading-text\">He olvidado mi contrase\u00f1a. \u00bfC\u00f3mo puedo restablecerla?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03ce460cec0-collapse-2\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03ce460cec0-heading-2\"\n                     data-cp-parent=\"#accordion-6a03ce460cec0\">\n                    <div class=\"cp-accordion-body\">\n                        <p>Puedes restablecer la contrase\u00f1a de tu cuenta de CoinPoker siguiendo estos pasos:<\/p>\n<ul>\n<li>Inicia sesi\u00f3n en CoinPoker desde el programa de escritorio o la aplicaci\u00f3n m\u00f3vil.<\/li>\n<li>Haz clic en la opci\u00f3n <strong>\u00bfHas olvidado tu contrase\u00f1a?<\/strong> que aparece debajo del campo de inicio de sesi\u00f3n.<\/li>\n<li>Introduce tu direcci\u00f3n de correo electr\u00f3nico registrada y haz clic en continuar.<\/li>\n<li>Te enviaremos un correo electr\u00f3nico con un c\u00f3digo OTP a esta direcci\u00f3n si coincide con una cuenta de CoinPoker.<\/li>\n<li>Introduce una nueva contrase\u00f1a y el c\u00f3digo OTP que has recibido en tu correo electr\u00f3nico registrado.<\/li>\n<li>Haz clic en el bot\u00f3n Restablecer Contrase\u00f1a para restablecerla.<\/li>\n<\/ul>\n<p>Nota: Siempre recomendamos cambiar la contrase\u00f1a de tu cuenta de CoinPoker con regularidad para garantizar su seguridad. Por seguridad, te recomendamos que cambies tu contrase\u00f1a cada pocos meses.<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03ce460cec0-collapse-3\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03ce460cec0-collapse-3\"\n                        id=\"accordion-6a03ce460cec0-heading-3\">\n                    <div class=\"cp-accordion-heading-text\">\u00bfPuedo cambiar mi nombre de usuario?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03ce460cec0-collapse-3\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03ce460cec0-heading-3\"\n                     data-cp-parent=\"#accordion-6a03ce460cec0\">\n                    <div class=\"cp-accordion-body\">\n                        <p>No, los nombres de usuario no se pueden cambiar.<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03ce460cec0-collapse-4\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03ce460cec0-collapse-4\"\n                        id=\"accordion-6a03ce460cec0-heading-4\">\n                    <div class=\"cp-accordion-heading-text\">\u00bfPuedo cambiar mi direcci\u00f3n de correo electr\u00f3nico?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03ce460cec0-collapse-4\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03ce460cec0-heading-4\"\n                     data-cp-parent=\"#accordion-6a03ce460cec0\">\n                    <div class=\"cp-accordion-body\">\n                        <p>Si necesitas cambiar tu direcci\u00f3n de correo electr\u00f3nico, ponte en contacto con <a href=\"mailto:support@coinpoker.com\">support@coinpoker.com<\/a>.<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03ce460cec0-collapse-5\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03ce460cec0-collapse-5\"\n                        id=\"accordion-6a03ce460cec0-heading-5\">\n                    <div class=\"cp-accordion-heading-text\">\u00bfC\u00f3mo puedo comprobar cu\u00e1ntas monedas he acumulado?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03ce460cec0-collapse-5\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03ce460cec0-heading-5\"\n                     data-cp-parent=\"#accordion-6a03ce460cec0\">\n                    <div class=\"cp-accordion-body\">\n                        <p>Puedes consultar tus monedas siguiendo los pasos que se indican a continuaci\u00f3n:<\/p>\n<ul>\n<li>Haz clic en el icono del monedero situado en la esquina superior derecha de la aplicaci\u00f3n de escritorio o m\u00f3vil de CoinPoker.<\/li>\n<li>Haz clic en <strong>Seguimiento de Monedas<\/strong>. Aqu\u00ed ver\u00e1s el total de coins que has generado dentro de un periodo de tiempo determinado al jugar partidas de poker<\/li>\n<\/ul>\n<p><strong>Nota<\/strong>: Puedes filtrar juegos y fechas haciendo clic en el filtro en la esquina superior izquierda Ten en cuenta que solo podr\u00e1s consultar las monedas que hayas generado en los \u00faltimos 3 meses.<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03ce460cec0-collapse-6\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03ce460cec0-collapse-6\"\n                        id=\"accordion-6a03ce460cec0-heading-6\">\n                    <div class=\"cp-accordion-heading-text\">Estoy recibiendo correos electr\u00f3nicos promocionales, \u00bfc\u00f3mo puedo dejar de recibirlos?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03ce460cec0-collapse-6\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03ce460cec0-heading-6\"\n                     data-cp-parent=\"#accordion-6a03ce460cec0\">\n                    <div class=\"cp-accordion-body\">\n                        <p>Para dejar de recibir correos electr\u00f3nicos promocionales, haz clic en la opci\u00f3n <strong>Cancelar suscripci\u00f3n<\/strong> que aparece en el correo electr\u00f3nico. Para desactivar las notificaciones push de las aplicaciones, ve a los ajustes del tel\u00e9fono y desactiva las notificaciones push de las aplicaciones.<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03ce460cec0-collapse-7\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03ce460cec0-collapse-7\"\n                        id=\"accordion-6a03ce460cec0-heading-7\">\n                    <div class=\"cp-accordion-heading-text\">He olvidado mi nombre de usuario de CoinPoker, \u00bfc\u00f3mo puedo recuperarlo?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03ce460cec0-collapse-7\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03ce460cec0-heading-7\"\n                     data-cp-parent=\"#accordion-6a03ce460cec0\">\n                    <div class=\"cp-accordion-body\">\n                        <p>Puedes recuperar el nombre de usuario de tu cuenta de CoinPoker consultando tu correo electr\u00f3nico registrado. Cualquier correo electr\u00f3nico que te enviemos sobre transferencias de recompensas o dep\u00f3sitos mencionar\u00e1 tu nombre de usuario<\/p>\n<p>Alternativamente, puedes restablecer tu contrase\u00f1a y recibir un nuevo correo electr\u00f3nico por nuestra parte Esto significa que ver\u00e1s tu nombre de usuario, pero tambi\u00e9n tendr\u00e1s que restablecer tu contrase\u00f1a.<\/p>\n<ul>\n<li>Inicia sesi\u00f3n en CoinPoker desde el software de PC o la app m\u00f3vil.<\/li>\n<li>Haz clic en la opci\u00f3n <strong>\u00bfHas olvidado tu contrase\u00f1a?<\/strong> que aparece debajo del campo de inicio de sesi\u00f3n.<\/li>\n<li>Introduce tu direcci\u00f3n de correo electr\u00f3nico registrada y haz clic en continuar.<\/li>\n<li>Te enviaremos un correo electr\u00f3nico con un c\u00f3digo OTP a esta direcci\u00f3n si coincide con una cuenta de CoinPoker.<\/li>\n<li>Introduce una nueva contrase\u00f1a y el c\u00f3digo OTP que has recibido en tu correo electr\u00f3nico registrado.<\/li>\n<li>Haz clic en el bot\u00f3n Restablecer Contrase\u00f1a para restablecerla.<\/li>\n<\/ul>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03ce460cec0-collapse-8\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03ce460cec0-collapse-8\"\n                        id=\"accordion-6a03ce460cec0-heading-8\">\n                    <div class=\"cp-accordion-heading-text\">\u00bfPuedo compartir mi contrase\u00f1a con otra persona para jugar?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03ce460cec0-collapse-8\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03ce460cec0-heading-8\"\n                     data-cp-parent=\"#accordion-6a03ce460cec0\">\n                    <div class=\"cp-accordion-body\">\n                        <p>Queda estrictamente prohibido compartir o divulgar la contrase\u00f1a a cualquier otro usuario, persona, grupo o tercero. CoinPoker no se hace responsable si otras personas acceden a tu cuenta o la abren utilizando tu contrase\u00f1a.<\/p>\n<p>Eres legalmente responsable de todas las actividades en la plataforma realizadas desde tu Cuenta, hayan sido realizadas por ti o no.<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03ce460cec0-collapse-9\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03ce460cec0-collapse-9\"\n                        id=\"accordion-6a03ce460cec0-heading-9\">\n                    <div class=\"cp-accordion-heading-text\">\u00bfC\u00f3mo cambio mi contrase\u00f1a?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03ce460cec0-collapse-9\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03ce460cec0-heading-9\"\n                     data-cp-parent=\"#accordion-6a03ce460cec0\">\n                    <div class=\"cp-accordion-body\">\n                        <p>Sigue los pasos que se indican a continuaci\u00f3n para cambiar tu contrase\u00f1a:<\/p>\n<ul>\n<li>En la aplicaci\u00f3n m\u00f3vil o de escritorio, pulsa sobre tu avatar y abre <strong>Mi perfil<\/strong>; en la p\u00e1gina siguiente, pulsa sobre <strong>Seguridad de la cuenta<\/strong>.<\/li>\n<li>Pulsa en <strong>Cambiar contrase\u00f1a.<\/strong><\/li>\n<li>Te enviaremos un c\u00f3digo OTP a tu correo electr\u00f3nico registrado. Introduce el c\u00f3digo y la nueva contrase\u00f1a.<\/li>\n<li>A continuaci\u00f3n, pulsa el bot\u00f3n <strong>Continuar<\/strong> para restablecer la contrase\u00f1a.<\/li>\n<\/ul>\n<p>Nota: Siempre recomendamos cambiar la contrase\u00f1a de tu cuenta de CoinPoker con regularidad para garantizar su seguridad. Por seguridad, te recomendamos que cambies tu contrase\u00f1a cada pocos meses.<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03ce460cec0-collapse-10\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03ce460cec0-collapse-10\"\n                        id=\"accordion-6a03ce460cec0-heading-10\">\n                    <div class=\"cp-accordion-heading-text\">\u00bfC\u00f3mo puedo activar la verificaci\u00f3n en dos pasos?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03ce460cec0-collapse-10\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03ce460cec0-heading-10\"\n                     data-cp-parent=\"#accordion-6a03ce460cec0\">\n                    <div class=\"cp-accordion-body\">\n                        <p>Sigue los pasos que se indican a continuaci\u00f3n para activar la verificaci\u00f3n en dos pasos:<\/p>\n<ul>\n<li>Inicia sesi\u00f3n en CoinPoker.<\/li>\n<li>Selecciona <strong>Mi perfil<\/strong> en el men\u00fa y, a continuaci\u00f3n, pulsa en <strong>Seguridad de la cuenta<\/strong>.<\/li>\n<li>Pulsa en el PIN de seguridad para crear o ajustar el c\u00f3digo PIN de 4 d\u00edgitos<\/li>\n<\/ul>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03ce460cec0-collapse-11\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03ce460cec0-collapse-11\"\n                        id=\"accordion-6a03ce460cec0-heading-11\">\n                    <div class=\"cp-accordion-heading-text\">\u00bfC\u00f3mo puedo cambiar mi avatar o mi foto de perfil?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03ce460cec0-collapse-11\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03ce460cec0-heading-11\"\n                     data-cp-parent=\"#accordion-6a03ce460cec0\">\n                    <div class=\"cp-accordion-body\">\n                        <p>Puedes seguir los pasos que se indican a continuaci\u00f3n para cambiar tu avatar:<\/p>\n<ul>\n<li>Durante una partida en CoinPoker, selecciona <strong>Configuraci\u00f3n de la mesa<\/strong>.<\/li>\n<li>Debajo de <strong>Temas<\/strong>, ver\u00e1s <strong>Avatares<\/strong>.<\/li>\n<li>Elige de la lista de avatares el dise\u00f1o que m\u00e1s te guste.<\/li>\n<\/ul>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03ce460cec0-collapse-12\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03ce460cec0-collapse-12\"\n                        id=\"accordion-6a03ce460cec0-heading-12\">\n                    <div class=\"cp-accordion-heading-text\">\u00bfQu\u00e9 es el dinero ficticio?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03ce460cec0-collapse-12\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03ce460cec0-heading-12\"\n                     data-cp-parent=\"#accordion-6a03ce460cec0\">\n                    <div class=\"cp-accordion-body\">\n                        <p>Las fichas de dinero ficticio no tienen ning\u00fan valor monetario y solo sirven para practicar el poker en la secci\u00f3n de dinero ficticio del lobby del juego.<\/p>\n<p>Puedes recargar tus fichas de pr\u00e1ctica cada d\u00eda<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03ce460cec0-collapse-13\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03ce460cec0-collapse-13\"\n                        id=\"accordion-6a03ce460cec0-heading-13\">\n                    <div class=\"cp-accordion-heading-text\">\u00bfC\u00f3mo puedo consultar mis tickets de torneo?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03ce460cec0-collapse-13\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03ce460cec0-heading-13\"\n                     data-cp-parent=\"#accordion-6a03ce460cec0\">\n                    <div class=\"cp-accordion-body\">\n                        <p>Para la App M\u00f3vil:<\/p>\n<ul>\n<li>Haz clic en tu avatar, situado en la esquina superior izquierda, y luego haz clic en <strong>Mis Tickets<\/strong>.<\/li>\n<li>Aqu\u00ed encontrar\u00e1s la secci\u00f3n Tickets Actuales, donde podr\u00e1s ver tus entradas sin usar, y la secci\u00f3n Tickets anteriores, donde podr\u00e1s ver tus tickets ya utilizados y caducados.<\/li>\n<\/ul>\n<p>Para el Cliente de Escritorio:<\/p>\n<ul>\n<li>Haz clic en tu nombre de usuario en la esquina superior derecha y, a continuaci\u00f3n, haz clic en <strong>Mi Perfil<\/strong>.<\/li>\n<li>En el men\u00fa de la izquierda, haz clic en <strong>Mis Tickets<\/strong> para ver tus tickets actuales y anteriores.<\/li>\n<\/ul>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03ce460cec0-collapse-14\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03ce460cec0-collapse-14\"\n                        id=\"accordion-6a03ce460cec0-heading-14\">\n                    <div class=\"cp-accordion-heading-text\">Quiero saber el desglose de mi saldo. \u00bfC\u00f3mo lo compruebo?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03ce460cec0-collapse-14\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03ce460cec0-heading-14\"\n                     data-cp-parent=\"#accordion-6a03ce460cec0\">\n                    <div class=\"cp-accordion-body\">\n                        <p>Puedes consultar el desglose de tu saldo en la secci\u00f3n Monedero de la App. Los componentes son:<\/p>\n<ol>\n<li><strong>Saldo total<\/strong>: Este saldo se puede utilizar para jugar en todos los formatos de juego (e incluye el importe de tu dep\u00f3sito). Esto puede convertirse completamente en saldo retirable despu\u00e9s de jugar.<\/li>\n<li><strong>Saldo Retirable<\/strong>: Esto representa tus ganancias, as\u00ed como la cantidad convertida desde el saldo no utilizado, recompensas y bonus liberable<\/li>\n<li><strong>Saldo de Recompensas<\/strong>: Esto incluye las recompensas recibidas en cualquier forma, incluidos los premios en met\u00e1lico de la clasificaci\u00f3n y los premios del programa \u00abRecomienda a un amigo\u00bb. Este importe se puede transferir al saldo disponible para retirar de forma inmediata.<\/li>\n<li><strong>Bonus Liberable<\/strong>: Este bono se va a\u00f1adiendo progresivamente a tu saldo disponible para retirar en funci\u00f3n de tu actividad de juego y de las monedas que generes.<\/li>\n<\/ol>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03ce460cec0-collapse-15\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03ce460cec0-collapse-15\"\n                        id=\"accordion-6a03ce460cec0-heading-15\">\n                    <div class=\"cp-accordion-heading-text\">\u00bfC\u00f3mo puedo consultar mi historial de transacciones?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03ce460cec0-collapse-15\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03ce460cec0-heading-15\"\n                     data-cp-parent=\"#accordion-6a03ce460cec0\">\n                    <div class=\"cp-accordion-body\">\n                        <p>En la aplicaci\u00f3n, haz clic en el icono de tu monedero y, a continuaci\u00f3n, en <strong>Mis transacciones<\/strong>. Aqu\u00ed podr\u00e1s ver todas las transacciones que has realizado en CoinPoker.<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03ce460cec0-collapse-16\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03ce460cec0-collapse-16\"\n                        id=\"accordion-6a03ce460cec0-heading-16\">\n                    <div class=\"cp-accordion-heading-text\">\u00bfC\u00f3mo puedo consultar mi Historial de Manos?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03ce460cec0-collapse-16\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03ce460cec0-heading-16\"\n                     data-cp-parent=\"#accordion-6a03ce460cec0\">\n                    <div class=\"cp-accordion-body\">\n                        <p>Haz clic en tu avatar, situado en la esquina superior izquierda, y luego haz clic en <strong>Historial de Partidas<\/strong>. Aqu\u00ed puedes consultar tu historial de manos de partidas de cash y torneos.<\/p>\n<p><strong>Nota<\/strong>: Puedes consultar el historial de manos de los \u00faltimos 30 d\u00edas.<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03ce460cec0-collapse-17\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03ce460cec0-collapse-17\"\n                        id=\"accordion-6a03ce460cec0-heading-17\">\n                    <div class=\"cp-accordion-heading-text\">\u00bfC\u00f3mo se utiliza el saldo de mi monedero?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03ce460cec0-collapse-17\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03ce460cec0-heading-17\"\n                     data-cp-parent=\"#accordion-6a03ce460cec0\">\n                    <div class=\"cp-accordion-body\">\n                        <p>Si tienes fondos tanto en tu Saldo Retirable como en tu Saldo Total, la cantidad se deducir\u00e1 primero de tu saldo retirable y despu\u00e9s de tu saldo total al entrar en una mesa de Cash Game o Torneo<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                <\/div>\n<\/div>\n\n\n\n<p><\/p>\n\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_redirections_enabled":"","_seopress_redirections_type":"","_seopress_redirections_value":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","editor_notices":[],"_cpsm_do_not_sync":false,"_cpsm_partial_sync":false,"footnotes":""},"topic-category":[436],"class_list":["post-165557","help","type-help","status-publish","hentry","topic-category-coinpoker-account"],"acf":{"card_image":null,"help_view":"","in_app_mode_link":""},"_links":{"self":[{"href":"https:\/\/coinpoker.com\/es\/wp-json\/wp\/v2\/help\/165557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coinpoker.com\/es\/wp-json\/wp\/v2\/help"}],"about":[{"href":"https:\/\/coinpoker.com\/es\/wp-json\/wp\/v2\/types\/help"}],"version-history":[{"count":1,"href":"https:\/\/coinpoker.com\/es\/wp-json\/wp\/v2\/help\/165557\/revisions"}],"predecessor-version":[{"id":165558,"href":"https:\/\/coinpoker.com\/es\/wp-json\/wp\/v2\/help\/165557\/revisions\/165558"}],"wp:attachment":[{"href":"https:\/\/coinpoker.com\/es\/wp-json\/wp\/v2\/media?parent=165557"}],"wp:term":[{"taxonomy":"topic-category","embeddable":true,"href":"https:\/\/coinpoker.com\/es\/wp-json\/wp\/v2\/topic-category?post=165557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}