{"id":165374,"date":"2026-03-30T08:19:58","date_gmt":"2026-03-30T08:19:58","guid":{"rendered":"https:\/\/coinpoker.com\/de\/promotions\/heads-up-cash-game-weltmeisterschaft\/"},"modified":"2026-05-06T07:55:38","modified_gmt":"2026-05-06T07:55:38","slug":"heads-up-cgwc","status":"publish","type":"promotion","link":"https:\/\/coinpoker.com\/de\/promotions\/cgwc\/heads-up\/","title":{"rendered":"Heads-Up-Cash-Game-Weltmeisterschaft"},"content":{"rendered":"\n<section\n        id=\"banner-block-block_00f7cedbe4e6dbd290d9aa3564d81d81\"\n        class=\"home-banner home-banner-block position-relative banner-with-description common-hero-banner mb-md-60 mb-40\"\n        role=\"banner\"\n        aria-labelledby=\"banner-block-block_00f7cedbe4e6dbd290d9aa3564d81d81-heading\">\n            <img loading=\"lazy\" width=\"3840\" height=\"1880\" src=\"https:\/\/coinpoker.com\/de\/wp-content\/uploads\/sites\/13\/2026\/03\/heads-up-banner-image-desktop_no_text-3840x1880-1.webp\" class=\"banner-image-desktop position-absolute top-0 start-0 w-100 h-100 d-none d-lg-block banner-image-position-center\" alt=\"Die CoinPoker &lt;br \/&gt;\r\nHeads-Up-Cash-Game- &lt;br \/&gt;\r\nWeltmeisterschaft \" decoding=\"async\" srcset=\"https:\/\/coinpoker.com\/de\/wp-content\/uploads\/sites\/13\/2026\/03\/heads-up-banner-image-desktop_no_text-3840x1880-1.webp 3840w, https:\/\/coinpoker.com\/de\/wp-content\/uploads\/sites\/13\/2026\/03\/heads-up-banner-image-desktop_no_text-3840x1880-1-300x147.webp 300w, https:\/\/coinpoker.com\/de\/wp-content\/uploads\/sites\/13\/2026\/03\/heads-up-banner-image-desktop_no_text-3840x1880-1-1024x501.webp 1024w, https:\/\/coinpoker.com\/de\/wp-content\/uploads\/sites\/13\/2026\/03\/heads-up-banner-image-desktop_no_text-3840x1880-1-130x63.webp 130w\" sizes=\"auto, (max-width: 3840px) 100vw, 3840px\" \/>    \n            <img loading=\"lazy\" width=\"1128\" height=\"2120\" src=\"https:\/\/coinpoker.com\/de\/wp-content\/uploads\/sites\/13\/2026\/03\/2_heads-up-responsive-mobile-image-1128x2120-1.webp\" class=\"banner-image-mobile position-absolute top-0 start-0 w-100 h-100 d-block d-lg-none\" alt=\"Die CoinPoker &lt;br \/&gt;\r\nHeads-Up-Cash-Game- &lt;br \/&gt;\r\nWeltmeisterschaft \" decoding=\"async\" srcset=\"https:\/\/coinpoker.com\/de\/wp-content\/uploads\/sites\/13\/2026\/03\/2_heads-up-responsive-mobile-image-1128x2120-1.webp 1128w, https:\/\/coinpoker.com\/de\/wp-content\/uploads\/sites\/13\/2026\/03\/2_heads-up-responsive-mobile-image-1128x2120-1-160x300.webp 160w, https:\/\/coinpoker.com\/de\/wp-content\/uploads\/sites\/13\/2026\/03\/2_heads-up-responsive-mobile-image-1128x2120-1-545x1024.webp 545w\" sizes=\"auto, (max-width: 1128px) 100vw, 1128px\" \/>        <div class=\"container burger position-relative block-banner-container\">\n        <div class=\"row\">\n            <div class=\"col-xl home-banner-content\">\n                                    <h1 id=\"banner-block-block_00f7cedbe4e6dbd290d9aa3564d81d81-heading\"\n                        class=\"banner-heading banner-heading--medium\">\n                        Die CoinPoker <br \/>\r\nHeads-Up-Cash-Game- <br \/>\r\nWeltmeisterschaft                     <\/h1>\n                \n                \n                <div class=\"banner-bottom-content-wrapper\">\n                                            <ul class=\"home-banner-list mt-20 mb-40 text-white\" role=\"list\"\n                            aria-label=\"Key features\">\n                                                            <li class=\"wp-block-media-text\" role=\"listitem\">\n                                                                            <figure class=\"wp-block-media-text__media\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"50\" height=\"50\"\n                                                 src=\"https:\/\/coinpoker.com\/de\/wp-content\/uploads\/sites\/13\/2025\/04\/White.png\" alt=\"bullet point decoration\"\n                                                 class=\"size-full\">\n                                        <\/figure>\n                                    \n                                                                            <div class=\"wp-block-media-text__content\">\n                                            <p>\ud83d\udc51 SeaLlama (NLHE)<\/p>\n                                        <\/div>\n                                                                    <\/li>\n                                                            <li class=\"wp-block-media-text\" role=\"listitem\">\n                                                                            <figure class=\"wp-block-media-text__media\">\n                                            <img loading=\"lazy\" decoding=\"async\" width=\"50\" height=\"50\"\n                                                 src=\"https:\/\/coinpoker.com\/de\/wp-content\/uploads\/sites\/13\/2025\/04\/White.png\" alt=\"bullet point decoration\"\n                                                 class=\"size-full\">\n                                        <\/figure>\n                                    \n                                                                            <div class=\"wp-block-media-text__content\">\n                                            <p>\ud83d\udc51 Yodogoki (PLO)<\/p>\n                                        <\/div>\n                                                                    <\/li>\n                                                    <\/ul>\n                    \n                                    <\/div>\n            <\/div>\n            <div class=\"col-xl\" aria-hidden=\"true\"><\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n<section class=\"last-updated-info-section\">\n    <div class=\"container\">\n        <p class=\"last-updated-info\">Last Updated: 6 Mai 2026<\/p>\n    <\/div>\n<\/section>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center has-large-font-size\">Unsere HU CGWC-Gewinner<\/h2>\n\n\n\n<p class=\"has-text-align-center\">Die erste Heads-Up-Cashgame-Weltmeisterschaft ist beendet und die Champions wurden gek\u00fcrt.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Die Gruppenphase beider Formate war ein Kopf-an-Kopf-Rennen, insbesondere in den PLO-Gruppen, wo weniger als 20 Punkte dar\u00fcber entschieden, wer ins Halbfinale einzog und wer nicht.<\/p>\n\n\n\n<p class=\"has-text-align-center\">In den Halbfinals und Finals bewiesen die sp\u00e4teren Sieger beider Formate ihre Klasse, indem sie ihre Gegner deutlich hinter sich lie\u00dfen.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Wir danken allen, die an dieser einzigartigen Cash Game Weltmeisterschaft teilgenommen und den Fans eine grandiose Show geboten haben.<\/p>\n\n\n\n<section class=\"two-column-section mb-30 mb-lg-30 pb-30 pb-lg-30\" id=\"title-two-column-block_1da4f2c625ef4a297cc4eac0c136605e\">\n    <div class=\"container\">\n        <div class=\"row justify-content-center\">\n            \n                                <div class=\"col-12 col-md-6 d-flex\">\n                        <div class=\"card card-content mb-25 w-100\"\n                             role=\"article\"\n                             aria-labelledby=\"box-title-title-two-column-block_1da4f2c625ef4a297cc4eac0c136605e-1\">\n                                                                                                                    <div class=\"mb-0\"><figure class=\"wp-block-image size-large\" style=\"margin-bottom: 9px;margin-top: -15px\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-32092 size-large\" src=\"https:\/\/coinpoker.com\/de\/wp-content\/uploads\/2026\/05\/nlh-hu-cgwc-winners.webp\" alt=\"\" width=\"455\" height=\"255\" \/><\/figure>\n<h3 class=\"wp-block-heading has-medium-font-size\" style=\"text-align: center;border-bottom: 2px solid #0F1014;padding-bottom: 10px;margin-bottom: 10px\">Texas Hold&#8217;em Bracket<\/h3>\n<p style=\"text-align: center\">Den Sieg im Texas Hold&#8217;em-Turnier sicherte sich <strong>SeaLlama<\/strong> , ein gef\u00fcrchteter und bekannter Name an den Tischen der Cash Game World Championship. Er erh\u00e4lt 291.594 Dollar an Preisgeldern sowie den Siegerpreis von 100.000 Dollar, der unter anderem eine Rolex beinhaltet.<\/p>\n<p style=\"text-align: center\">Auf dem zweiten Platz und damit dem Preisgeld von 50.000 US-Dollar landet <strong>KraciFisk<\/strong> , gefolgt von <strong>Jungleman<\/strong> auf dem dritten Platz mit einem Preisgeld von 30.000 US-Dollar.<\/p>\n<p style=\"text-align: center\"><strong>Die drei Spieler mit den h\u00f6chsten Spielgewinnen<\/strong> :<\/p>\n<p style=\"text-align: center\"><table id=\"tablepress-523\" class=\"tablepress tablepress-id-523 coinpoker-table table csop-table\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Spieler<\/th><th class=\"column-2\">Gesamtgewinne<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr class=\"row-2\">\n\t<td class=\"column-1\">SeaLlama<\/td><td class=\"column-2\">$291,594.55<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">Jungleman<\/td><td class=\"column-2\">$241,675.08<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">PR0DIGY<\/td><td class=\"column-2\">$115,556.30<\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/p>\n<\/div>\n                                                    <\/div>\n                    <\/div>\n                                    <div class=\"col-12 col-md-6 d-flex\">\n                        <div class=\"card card-content mb-25 w-100\"\n                             role=\"article\"\n                             aria-labelledby=\"box-title-title-two-column-block_1da4f2c625ef4a297cc4eac0c136605e-2\">\n                                                                                                                    <div class=\"mb-0\"><figure class=\"wp-block-image size-large\" style=\"margin-bottom: 9px;margin-top: -15px\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-32092 size-large\" src=\"https:\/\/coinpoker.com\/de\/wp-content\/uploads\/2026\/05\/plo-hu-cgwc-winners.webp\" alt=\"\" width=\"455\" height=\"255\" \/><\/figure>\n<h3 class=\"wp-block-heading has-medium-font-size\" style=\"text-align: center;border-bottom: 2px solid #0F1014;padding-bottom: 10px;margin-bottom: 10px\">Pot Limit Omaha Bracket<\/h3>\n<p style=\"text-align: center\">Den PLO-Wettbewerb gewann eindeutig <strong>Yodogoki<\/strong> , ein bekannter Stammgast bei CoinPoker, der 188.354 US-Dollar an Spielgewinnen und den 100.000 US-Dollar schweren Siegerpreis, der eine hochwertige Rolex-Uhr beinhaltet, einstreichen wird.<\/p>\n<p style=\"text-align: center\">Ein weiterer Spieler, den wir bei den h\u00f6chsten Online-Eins\u00e4tzen k\u00e4mpfen sahen, <strong>GucciNIKE<\/strong> , belegte den zweiten Platz und erh\u00e4lt das Preisgeld von 30.000 Dollar.<\/p>\n<p style=\"text-align: center\"><strong>Die drei Spieler mit den h\u00f6chsten Spielgewinnen<\/strong> :<\/p>\n<p style=\"text-align: center\"><table id=\"tablepress-524\" class=\"tablepress tablepress-id-524 coinpoker-table table csop-table\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Spieler<\/th><th class=\"column-2\">Gesamtgewinne<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr class=\"row-2\">\n\t<td class=\"column-1\">Yodogoki<\/td><td class=\"column-2\">$188,354.05<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">DogeCoinMaximaliste<\/td><td class=\"column-2\">$146,491.45<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">GucciNIKE<\/td><td class=\"column-2\">$69,174.27<\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/p>\n<\/div>\n                                                    <\/div>\n                    <\/div>\n                        <\/div>\n    <\/div>\n<\/section>\n\n\n\n<br>\n\n\n\n<br>\n\n\n\n<section class=\"tournament-tabs-wrapper px-0\" data-block-instance=\"tournament-tabs-6a03d95adb22e\">\n    <div class=\"container\">\n        <nav id=\"navbar-example2\" class=\"sticky-navs mb-3\">\n            <ul class=\"nav nav-pills cp-line-navbar\">\n                                    <li class=\"nav-item\">\n                        <a class=\"nav-link active\" href=\"#aboutContent\">\n                            Die Heads-Up-CGWC                        <\/a>\n                    <\/li>\n                                    \n                \n                                    <li class=\"nav-item\">\n                        <a class=\"nav-link\" href=\"#leaderboardContent\">\n                            Veranstaltungsb\u00fchnen                        <\/a>\n                    <\/li>\n                \n                                    <li class=\"nav-item\">\n                        <a class=\"nav-link\" href=\"#content_1\">\n                            Die Preise                        <\/a>\n                    <\/li>\n                \n                \n                \n                \n                \n                            <\/ul>\n        <\/nav>\n        <div class=\"tournaments-tab-content-wrapper\">\n                            <div id=\"aboutContent\">\n                    <div class=\"pt-10 pt-lg-50 pb-10 pb-lg-30 section-with-bottom-border\">\n                        <div class=\"row\">\n                            <div class=\"col-12 col-lg-8\">\n                                <h2 class=\"h3\">\n                                    Die Heads-Up-CGWC                                <\/h2>\n                                                                    <p>Der weltweit prestigetr\u00e4chtigste Cash-Game-Wettbewerb kehrte am 6. April mit Buy-ins von 10.000 US-Dollar und ohne Rake zur\u00fcck.<\/p>\n<p>CoinPoker veranstaltet jedes Jahr mehrere <a href=\"https:\/\/coinpoker.com\/de\/promotions\/cgwc\/\">Cash-Game-Weltmeisterschaften<\/a> und zieht damit die Besten der Besten an. Wir w\u00e4hlen immer unterschiedliche Formate und Eins\u00e4tze, und die Spiele haben nie einen Rake. Doch diesmal gab es eine besondere Wendung.<\/p>\n<p>Dies war die erste Eins-gegen-Eins-Cashgame-Serie auf CoinPoker.<\/p>\n<p>Acht Spieler traten beim <a href=\"https:\/\/coinpoker.com\/de\/games\/texas-holdem\/\">Texas Hold&#8217;em-<\/a> Turnier an, und weitere acht k\u00e4mpften beim <a href=\"https:\/\/coinpoker.com\/de\/games\/plo\/\">Pot Limit Omaha<\/a> -Turnier.<\/p>\n<p>Nach der <strong>Gruppenphase<\/strong> und <strong>den Halbfinals<\/strong> wurden im <strong>gro\u00dfen Finale<\/strong> die weltbesten Online-Heads-up-Spieler gek\u00fcrt.<\/p>\n<h3 class=\"wp-block-heading has-large-font-size\">Serien\u00fcbersicht<\/h3>\n<div style=\"padding: 2px;border-radius: 9px;background: linear-gradient(to right, #35394A 75%, #35394A 100%)\">\n<div style=\"background: #101116;border-radius: 7px;padding: 10px 20px;align-items: center;gap: 10px\">\u25ab\ufe0f <strong>Veranstaltungsdatum:<\/strong>\u00a06. April bis 3. Mai 2026<br \/>\n\u25ab\ufe0f <strong>Formate:<\/strong>\u00a0No Limit Texas Hold&#8217;em und Pot Limit Omaha<br \/>\n\u25ab\ufe0f <strong>Wettbewerber:<\/strong> 12 Spieler bei NLHE, 8 Spieler bei PLO<br \/>\n\u25ab\ufe0f <strong>Eins\u00e4tze<\/strong>: 50 $\/100 $<br \/>\n\u25ab\ufe0f <strong>Buy-In:<\/strong>\u00a0100 BB (10.000 $) mit obligatorischer automatischer Wiederaufladung<br \/>\n\u25ab\ufe0f <strong>Rake:<\/strong>\u00a0100 % rake-frei<br \/>\n\u25ab\ufe0f <strong>Ante:<\/strong>\u00a0Kein Ante<\/div>\n<\/div>\n<p>\u00a0<\/p>\n<p>Schalten Sie jederzeit direkt \u00fcber die CoinPoker-Desktop-App in den Heads-Up-CGWC ein.<\/p>\n<p>W\u00e4hlen Sie den Reiter CGWC, um eine Serien\u00fcbersicht, die laufenden Spiele und die Tabelle anzuzeigen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-183365\" src=\"https:\/\/coinpoker.com\/de\/wp-content\/uploads\/2026\/03\/cgwc-matches-apr6.webp\" alt=\"\" width=\"1450\" height=\"1025\" \/><\/p>\n<h4 class=\"wp-block-heading has-large-font-size\">\u00c4nderung der Eins\u00e4tze und Pokerformate<\/h4>\n<p>Bei der Heads-Up-Cash-Game-Weltmeisterschaft k\u00f6nnen sich die Spieler auf einige \u00c4nderungen einigen.<\/p>\n<ol>\n<li><strong>Eins\u00e4tze<\/strong>: Der Mindesteinsatz betr\u00e4gt 50 $\/100 $, Spieler k\u00f6nnen sich jedoch auch f\u00fcr h\u00f6here Eins\u00e4tze entscheiden.<\/li>\n<li><strong>Poker-Formate<\/strong>: Bei Pot-Limit-Omaha-Turnieren k\u00f6nnen die Teilnehmer zwischen PLO5 und PLO6 w\u00e4hlen.<\/li>\n<\/ol>\n<p>\u00c4nderungen m\u00fcssen von beiden Kontrahenten vollst\u00e4ndig vereinbart werden und gelten nicht f\u00fcr zuk\u00fcnftige Spiele.<\/p>\n                                                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            \n            \n                            <div id=\"leaderboardContent\" class=\"\">\n                    <div class=\"pt-10 pt-lg-50 pb-10 pb-lg-30 section-with-bottom-border\">\n                        <h2 class=\"h3\">\n                            Veranstaltungsb\u00fchnen                        <\/h2>\n                                                    <p>Die Heads Up Cash Game Weltmeisterschaft war in drei Phasen unterteilt.<\/p>\n<h3 class=\"wp-block-heading has-large-font-size\">Gruppenphase \u2013 6. bis 19. April<\/h3>\n<p><strong>Beim Pot Limit Omaha Event<\/strong> spielten die Spieler in ihrer Vierergruppe 1.250 H\u00e4nde gegen jeden Gegner. Die jeweils zwei st\u00e4rksten Spieler jeder Gruppe erreichten das Halbfinale.<\/p>\n<p><strong>Beim Texas Hold&#8217;em Event<\/strong> traten die Spieler in ihrer Dreiergruppe 1.875 H\u00e4nde lang gegen jeden Gegner an. Der jeweils st\u00e4rkste Spieler jeder Gruppe erreichte das Halbfinale.<\/p>\n<p>In der Gruppenphase wurde ein Punktesystem zur Ermittlung der Sieger eingesetzt.<\/p>\n<ul>\n<li><strong>Spielgewinne<\/strong>: F\u00fcr jeden gewonnenen Spiel erhielten die Spieler 50 Punkte.<\/li>\n<li><strong>EV BB-Wertung<\/strong>: Die Spieler konnten in jedem Spiel zwischen 0 und 150 Punkten gewinnen oder verlieren.<br \/>\n10 EV BB entspricht 1 Punkt, gerundet auf die n\u00e4chste ganze Zahl.<\/li>\n<\/ul>\n<p>Spieler konnten in einem einzelnen Spiel maximal 200 Punkte gewinnen: 150 Punkte vom EV BB (15 Buy-Ins) plus 50 Punkte f\u00fcr den Sieg.<\/p>\n<p>In den Teilnahmebedingungen erfahren Sie mehr \u00fcber die Punktevergabe f\u00fcr die Gruppenphase.<\/p>\n<h3 class=\"wp-block-heading has-large-font-size\">Halbfinale \u2013 20. bis 26. April<\/h3>\n<p>Der Spieler mit der h\u00f6chsten Gesamtpunktzahl aus der Gruppenphase erhielt das Recht, seinen Gegner f\u00fcr das Halbfinale auszuw\u00e4hlen.<\/p>\n<p>Jedes Halbfinalspiel dauerte 2000 H\u00e4nde, danach zogen zwei Spieler ins gro\u00dfe Finale ein.<\/p>\n<h3 class=\"wp-block-heading has-large-font-size\">Spiel um Platz 3\/4 \u2013 27. April bis 1. Mai<\/h3>\n<p>Vom 27. April bis zum 3. Mai fand ein Spiel zwischen den Verlierern des Texas Hold&#8217;em Halbfinales statt.<\/p>\n<p>Die Gegner mussten 1.000 H\u00e4nde spielen, um eine Chance auf den dritten Preis in H\u00f6he von 30.000 Dollar zu haben.<\/p>\n<h3 class=\"wp-block-heading has-large-font-size\">Gro\u00dfes Finale \u2013 27. April bis 3. Mai<\/h3>\n<p>Ein legend\u00e4res Duell \u00fcber 2000 H\u00e4nde kr\u00f6nte die Heads-Up-Cashgame-Weltmeister 2026.<\/p>\n<p>Wir haben die gesamte Reise live auf <a href=\"https:\/\/www.youtube.com\/@CoinPoker_TV\">YouTube<\/a> \u00fcbertragen. Wenn Sie die weltbesten Cash-Game-Spieler sehen m\u00f6chten, sind Sie dort genau richtig.<\/p>\n                                            <\/div>\n                <\/div>\n            \n                            <div id=\"content_1\">\n                    <div class=\"pt-10 pt-lg-50 pb-10 pb-lg-30 section-with-bottom-border\">\n                        <div class=\"row align-items-center\">\n                            <div class=\"col-12\">\n                                <h2 class=\"h3\">\n                                    Die Preise                                <\/h2>\n                                                                    <div><p><strong>No Limit Hold&#8217;em Event<\/strong> :<\/p>\n<p>\ud83e\udd47 &#8211; $100,000: Beinhaltet eine Rolex und einen Geldpreis<br \/>\n\ud83e\udd48 &#8211; 50.000 $ Geldpreis<br \/>\n\ud83e\udd49 &#8211; 30.000 $ Geldpreis<\/p>\n<p><strong>Pot Limit Omaha Event<\/strong>:<\/p>\n<p>\ud83e\udd47 &#8211; $100,000: Beinhaltet eine Rolex und einen Geldpreis<br \/>\n\ud83e\udd48 &#8211; 30.000 $ Geldpreis<\/p>\n<p>Die Spieler steuerten jeweils 10.000 US-Dollar bei, wobei CoinPoker 50 % jedes Beitrags hinzuf\u00fcgte.<\/p>\n<\/div>\n                                                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            \n            \n            \n            \n            \n                    <\/div>\n    <\/div>\n<\/section>\n<script>\n    (function () {\n        const blockInstanceId = 'tournament-tabs-6a03d95adb22e';\n        const sectionElement = document.querySelector(`section[data-block-instance=\"${blockInstanceId}\"]`);\n        if (!sectionElement) {\n            return;\n        }\n\n        function getSections(links) {\n            return Array.from(links)\n                .map(link => sectionElement.querySelector(link.getAttribute('href')))\n                .filter(section => section !== null);\n        }\n\n        function activateLink(sections, links) {\n            const yPosition = window.scrollY;\n\n            for (let i = sections.length - 1; i >= 0; i--) {\n                const section = sections[i];\n\n                if (yPosition >= section.offsetTop - 130) {\n                    links.forEach(link => link.classList.remove('active'));\n                    const activeLink = sectionElement.querySelector(`a[href=\"#${section.id}\"]`);\n                    if (activeLink) activeLink.classList.add('active');\n                    return;\n                }\n            }\n        }\n\n        function onScrollHandler() {\n            activateLink(sections, links);\n        }\n\n        function onClickHandler(e) {\n            const target = e.target;\n            if (target.tagName !== 'A') return;\n\n            const href = target.getAttribute('href');\n            if (!href || href.charAt(0) !== '#') return;\n\n            if (!sectionElement.contains(target)) return;\n\n            e.preventDefault();\n\n            const targetElement = sectionElement.querySelector(href);\n            if (targetElement) {\n                const offset = 126;\n                const targetPosition = targetElement.offsetTop - offset;\n\n                window.scrollTo({\n                    top: targetPosition,\n                    behavior: 'smooth'\n                });\n\n                setTimeout(() => {\n                    const targetId = href.substring(1);\n                    history.pushState(null, null, `#${targetId}`);\n                }, 100);\n            }\n        }\n\n        const navbar = sectionElement.querySelector('#navbar-example2');\n        const links = navbar ? Array.from(navbar.querySelectorAll('.cp-line-navbar > li > a')) : [];\n        const sections = getSections(links);\n        const hashLinks = Array.from(sectionElement.querySelectorAll('a[href^=\"#\"]:not([href=\"#\"])'));\n\n        const stickyClass = 'tab-bar-sticky';\n        let stickyNavOffset = 0;\n        if (navbar) {\n            stickyNavOffset = navbar.getBoundingClientRect().top + window.scrollY;\n        }\n\n        function checkStickyNav() {\n            if (!navbar) {\n                return;\n            }\n            if (window.scrollY >= stickyNavOffset - 56) {\n                navbar.classList.add(stickyClass);\n            } else {\n                navbar.classList.remove(stickyClass);\n            }\n        }\n\n        sectionElement.querySelectorAll('.terms-link-toggle').forEach(function (termsLink) {\n            termsLink.addEventListener('click', function (e) {\n                e.preventDefault();\n                const tabPane = termsLink.closest('.tab-pane');\n                const termsContent = tabPane ? tabPane.querySelector('.terms-content-sub') : null;\n                if (!termsContent) {\n                    return;\n                }\n                const isHidden = termsContent.style.display === 'none' || window.getComputedStyle(termsContent).display === 'none';\n                termsContent.style.display = isHidden ? 'block' : 'none';\n                termsLink.classList.toggle('open');\n            });\n        });\n\n        checkStickyNav();\n\n        if (links.length === 0) {\n            window.addEventListener('scroll', checkStickyNav);\n            return;\n        }\n\n        const scrollHandler = function () {\n            onScrollHandler();\n            checkStickyNav();\n        };\n        window.addEventListener('scroll', scrollHandler);\n\n        hashLinks.forEach(link => {\n            const clickHandler = function (e) {\n                onClickHandler(e);\n            };\n            link.addEventListener('click', clickHandler);\n        });\n\n        activateLink(sections, links);\n    })();\n<\/script>\n\n\n\n<div id=\"coinpoker-accordion-block_ecc26e22e083c3b1bdaee5df0754e1ea\" class=\"coinpoker-accordion\" role=\"region\" aria-label=\"Accordion content\">\n            <div class=\"cp-accordion-title\">\n            <h2 class=\"wp-block-heading has-large-font-size\">H\u00e4ufig gestellte Fragen<\/h2>\n        <\/div>\n        <div class=\"cp-accordion\" id=\"accordion-6a03d95adb94b\">\n                    <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d95adb94b-collapse-1\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d95adb94b-collapse-1\"\n                        id=\"accordion-6a03d95adb94b-heading-1\">\n                    <div class=\"cp-accordion-heading-text\">Was ist die Heads-Up-Cash-Game-Weltmeisterschaft?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d95adb94b-collapse-1\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d95adb94b-heading-1\"\n                     data-cp-parent=\"#accordion-6a03d95adb94b\">\n                    <div class=\"cp-accordion-body\">\n                        <p>Eine Heads-Up-Cash-Game-Serie auf CoinPoker mit den weltbesten Spielern und riesigen Echtgeldpreisen.<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d95adb94b-collapse-2\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d95adb94b-collapse-2\"\n                        id=\"accordion-6a03d95adb94b-heading-2\">\n                    <div class=\"cp-accordion-heading-text\">Wann findet die Heads-Up-Cash-Game-Weltmeisterschaft statt?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d95adb94b-collapse-2\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d95adb94b-heading-2\"\n                     data-cp-parent=\"#accordion-6a03d95adb94b\">\n                    <div class=\"cp-accordion-body\">\n                        <p>Die Veranstaltung fand vom 6. April bis zum 3. Mai 2026 statt.<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d95adb94b-collapse-3\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d95adb94b-collapse-3\"\n                        id=\"accordion-6a03d95adb94b-heading-3\">\n                    <div class=\"cp-accordion-heading-text\">Welches Pokerformat wird beim Heads-Up-CGWC verwendet?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d95adb94b-collapse-3\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d95adb94b-heading-3\"\n                     data-cp-parent=\"#accordion-6a03d95adb94b\">\n                    <div class=\"cp-accordion-body\">\n                        <p>Die Serie umfasste sowohl NL10K- als auch PLO10K-Matches. PLO-Spieler k\u00f6nnen in ihren Matches auch 5\/6-Card Pot Limit Omaha spielen.<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d95adb94b-collapse-4\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d95adb94b-collapse-4\"\n                        id=\"accordion-6a03d95adb94b-heading-4\">\n                    <div class=\"cp-accordion-heading-text\">Welche Eins\u00e4tze gelten f\u00fcr die Spiele der Heads-Up-Cash-Game-Weltmeisterschaft?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d95adb94b-collapse-4\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d95adb94b-heading-4\"\n                     data-cp-parent=\"#accordion-6a03d95adb94b\">\n                    <div class=\"cp-accordion-body\">\n                        <p>Die Mindesteins\u00e4tze f\u00fcr das Heads Up CGWC-Spiel betrugen 50 bzw. 100 US-Dollar. Wenn jedoch beide Spieler in einem Match zustimmen, k\u00f6nnen diese Eins\u00e4tze \u00fcber das Minimum von 50 bzw. 100 Dollar hinaus erh\u00f6ht werden.<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d95adb94b-collapse-5\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d95adb94b-collapse-5\"\n                        id=\"accordion-6a03d95adb94b-heading-5\">\n                    <div class=\"cp-accordion-heading-text\">Was ist EV BB und warum wird es bei der Cash-Game-Weltmeisterschaft verwendet?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d95adb94b-collapse-5\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d95adb94b-heading-5\"\n                     data-cp-parent=\"#accordion-6a03d95adb94b\">\n                    <div class=\"cp-accordion-body\">\n                        <p>Der Erwartungswert (EV) in Big Blinds (BB) misst die Rentabilit\u00e4t von Aktionen, nicht den Gewinn oder Verlust in Dollar.<\/p>\n<p>Durch die Verwendung der erwarteten Gewinnquote l\u00e4sst sich das Ergebnis der Spiele bei der Cash-Game-Weltmeisterschaft genauer messen. W\u00fcrden Spiele nach dem gewonnenen oder verlorenen Geld bewertet, k\u00f6nnten bestimmte Spieler Wettbewerbe durch Gl\u00fcck statt durch K\u00f6nnen gewinnen.<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d95adb94b-collapse-6\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d95adb94b-collapse-6\"\n                        id=\"accordion-6a03d95adb94b-heading-6\">\n                    <div class=\"cp-accordion-heading-text\">Gibt es im Heads-Up-CGWC einen Rake?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d95adb94b-collapse-6\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d95adb94b-heading-6\"\n                     data-cp-parent=\"#accordion-6a03d95adb94b\">\n                    <div class=\"cp-accordion-body\">\n                        <p>Nein, alle Spiele der Heads Up Cash Game Weltmeisterschaft waren zu 100 % rake-frei. Die Spieler mussten w\u00e4hrend ihrer Cash Games keine Geb\u00fchren f\u00fcr die Teilnahme bezahlen.<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d95adb94b-collapse-7\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d95adb94b-collapse-7\"\n                        id=\"accordion-6a03d95adb94b-heading-7\">\n                    <div class=\"cp-accordion-heading-text\">Wo kann ich mir die Heads-Up-CGWC ansehen?<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d95adb94b-collapse-7\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d95adb94b-heading-7\"\n                     data-cp-parent=\"#accordion-6a03d95adb94b\">\n                    <div class=\"cp-accordion-body\">\n                        <p>Verfolgen Sie die Live-Berichterstattung und Highlights auf den YouTube-, Twitch- und X-Kan\u00e4len (Twitter) von CoinPoker.<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                <\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<section class=\"pb-40 pb-md-160\" id=\"seo-section-block_6325db6aaffe4936650cb3efc1ed3944\">\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-12\">\n                            <\/div>\n\n                            <div class=\"seo-content\">\n                    <h2 class=\"wp-block-heading has-large-font-size\">Heads-Up-CGWC \u2013 Allgemeine Gesch\u00e4ftsbedingungen<\/h2>\n<p>Die CoinPoker Heads-Up-Cash-Game-Weltmeisterschaft (auch Heads-Up-CGWC genannt) ist eine Cash-Game-Serie, die aus einer Reihe von Einer-gegen-Einen-Spiele besteht.<\/p>\n<p>Diese Veranstaltung findet vom 6. April bis zum 3. Mai statt und umfasst zwei parallel laufende Events (eines f\u00fcr Texas Hold&#8217;em und eines f\u00fcr Pot Limit Omaha), die jeweils \u00fcber eigene Eventphasen (Gruppenphase, Halbfinale und Finale) verf\u00fcgen.<\/p>\n<p>Die Richtlinien f\u00fcr die Heads-Up-CGWC, die einzelnen Veranstaltungsphasen, die Teilnahmebedingungen und den Zeitplan sind nachfolgend aufgef\u00fchrt.<\/p>\n<h3 class=\"wp-block-heading has-medium-font-size\">1. Das Spiel<\/h3>\n<ul>\n<li>Die Teilnehmer der Heads-Up-Cash-Game-Weltmeisterschaft k\u00f6nnen w\u00e4hlen, ob sie am Texas Hold&#8217;em (NLH)-Teilnehmerpool, am Pot Limit Omaha (PLO)-Teilnehmerpool oder an beiden teilnehmen m\u00f6chten.<\/li>\n<li>Die Mindesteins\u00e4tze f\u00fcr das Heads-Up-CGWC betragen 50 $\/100 $ (Buy-In: 10.000 $), wobei w\u00e4hrend der Spiele eine obligatorische automatische Aufladung auf 100 BB aktiv ist.<\/li>\n<li>Von den Spielern wird erwartet, dass sie an mindestens zwei Tischen gleichzeitig spielen. Wenn beide Parteien zustimmen, ist auch das Spielen an nur einem Tisch erlaubt.<\/li>\n<li>Jedes Spiel hat eine festgelegte Anzahl von Runden, die die Spieler absolvieren m\u00fcssen.<\/li>\n<li>Bei Pot Limit Omaha (PLO)-Matches wird standardm\u00e4\u00dfig das Format 4-Card Pot Limit Omaha verwendet. Zwei Spieler k\u00f6nnen jedoch durch gegenseitige Vereinbarung an ihrem Tisch zwischen 4-Card Pot Limit Omaha und 5-Card Pot Limit Omaha (PLO5) oder 6-Card Pot Limit Omaha (PLO6) wechseln.<\/li>\n<li>Bei allen Spielen gelten festgelegte Blinds in H\u00f6he von 50 $ bzw. 100 $. Allerdings k\u00f6nnen sich zwei Spieler jederzeit darauf einigen, den Einsatz zu erh\u00f6hen oder zu senken, wobei 50 $\/100 $ der Standard-Mindesteinsatz sind.<\/li>\n<li>Bei diesem Event der Heads-Up-Cash-Game-Weltmeisterschaft (CGWC) ist das Limpen verboten. Unbeabsichtigt gelimpte H\u00e4nde werden von den EV BB-Ergebnissen und der Gesamtzahl der H\u00e4nde abgezogen. Vors\u00e4tzliche oder wiederholte Verst\u00f6\u00dfe k\u00f6nnen zur Disqualifikation f\u00fchren.<\/li>\n<\/ul>\n<h3 class=\"wp-block-heading has-medium-font-size\">2. Gruppenphase<\/h3>\n<ul>\n<li>Die Gruppenphase der Heads-Up-Cash-Game-Weltmeisterschaft findet vom 6. bis 19. April statt.<\/li>\n<li>Die Gruppeneinteilung w\u00e4hrend der Gruppenphase erfolgt per RNG. Gleichzeitig muss ein Avatar aus dem von CoinPoker bereitgestellten Pool an verf\u00fcgbaren Avataren ausgew\u00e4hlt werden.<\/li>\n<li>Je nach Anzahl der Teilnehmer treten die Spieler in jedem Match gegen jeden anderen Spieler an, insgesamt werden 1.250 bis 1.875 H\u00e4nde gespielt. Die genaue Zahl wird vor Beginn der Gruppenphase bekannt gegeben.<\/li>\n<li>Je nach Teilnehmerzahl qualifiziert sich eine unterschiedliche Anzahl von Spielern f\u00fcr das Halbfinale:<br \/>\n&#8211; Bei 8 Teilnehmern in der Gruppenphase werden 2 Gruppen mit je 4 Spielern gebildet, wobei jeweils 2 Spieler pro Gruppe ins Halbfinale einziehen.<br \/>\n&#8211; Bei 12 Teilnehmern in der Gruppenphase gibt es 4 Gruppen mit je 3 Spielern, wobei jeweils 1 Spieler pro Gruppe ins Halbfinale einzieht.<br \/>\n&#8211; Bei 16 Teilnehmern in der Gruppenphase wird es 4 Gruppen mit je 4 Spielern geben, wobei jeweils 1 Spieler pro Gruppe ins Halbfinale einzieht.<\/li>\n<li>Zur Ermittlung der Gewinner in der Gruppenphase verwendet CoinPoker ein Punktesystem, das im n\u00e4chsten Abschnitt erl\u00e4utert wird.<\/li>\n<\/ul>\n<h4 class=\"wp-block-heading has-medium-font-size\">2.1. Das Punktesystem der Gruppenphase<\/h4>\n<ul>\n<li>Der Sieg in einem Gruppenspiel bringt dem Gewinner 50 Punkte ein.<\/li>\n<li>Spieler k\u00f6nnen je nach ihrem EV- BB-Wert zwischen 0 und 150 Punkten pro Spiel gewinnen oder verlieren.<\/li>\n<li>10 EV BB entsprechen 1 Punkt in der Gruppenphase.<\/li>\n<li>Die maximale Punktzahl, die ein Spieler in einem einzelnen Spiel der Gruppenphase erreichen kann, betr\u00e4gt 200 Punkte (50 Punkte f\u00fcr den Sieg im Spiel, plus 150 Punkte aus der EV-BB-Wertung).<\/li>\n<li>Wenn zwei Spieler, die ihre Gruppe anf\u00fchren, punktgleich sind, beginnt ein Entscheidungsspiel. Wer als Erster einen Gewinn von 100 BB oder mehr (nicht im Erwartungswert) erzielt, gewinnt bei Gleichstand.<\/li>\n<li>Gibt ein Spieler ein Match auf, erh\u00e4lt jeder in der Gruppe 50 Punkte, als h\u00e4tte er sein Match gegen diesen Spieler gewonnen; sein Gegner im Match erh\u00e4lt au\u00dferdem die volle Punktzahl proportional zu den gewonnenen EV BBs, w\u00e4hrend die anderen Spieler die H\u00e4lfte dieser Punktzahl erhalten.<\/li>\n<\/ul>\n<h3 class=\"wp-block-heading has-medium-font-size\">3. Die Halbfinal-Runden<\/h3>\n<ul>\n<li>Die Halbfinalrunden finden vom 20. bis 26. April im Anschluss an die Gruppenphase statt.<\/li>\n<li>Der Spieler mit der h\u00f6chsten Gesamtpunktzahl am Ende der Gruppenphase hat die M\u00f6glichkeit, seinen Gegner f\u00fcr das Halbfinale auszuw\u00e4hlen.<\/li>\n<li>Die Halbfinalspiele dauern 2.000 H\u00e4nde.<\/li>\n<li>Zwei Spieler werden vom Halbfinale ins gro\u00dfe Finale einziehen.<\/li>\n<\/ul>\n<h3 class=\"wp-block-heading has-medium-font-size\">4. Spiel um Platz 3\/4<\/h3>\n<ul>\n<li>Beim Texas Hold&#8217;em Event findet zwischen dem 27. April und dem 1. Mai ein Spiel zwischen den Verlierern des Halbfinales um den dritten Platz mit einem Preisgeld von 30.000 US-Dollar statt.<\/li>\n<li>F\u00fcr das Spiel um Platz 3\/4 m\u00fcssen 1000 H\u00e4nde gespielt werden.<\/li>\n<\/ul>\n<h3 class=\"wp-block-heading has-medium-font-size\">5. Das gro\u00dfe Finale<\/h3>\n<ul>\n<li>Das gro\u00dfe Finale findet vom 27. April bis zum 3. Mai im Anschluss an das Halbfinale statt.<\/li>\n<li>F\u00fcr die Spiele des gro\u00dfen Finales m\u00fcssen 2.000 H\u00e4nde gespielt werden.<\/li>\n<\/ul>\n<h3 class=\"wp-block-heading has-medium-font-size\">6. Teilnahme<\/h3>\n<ul>\n<li>Im Heads-Up-CGWC steht nur eine begrenzte Anzahl an Spielerpl\u00e4tzen zur Verf\u00fcgung. Die Zulassung der Bewerber zu der Veranstaltung liegt im alleinigen Ermessen von CoinPoker.<\/li>\n<li>Abh\u00e4ngig von der Gesamtzahl der an der Veranstaltung teilnehmenden Spieler kann ein Spiel zur Ermittlung des dritten und vierten Platzes stattfinden.<\/li>\n<li>Zus\u00e4tzlich zum Buy-In von 10.000 $ hinterlegt jeder Spieler 10.000 $ auf einem Treuhandkonto als Teilnahmegarantie. Im Falle eines vorzeitigen Ausscheidens aus dem Turnier verf\u00e4llt die Garantie von 10.000 $ und wird an die Spieler in der Gruppe des Ausscheidenden im Verh\u00e4ltnis zur Anzahl der noch zu spielenden H\u00e4nde verteilt.<\/li>\n<li>Von den Spielern wird erwartet, dass sie mit dem Marketingteam von CoinPoker zusammenarbeiten, indem sie gelegentlich Fragen zu ihren Spielen\/H\u00e4nden beantworten. Der Gewinner des Events muss an einem Interview per Text, Audio und\/oder Video teilnehmen.<\/li>\n<li>Vor Beginn der Gruppenphase m\u00fcssen die Spieler einen Avatar ausw\u00e4hlen, der noch von keinem anderen Spieler gew\u00e4hlt wurde.<\/li>\n<li>Die Avatare d\u00fcrfen, sobald sie ausgew\u00e4hlt wurden, w\u00e4hrend der gesamten Dauer des Heads-Up-CGWC-Events nicht mehr ge\u00e4ndert werden.<\/li>\n<\/ul>\n<h3 class=\"wp-block-heading has-medium-font-size\">7. Terminplanung<\/h3>\n<ul>\n<li>Von den Spielern wird erwartet, dass sie ihre Heads-Up-Spiele im Rahmen der CGWC privat vereinbaren. Ein Mitarbeiter von CoinPoker wird in diesen Gespr\u00e4chen als Vermittler fungieren.<\/li>\n<li>Falls keine Einigung \u00fcber einen Termin erzielt werden kann, wird CoinPoker das Heads-Up-CGWC-Match unter Ber\u00fccksichtigung der Verf\u00fcgbarkeit beider Spieler nach bestem Wissen und Gewissen ansetzen.<\/li>\n<li>Erscheint einer der beiden Spieler nicht zum angesetzten Zeitpunkt zum Spiel, f\u00fchrt dies zur Spielverlust.<\/li>\n<li>Der Verlust eines Spiels kann sich auf die Punkte w\u00e4hrend der Gruppenphase und auch auf die Teilnahmegarantie des Spielers auswirken, die im Abschnitt \u201eTeilnahme\u201c beschrieben ist.<\/li>\n<\/ul>\n<h3 class=\"wp-block-heading has-medium-font-size\">8. Allgemein<\/h3>\n<ul>\n<li>Die Teilnahme an dieser Aktion setzt die vollst\u00e4ndige Akzeptanz und das Verst\u00e4ndnis dieser Teilnahmebedingungen voraus.<\/li>\n<li>Diese Aktion unterliegt den <a href=\"https:\/\/coinpoker.com\/de\/terms-and-conditions\/\">Allgemeinen Gesch\u00e4ftsbedingungen<\/a> von CoinPoker.<\/li>\n<li>Von allen Teilnehmern des Heads-Up-CGWC wird ein hohes Ma\u00df an Sportsgeist und Spielethik erwartet. CoinPoker wird alle Spiele auf Verst\u00f6\u00dfe gegen den Geist dieser Bedingungen oder die Nutzungsbedingungen von CoinPoker \u00fcberwachen.<\/li>\n<li>Alle von CoinPoker getroffenen Entscheidungen hinsichtlich der Teilnahmeberechtigung, Berechnungen, Streitigkeiten, Durchsetzungsma\u00dfnahmen oder der Auslegung dieser Bedingungen sind endg\u00fcltig und verbindlich.<\/li>\n<\/ul>\n                <\/div>\n                    <\/div>\n    <\/div>\n<\/section>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unsere HU CGWC-Gewinner Die erste Heads-Up-Cashgame-Weltmeisterschaft ist beendet und die Champions wurden gek\u00fcrt. Die Gruppenphase beider Formate war ein Kopf-an-Kopf-Rennen, insbesondere in den PLO-Gruppen, wo weniger als 20 Punkte dar\u00fcber entschieden, wer ins Halbfinale einzog und wer nicht. In den Halbfinals und Finals bewiesen die sp\u00e4teren Sieger beider Formate ihre Klasse, indem sie ihre Gegner <a href=\"https:\/\/coinpoker.com\/de\/promotions\/cgwc\/heads-up\/\" class=\"more-link\">&#8230;<span class=\"screen-reader-text\">  Heads-Up-Cash-Game-Weltmeisterschaft<\/span><\/a><\/p>\n","protected":false},"featured_media":165387,"template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"Heads-Up-Cash-Game-Weltmeisterschaft (CGWC) auf CoinPoker","_seopress_titles_desc":"Bei der CoinPoker Heads-Up-Cash-Game-Weltmeisterschaft gibt es Rolex-Uhren und Geldpreise f\u00fcr Hold'em- und Pot Limit Omaha Heads-Up-Spezialisten.","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_redirections_enabled":"","_seopress_redirections_type":"301","_seopress_redirections_value":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","editor_notices":[],"_cpsm_do_not_sync":false,"_cpsm_partial_sync":false,"footnotes":""},"class_list":["post-165374","promotion","type-promotion","status-publish","has-post-thumbnail","hentry"],"acf":{"card_image":165386,"promotions_price":"","promotions_price_text":""},"_links":{"self":[{"href":"https:\/\/coinpoker.com\/de\/wp-json\/wp\/v2\/promotion\/165374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coinpoker.com\/de\/wp-json\/wp\/v2\/promotion"}],"about":[{"href":"https:\/\/coinpoker.com\/de\/wp-json\/wp\/v2\/types\/promotion"}],"version-history":[{"count":10,"href":"https:\/\/coinpoker.com\/de\/wp-json\/wp\/v2\/promotion\/165374\/revisions"}],"predecessor-version":[{"id":165768,"href":"https:\/\/coinpoker.com\/de\/wp-json\/wp\/v2\/promotion\/165374\/revisions\/165768"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coinpoker.com\/de\/wp-json\/wp\/v2\/media\/165387"}],"wp:attachment":[{"href":"https:\/\/coinpoker.com\/de\/wp-json\/wp\/v2\/media?parent=165374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}