{"id":166724,"date":"2026-05-12T11:59:26","date_gmt":"2026-05-12T11:59:26","guid":{"rendered":"https:\/\/coinpoker.com\/cn\/help\/%e6%b8%b8%e6%88%8f%e7%8e%a9%e6%b3%95%e5%af%bc%e8%88%aa%e5%b8%b8%e8%a7%81%e9%97%ae%e9%a2%98%e8%a7%a3%e7%ad%94\/"},"modified":"2026-05-12T12:06:25","modified_gmt":"2026-05-12T12:06:25","slug":"gameplay-navigation-faq","status":"publish","type":"help","link":"https:\/\/coinpoker.com\/cn\/help\/gameplay-navigation-faq\/","title":{"rendered":"\u6e38\u620f\u73a9\u6cd5\u5bfc\u822a\u5e38\u89c1\u95ee\u9898\u89e3\u7b54"},"content":{"rendered":"\n<div id=\"coinpoker-accordion-block_5642a85ff3dbe1101c442ee15fa35187\" class=\"coinpoker-accordion\" role=\"region\" aria-label=\"Accordion content\">\n        <div class=\"cp-accordion\" id=\"accordion-6a03d8bce7269\">\n                    <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bce7269-collapse-1\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bce7269-collapse-1\"\n                        id=\"accordion-6a03d8bce7269-heading-1\">\n                    <div class=\"cp-accordion-heading-text\">\u54ea\u91cc\u53ef\u4ee5\u627e\u5230\u9526\u6807\u8d5b\u4fe1\u606f\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bce7269-collapse-1\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bce7269-heading-1\"\n                     data-cp-parent=\"#accordion-6a03d8bce7269\">\n                    <div class=\"cp-accordion-body\">\n                        <p><span style=\"font-weight: 400\">\u79fb\u52a8\u5e94\u7528\u7248\uff1a<\/span><\/p>\n<ul>\n<li><span style=\"font-weight: 400\">\u6253\u5f00 CoinPoker \u5e94\u7528\u7a0b\u5e8f\u540e\uff0c\u70b9\u51fb<strong>\u201c\u9526\u6807\u8d5b\u201d<\/strong> \u3002<\/span><\/li>\n<li>\u8fd9\u91cc\u5217\u51fa\u4e86\u6240\u6709\u9526\u6807\u8d5b\u3002\u5b83\u663e\u793a\u4e86\u9526\u6807\u8d5b\u540d\u79f0\u3001\u5956\u91d1\u6c60\uff08\u6216\u95e8\u7968\uff09\u3001\u53c2\u8d5b\u4eba\u6570\u3001\u62a5\u540d\u8d39\u548c\u62a5\u540d\u65f6\u95f4\u3002<\/li>\n<li>\u70b9\u51fb\u60a8\u9009\u62e9\u7684\u9526\u6807\u8d5b\u3002<\/li>\n<li>\u70b9\u51fb\u201c\u62a5\u540d\u201d\u3002\u5982\u679c\u60a8\u7684\u8d44\u91d1\u4e0d\u8db3\u4ee5\u4e70\u5165\uff0c\u7cfb\u7edf\u4f1a\u63d0\u793a\u60a8\u5145\u503c\u3002<\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">\u9526\u6807\u8d5b\u5f00\u59cb\u540e\uff0c\u60a8\u5c06\u88ab\u81ea\u52a8\u5206\u914d\u4e00\u4e2a\u5ea7\u4f4d\uff0c\u5373\u53ef\u5f00\u59cb\u6bd4\u8d5b\u3002<\/span><\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bce7269-collapse-2\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bce7269-collapse-2\"\n                        id=\"accordion-6a03d8bce7269-heading-2\">\n                    <div class=\"cp-accordion-heading-text\">\u6211\u5982\u4f55\u62a5\u540d\u53c2\u52a0\u9526\u6807\u8d5b\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bce7269-collapse-2\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bce7269-heading-2\"\n                     data-cp-parent=\"#accordion-6a03d8bce7269\">\n                    <div class=\"cp-accordion-body\">\n                        <ul>\n<li><span style=\"font-weight: 400\">\u6253\u5f00 CoinPoker \u5e94\u7528\u7a0b\u5e8f\u540e\uff0c\u70b9\u51fb<strong>\u201c\u9526\u6807\u8d5b\u201d<\/strong> \u3002<\/span><\/li>\n<li>\u8fd9\u91cc\u5217\u51fa\u4e86\u6240\u6709\u9526\u6807\u8d5b\u3002\u5b83\u663e\u793a\u4e86\u9526\u6807\u8d5b\u540d\u79f0\u3001\u5956\u91d1\u6c60\uff08\u6216\u95e8\u7968\uff09\u3001\u53c2\u8d5b\u4eba\u6570\u3001\u62a5\u540d\u8d39\u548c\u62a5\u540d\u65f6\u95f4\u3002<\/li>\n<li>\u70b9\u51fb\u60a8\u9009\u62e9\u7684\u9526\u6807\u8d5b\u3002<\/li>\n<li>\u5982\u679c\u9526\u6807\u8d5b\u5df2\u7ecf\u5f00\u59cb\u4e14\u5141\u8bb8\u5ef6\u8fdf\u62a5\u540d\uff0c\u8bf7\u70b9\u51fb<strong>\u201c\u62a5\u540d\u201d<\/strong> \u3002\u5982\u679c\u60a8\u7684\u8d44\u91d1\u4e0d\u8db3\u4ee5\u4e70\u5165\uff0c\u7cfb\u7edf\u4f1a\u63d0\u793a\u60a8\u5145\u503c\u3002<\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">\u9526\u6807\u8d5b\u5f00\u59cb\u540e\uff0c\u60a8\u5c06\u88ab\u81ea\u52a8\u5206\u914d\u4e00\u4e2a\u5ea7\u4f4d\uff0c\u5373\u53ef\u5f00\u59cb\u6bd4\u8d5b\u3002<\/span><\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bce7269-collapse-3\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bce7269-collapse-3\"\n                        id=\"accordion-6a03d8bce7269-heading-3\">\n                    <div class=\"cp-accordion-heading-text\">\u6211\u5982\u4f55\u624d\u80fd\u5ef6\u8fdf\u62a5\u540d\u6bd4\u8d5b\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bce7269-collapse-3\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bce7269-heading-3\"\n                     data-cp-parent=\"#accordion-6a03d8bce7269\">\n                    <div class=\"cp-accordion-body\">\n                        <ul>\n<li><span style=\"font-weight: 400\">\u6253\u5f00 CoinPoker \u5e94\u7528\u7a0b\u5e8f\u540e\uff0c\u70b9\u51fb<strong>\u201c\u9526\u6807\u8d5b\u201d<\/strong> \u3002<\/span><\/li>\n<li>\u8fd9\u91cc\u5217\u51fa\u4e86\u6240\u6709\u9526\u6807\u8d5b\u3002\u5b83\u663e\u793a\u4e86\u9526\u6807\u8d5b\u540d\u79f0\u3001\u5956\u91d1\u6c60\uff08\u6216\u95e8\u7968\uff09\u3001\u53c2\u8d5b\u4eba\u6570\u3001\u62a5\u540d\u8d39\u548c\u62a5\u540d\u65f6\u95f4\u3002<\/li>\n<li>\u5bfb\u627e\u663e\u793a\u7ea2\u8272\u201c\u5ef6\u8fdf\u62a5\u540d\u201d\u9009\u9879\u7684\u9526\u6807\u8d5b\u3002<\/li>\n<li>\u70b9\u51fb\u9526\u6807\u8d5b\uff0c\u7136\u540e\u70b9\u51fb\u53f3\u4e0b\u89d2\u7684\u201c\u62a5\u540d\u201d\u3002<\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">\u9526\u6807\u8d5b\u5f00\u59cb\u540e\uff0c\u7acb\u5373\u5f00\u59cb\u6bd4\u8d5b\uff01<\/span><\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bce7269-collapse-4\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bce7269-collapse-4\"\n                        id=\"accordion-6a03d8bce7269-heading-4\">\n                    <div class=\"cp-accordion-heading-text\">\u5982\u4f55\u53d6\u6d88\u53c2\u52a0\u9526\u6807\u8d5b\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bce7269-collapse-4\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bce7269-heading-4\"\n                     data-cp-parent=\"#accordion-6a03d8bce7269\">\n                    <div class=\"cp-accordion-body\">\n                        <ul>\n<li><span style=\"font-weight: 400\">\u6253\u5f00 CoinPoker \u5e94\u7528\u7a0b\u5e8f\u540e\uff0c\u70b9\u51fb<strong>\u201c\u9526\u6807\u8d5b\u201d<\/strong> \u3002<\/span><\/li>\n<li>\u70b9\u51fb\u60a8\u8981\u53d6\u6d88\u62a5\u540d\u7684\u9526\u6807\u8d5b\u3002<\/li>\n<li>\u70b9\u51fb<strong>\u201c\u53d6\u6d88\u62a5\u540d\u201d<\/strong> \uff0c\u5373\u53ef\u6210\u529f\u53d6\u6d88\u53c2\u8d5b\u8d44\u683c\u3002<\/li>\n<\/ul>\n<p>\u8bf7\u7559\u610f\uff1a\u9526\u6807\u8d5b\u5f00\u59cb\u540e\uff0c\u60a8\u5c06\u65e0\u6cd5\u53d6\u6d88\u62a5\u540d\u3002<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bce7269-collapse-5\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bce7269-collapse-5\"\n                        id=\"accordion-6a03d8bce7269-heading-5\">\n                    <div class=\"cp-accordion-heading-text\">\u6211\u5982\u4f55\u91cd\u65b0\u62a5\u540d\u53c2\u52a0\u9526\u6807\u8d5b\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bce7269-collapse-5\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bce7269-heading-5\"\n                     data-cp-parent=\"#accordion-6a03d8bce7269\">\n                    <div class=\"cp-accordion-body\">\n                        <ul>\n<li><span style=\"font-weight: 400\">\u6253\u5f00 CoinPoker \u5e94\u7528\u7a0b\u5e8f\u540e\uff0c\u70b9\u51fb<strong>\u201c\u9526\u6807\u8d5b\u201d<\/strong> \u3002<\/span><\/li>\n<li>\u70b9\u51fb\u60a8\u60f3\u8981\u91cd\u65b0\u62a5\u540d\u7684\u9526\u6807\u8d5b\u3002<\/li>\n<li>\u70b9\u51fb\u201c\u62a5\u540d\u201d\u3002<\/li>\n<\/ul>\n<p><strong>\u8bf7\u7559\u610f<\/strong>\uff1a\u91cd\u65b0\u62a5\u540d\u53ea\u80fd\u5728\u5ef6\u8fdf\u62a5\u540d\u671f\u4e4b\u524d\u8fdb\u884c\u3002<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bce7269-collapse-6\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bce7269-collapse-6\"\n                        id=\"accordion-6a03d8bce7269-heading-6\">\n                    <div class=\"cp-accordion-heading-text\">\u5982\u4f55\u627e\u5230\u514d\u8d39\u53c2\u8d5b\u9526\u6807\u8d5b\uff08\u514d\u8d39\u8d5b\uff09\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bce7269-collapse-6\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bce7269-heading-6\"\n                     data-cp-parent=\"#accordion-6a03d8bce7269\">\n                    <div class=\"cp-accordion-body\">\n                        <ul>\n<li>\u5728\u9009\u5355\u4e2d\u67e5\u627e<strong>\u201c\u514d\u8d39\u9526\u6807\u8d5b\u201d<\/strong>\u533a\u3002<\/li>\n<li>\u8fd9\u91cc\u5217\u51fa\u4e86\u6240\u6709\u514d\u8d39\u9526\u6807\u8d5b\u3002\u5b83\u4f1a\u663e\u793a\u9526\u6807\u8d5b\u540d\u79f0\u3001\u5956\u91d1\u6c60\uff08\u6216\u95e8\u7968\uff09\u3001\u53c2\u8d5b\u4eba\u6570\u3001\u62a5\u540d\u8d39\u548c\u62a5\u540d\u65f6\u95f4\u3002<\/li>\n<li>\u70b9\u51fb\u60a8\u9009\u62e9\u7684\u9526\u6807\u8d5b\u3002<\/li>\n<li>\u70b9\u51fb\u201c\u62a5\u540d\u201d\u5373\u53ef\u53c2\u52a0\u6d3b\u52a8\u3002<\/li>\n<\/ul>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bce7269-collapse-7\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bce7269-collapse-7\"\n                        id=\"accordion-6a03d8bce7269-heading-7\">\n                    <div class=\"cp-accordion-heading-text\">\u6211\u60f3\u4e86\u89e3\u9526\u6807\u8d5b\u7684\u7ed3\u6784\uff0c\u8be5\u5982\u4f55\u67e5\u770b\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bce7269-collapse-7\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bce7269-heading-7\"\n                     data-cp-parent=\"#accordion-6a03d8bce7269\">\n                    <div class=\"cp-accordion-body\">\n                        <ul>\n<li>\u6253\u5f00 CoinPoker \u5e94\u7528\u7a0b\u5e8f\u3002<\/li>\n<li>\u524d\u5f80\u5e94\u7528\u7a0b\u5e8f\u7684<strong>\u201c\u9526\u6807\u8d5b\u201d<\/strong>\u6807\u7b7e\u9875\u3002<\/li>\n<li>\u9009\u62e9\u60a8\u60f3\u53c2\u52a0\u7684\u9526\u6807\u8d5b\u3002<\/li>\n<li>\u60a8\u53ef\u4ee5\u5728\u9876\u90e8\u680f\u770b\u5230\u8be6\u60c5\u3001\u53c2\u8d5b\u4eba\u6570\u3001\u5956\u91d1\u548c\u76f2\u6ce8\u7ed3\u6784\u3002<\/li>\n<li>\u70b9\u51fb\u4ee5\u4e0b\u4efb\u610f\u9009\u9879\u5373\u53ef\u4e86\u89e3\u9526\u6807\u8d5b\u8be6\u60c5\u3002<\/li>\n<\/ul>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bce7269-collapse-8\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bce7269-collapse-8\"\n                        id=\"accordion-6a03d8bce7269-heading-8\">\n                    <div class=\"cp-accordion-heading-text\">\u4ec0\u4e48\u662f\u8d5b\u4e8b\u4e2d\u7684\u201c\u6ce1\u6cab\u671f\u4fdd\u969c\u201d\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bce7269-collapse-8\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bce7269-heading-8\"\n                     data-cp-parent=\"#accordion-6a03d8bce7269\">\n                    <div class=\"cp-accordion-body\">\n                        <p>\u6ce1\u6cab\u671f\u4fdd\u969c\u662f\u9526\u6807\u8d5b\u7684\u4e00\u9879\u5185\u7f6e\u529f\u80fd\uff0c\u5f53\u60a8\u5728\u6ce1\u6cab\u9636\u6bb5\u51fa\u5c40\u65f6\uff0c\u5b83\u4f1a\u81ea\u52a8\u9000\u8fd8\u60a8\u7684\u4e70\u5165\u8d39\u7528\u3002<\/p>\n<p>\u6ee1\u8db3\u4ee5\u4e0b\u6761\u4ef6\u5373\u53ef\u542f\u7528\u6b64\u529f\u80fd\uff1a<\/p>\n<ul>\n<li>\u5c3d\u65e9\u62a5\u540d\uff0c\u5728\u9526\u6807\u8d5b\u5f00\u59cb\u524d\u5b8c\u6210\u3002<\/li>\n<li>\u4f7f\u7528\u73b0\u91d1\u6216\u536b\u661f\u8d5b\u83b7\u5f97\u7684\u95e8\u7968\u5165\u573a\u3002<\/li>\n<\/ul>\n<p>\u5728\u9526\u6807\u8d5b\u5927\u5385\u4e2d\u67e5\u627e\u201c\u6ce1\u6cab\u671f\u4fdd\u969c\u201d\u56fe\u6807\uff0c\u67e5\u770b\u8be5\u9009\u9879\u662f\u5426\u53ef\u7528\u3002<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bce7269-collapse-9\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bce7269-collapse-9\"\n                        id=\"accordion-6a03d8bce7269-heading-9\">\n                    <div class=\"cp-accordion-heading-text\">\u54ea\u91cc\u53ef\u4ee5\u627e\u5230\u73b0\u91d1\u684c\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bce7269-collapse-9\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bce7269-heading-9\"\n                     data-cp-parent=\"#accordion-6a03d8bce7269\">\n                    <div class=\"cp-accordion-body\">\n                        <ul>\n<li>\u6253\u5f00 CoinPoker \u5e94\u7528\u7a0b\u5e8f\u3002<\/li>\n<li>\u70b9\u51fb\u73b0\u91d1\u684c\u6216\u77ed\u724c\u684c\u3002<\/li>\n<li>\u5728\u8fd9\u4e9b\u6807\u7b7e\u9875\u4e2d\uff0c\u60a8\u5c06\u770b\u5230\u6240\u6709\u53ef\u7528\u7684\u73b0\u91d1\u684c\u3002\u60a8\u53ef\u4ee5\u9009\u62e9\u5fb7\u5dde\u6251\u514b\u548c\u5e95\u6c60\u9650\u6ce8\u5965\u9a6c\u54c8\u7b49\u6e38\u620f\uff0c\u4ee5\u53ca\u6ce8\u989d\u7ea7\u522b\uff08\u4f4e\u3001\u4e2d\u6216\u9ad8\uff09\u3002<\/li>\n<\/ul>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bce7269-collapse-10\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bce7269-collapse-10\"\n                        id=\"accordion-6a03d8bce7269-heading-10\">\n                    <div class=\"cp-accordion-heading-text\">\u4ec0\u4e48\u662f\u201c\u53d1\u4e24\u6b21\u724c\u201d\uff1f\u6211\u8be5\u5982\u4f55\u4f7f\u7528\u5b83\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bce7269-collapse-10\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bce7269-heading-10\"\n                     data-cp-parent=\"#accordion-6a03d8bce7269\">\n                    <div class=\"cp-accordion-body\">\n                        <p>\u5728\u73b0\u91d1\u684c\u4e2d\uff0c\u4e24\u540d\u5728\u6cb3\u724c\u5708\u4e4b\u524d\u5168\u62bc\u7684\u73a9\u5bb6\u53ef\u4ee5\u540c\u610f\u53d1\u591a\u6b21\u516c\u5171\u724c\uff0c\u5c06\u5e95\u6c60\u5206\u6210\u591a\u4efd\u3002<\/p>\n<p>\u6b64\u529f\u80fd\u9002\u7528\u4e8e\u73b0\u91d1\u684c\uff0c\u53ef\u4ee5\u5728\u201c\u724c\u684c\u89c4\u8303\u201d\u533a\u57df\u7684<strong>\u201c\u53d1\u591a\u6b21\u724c\u201d<\/strong>\u4e0b\u627e\u5230\u3002<\/p>\n<p>\u80dc\u7387\u66f4\u9ad8\u7684\u5168\u62bc\u73a9\u5bb6\u53ef\u4ee5\u51b3\u5b9a\u53d1\u591a\u5c11\u6b21\u3002\u7136\u540e\uff0c\u53e6\u4e00\u540d\u73a9\u5bb6\u53ef\u4ee5\u9009\u62e9\u63a5\u53d7\u6216\u62d2\u7edd\u8be5\u63d0\u8bae\u3002<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bce7269-collapse-11\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bce7269-collapse-11\"\n                        id=\"accordion-6a03d8bce7269-heading-11\">\n                    <div class=\"cp-accordion-heading-text\">\u5982\u4f55\u79bb\u5f00\u73b0\u91d1\u684c\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bce7269-collapse-11\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bce7269-heading-11\"\n                     data-cp-parent=\"#accordion-6a03d8bce7269\">\n                    <div class=\"cp-accordion-body\">\n                        <p>\u79fb\u52a8\u5e94\u7528\u7248\uff1a<\/p>\n<ul>\n<li>\u70b9\u51fb\u5de6\u4e0a\u89d2\u7684\uff08\u2630\uff09\u56fe\u6807\u3002<\/li>\n<li>\u9009\u62e9\u201c\u79bb\u5f00\u5ea7\u4f4d\u201d\uff0c\u7136\u540e\u70b9\u51fb<strong>\u201c\u79bb\u5f00\u5ea7\u4f4d\u201d<\/strong>\u6309\u94ae\u8fdb\u884c\u786e\u8ba4\u3002<\/li>\n<\/ul>\n<p>\u73b0\u5728\u518d\u6b21\u70b9\u51fb\uff08\u2630\uff09\u56fe\u6807\uff0c\u7136\u540e\u9009\u62e9<strong>\u201c\u9000\u51fa\u724c\u684c\u201d<\/strong> \u3002<\/p>\n<p>\u5728\u684c\u673a\u7aef\uff1a<\/p>\n<ul>\n<li>\u4ece\u724c\u684c\u7a97\u53e3\u53f3\u4e0a\u89d2\u9009\u62e9\u8bbe\u7f6e\u56fe\u6807\u3002<\/li>\n<li>\u9009\u62e9\u201c\u79bb\u5f00\u5ea7\u4f4d\u201d\u3002<\/li>\n<li>\u70b9\u51fb\u53f3\u4e0a\u89d2\u7684 X \u5373\u53ef\u5b8c\u5168\u5173\u95ed\u7a97\u53e3\u3002<\/li>\n<\/ul>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bce7269-collapse-12\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bce7269-collapse-12\"\n                        id=\"accordion-6a03d8bce7269-heading-12\">\n                    <div class=\"cp-accordion-heading-text\">\u5982\u4f55\u5728\u4e0d\u5145\u503c\u7684\u60c5\u51b5\u4e0b\u73a9\u6251\u514b\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bce7269-collapse-12\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bce7269-heading-12\"\n                     data-cp-parent=\"#accordion-6a03d8bce7269\">\n                    <div class=\"cp-accordion-body\">\n                        <p>\u5982\u679c\u60a8\u60f3\u514d\u8d39\u73a9\u6251\u514b\u800c\u65e0\u9700\u5145\u503c\uff0c\u60a8\u53ef\u4ee5\u73a9\u514d\u8d39\u9526\u6807\u8d5b\u6216\u7ec3\u4e60\u8d5b\u3002<\/p>\n<p>\u8bf7\u6309\u7167\u4ee5\u4e0b\u6b65\u9aa4\u64cd\u4f5c\uff1a<\/p>\n<ul>\n<li>\u6253\u5f00 CoinPoker\uff1a<\/li>\n<li>\u70b9\u51fb<strong>\u201c\u7ec3\u4e60\u8d5b\u201d<\/strong>\u6216<strong>\u201c\u514d\u8d39\u8d5b\u201d<\/strong> \u3002<\/li>\n<li>\u5982\u679c\u60a8\u8fdb\u5165\u7ec3\u4e60\u8d5b\uff0c\u60a8\u53ef\u4ee5\u9009\u62e9\u60a8\u559c\u6b22\u7684\u6a21\u5f0f\uff08\u5fb7\u5dde\u6251\u514b\/\u5e95\u6c60\u9650\u6ce8\u5965\u9a6c\u54c8\uff09\uff0c\u7136\u540e\u8fdb\u5165\u724c\u684c\u5f00\u59cb\u6e38\u620f\u3002<\/li>\n<li>\u5982\u679c\u60a8\u53c2\u52a0\u514d\u8d39\u8d5b\uff0c\u60a8\u53ef\u4ee5\u62a5\u540d\u53c2\u52a0\u9526\u6807\u8d5b\uff0c\u5e76\u5728\u9526\u6807\u8d5b\u5f00\u59cb\u65f6\u5f00\u59cb\u6bd4\u8d5b\u3002<\/li>\n<\/ul>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bce7269-collapse-13\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bce7269-collapse-13\"\n                        id=\"accordion-6a03d8bce7269-heading-13\">\n                    <div class=\"cp-accordion-heading-text\">\u5982\u4f55\u66f4\u6539\u724c\u684c\u80cc\u666f\u548c\u724c\u7ec4\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bce7269-collapse-13\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bce7269-heading-13\"\n                     data-cp-parent=\"#accordion-6a03d8bce7269\">\n                    <div class=\"cp-accordion-body\">\n                        <p>\u5728\u79fb\u52a8\u8bbe\u5907\u4e0a\uff1a<\/p>\n<ul>\n<li>\u9009\u62e9\u60a8\u60f3\u73a9\u7684\u73b0\u91d1\u684c\uff0c\u7136\u540e\u8fdb\u5165\u724c\u684c\u3002<\/li>\n<li>\u70b9\u51fb\uff08\u2630\uff09\u56fe\u6807\u5e76\u9009\u62e9<strong>\u724c\u684c\u4e3b\u9898<\/strong>\u3002<\/li>\n<li>\u6d4f\u89c8\u4e3b\u9898\u3001\u5361\u7247\u6b63\u9762\u548c\u5361\u7247\u80cc\u9762\uff0c\u5e76\u4ece\u8fd9 3 \u4e2a\u9009\u9879\u4e2d\u9009\u62e9\u60a8\u559c\u6b22\u7684\u3002<\/li>\n<\/ul>\n<p>\u5728\u684c\u673a\u7aef\uff1a<\/p>\n<ul>\n<li>\u4ece\u7a97\u53e3\u53f3\u4e0a\u89d2\u9009\u62e9\u8bbe\u7f6e\u9f7f\u8f6e\u56fe\u6807\u3002<\/li>\n<li>\u9009\u62e9<strong>\u724c\u684c\u4e3b\u9898<\/strong>\u4ee5\u8c03\u6574\u724c\u684c\u7684\u89c6\u89c9\u6548\u679c\u3002<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bce7269-collapse-14\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bce7269-collapse-14\"\n                        id=\"accordion-6a03d8bce7269-heading-14\">\n                    <div class=\"cp-accordion-heading-text\">\u5982\u4f55\u5173\u95ed\u97f3\u6548\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bce7269-collapse-14\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bce7269-heading-14\"\n                     data-cp-parent=\"#accordion-6a03d8bce7269\">\n                    <div class=\"cp-accordion-body\">\n                        <p>\u79fb\u52a8\u5e94\u7528\u4e0a\uff1a<\/p>\n<ul>\n<li>\u8fdb\u5165\u73b0\u91d1\u684c\u65f6\uff0c\u70b9\u51fb\u5de6\u4e0a\u89d2\u7684\uff08\u2630\uff09\u56fe\u6807\u3002<\/li>\n<li>\u70b9\u51fb\u724c\u684c\u8bbe\u5b9a\u3002\u5728\u8fd9\u91cc\uff0c\u60a8\u53ef\u4ee5\u7981\u7528\u58f0\u97f3\u9009\u9879\u4ee5\u9759\u97f3\u97f3\u6548\u3002<\/li>\n<\/ul>\n<p>\u5728\u684c\u673a\u7aef\uff1a<\/p>\n<ul>\n<li>\u4ece\u7a97\u53e3\u53f3\u4e0a\u89d2\u9009\u62e9\u8bbe\u7f6e\u9f7f\u8f6e\u56fe\u6807\u3002<\/li>\n<li>\u9009\u62e9<strong>\u724c\u684c\u8bbe\u7f6e\u3002<\/strong><\/li>\n<li>\u9009\u62e9\u201c\u58f0\u97f3\u201d\u4ee5\u8c03\u6574\u724c\u684c\u4e0a\u64ad\u653e\u7684\u58f0\u97f3\u3002<\/li>\n<\/ul>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bce7269-collapse-15\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bce7269-collapse-15\"\n                        id=\"accordion-6a03d8bce7269-heading-15\">\n                    <div class=\"cp-accordion-heading-text\">\u5982\u4f55\u67e5\u770b\u6211\u4e0a\u4e00\u5c40\u724c\u7684\u724c\u5c40\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bce7269-collapse-15\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bce7269-heading-15\"\n                     data-cp-parent=\"#accordion-6a03d8bce7269\">\n                    <div class=\"cp-accordion-body\">\n                        <p>\u70b9\u51fb\u724c\u684c\u4e0a\u7684\u201c\u724c\u5c40\u5386\u53f2\u8bb0\u5f55\u201d\u6309\u94ae\uff0c\u8be5\u6309\u94ae\u7684\u56fe\u6807\u663e\u793a\u4e24\u5f20\u724c\u3002<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bce7269-collapse-16\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bce7269-collapse-16\"\n                        id=\"accordion-6a03d8bce7269-heading-16\">\n                    <div class=\"cp-accordion-heading-text\">\u5982\u4f55\u66f4\u6539\u6e38\u620f\u5185\u8bbe\u7f6e\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bce7269-collapse-16\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bce7269-heading-16\"\n                     data-cp-parent=\"#accordion-6a03d8bce7269\">\n                    <div class=\"cp-accordion-body\">\n                        <p>\u79fb\u52a8\u5e94\u7528\u7248\uff1a<\/p>\n<ul>\n<li>\u9009\u62e9\u73b0\u91d1\u684c\u5e76\u8fdb\u5165\u724c\u684c\u3002<\/li>\n<li>\u70b9\u51fb\u5de6\u4e0a\u89d2\u7684\uff08\u2630\uff09\u56fe\u6807\u3002<\/li>\n<li>\u70b9\u51fb<strong>\u201c\u724c\u684c\u8bbe\u7f6e\u201d<\/strong>\u53ef\u4ee5\u8c03\u6574\u6e38\u620f\u4e2d\u7684\u5404\u79cd\u8bbe\u7f6e\u3002<\/li>\n<\/ul>\n<p>\u5728\u684c\u673a\u7aef\uff1a<\/p>\n<ul>\n<li>\u4ece\u7a97\u53e3\u53f3\u4e0a\u89d2\u9009\u62e9\u8bbe\u7f6e\u9f7f\u8f6e\u56fe\u6807\u3002<\/li>\n<li>\u9009\u62e9<strong>\u724c\u684c\u8bbe\u7f6e\u3002<\/strong><\/li>\n<li>\u5728\u8fd9\u91cc\uff0c\u60a8\u53ef\u4ee5\u8c03\u6574\u8bb8\u591a\u4e0d\u540c\u7684\u6e38\u620f\u5185\u8bbe\u7f6e\u3002<\/li>\n<\/ul>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bce7269-collapse-17\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bce7269-collapse-17\"\n                        id=\"accordion-6a03d8bce7269-heading-17\">\n                    <div class=\"cp-accordion-heading-text\">\u5982\u4f55\u5c06\u804a\u5929\u9759\u97f3\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bce7269-collapse-17\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bce7269-heading-17\"\n                     data-cp-parent=\"#accordion-6a03d8bce7269\">\n                    <div class=\"cp-accordion-body\">\n                        <p><span style=\"font-weight: 400\">\u73b0\u5728\u60a8\u53ef\u4ee5\u76f4\u63a5\u5728\u804a\u5929\u6846\u4e2d\u5c06\u6240\u6709\u7528\u6237\u6216\u65c1\u89c2\u8005\u7684\u804a\u5929\u9759\u97f3\u3002\u60a8\u53ef\u4ee5\u52fe\u9009\u201c\u9759\u97f3\u65c1\u89c2\u8005\u804a\u5929\u201d\u6216\u201c\u9759\u97f3\u6240\u6709\u804a\u5929\u201d\u7684\u590d\u9009\u6846\u3002<\/span><\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bce7269-collapse-18\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bce7269-collapse-18\"\n                        id=\"accordion-6a03d8bce7269-heading-18\">\n                    <div class=\"cp-accordion-heading-text\">\u5982\u4f55\u9690\u85cf\u804a\u5929\u6c14\u6ce1\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bce7269-collapse-18\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bce7269-heading-18\"\n                     data-cp-parent=\"#accordion-6a03d8bce7269\">\n                    <div class=\"cp-accordion-body\">\n                        <ul>\n<li>\u70b9\u51fb\u804a\u5929\u56fe\u6807\u3002<\/li>\n<li>\u70b9\u51fb\uff08&#8230;\uff09\u9009\u9879\uff0c\u60a8\u5c06\u770b\u5230 3 \u4e2a\u9009\u9879\uff1a\u9759\u97f3\u65c1\u89c2\u8005\u804a\u5929\u3001\u9690\u85cf\u804a\u5929\u6c14\u6ce1\u3001\u9759\u97f3\u6240\u6709\u804a\u5929\u3002<\/li>\n<li>\u70b9\u51fb\u201c\u9690\u85cf\u804a\u5929\u6c14\u6ce1\u201d\u5373\u53ef\u5728\u6e38\u620f\u8fc7\u7a0b\u4e2d\u4e0d\u518d\u770b\u5230\u5b83\u4eec\u3002<\/li>\n<\/ul>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bce7269-collapse-19\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bce7269-collapse-19\"\n                        id=\"accordion-6a03d8bce7269-heading-19\">\n                    <div class=\"cp-accordion-heading-text\">\u6253\u724c\u65f6\uff0c\u6211\u8be5\u5982\u4f55\u67e5\u770b\u81ea\u5df1\u7684\u624b\u724c\u5f3a\u5ea6\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bce7269-collapse-19\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bce7269-heading-19\"\n                     data-cp-parent=\"#accordion-6a03d8bce7269\">\n                    <div class=\"cp-accordion-body\">\n                        <p>\u5f53\u60a8\u52a0\u5165\u724c\u684c\u65f6\uff0c\u60a8\u4f1a\u770b\u5230\u60a8\u7684\u5934\u50cf\u65c1\u8fb9\u6709 10 \u4e2a\u6761\u5f62\u7b26\u53f7\uff08IIIIIIIIII\uff09\uff0c\u5b83\u4eec\u4f1a\u6839\u636e\u60a8\u624b\u724c\u5f3a\u5ea6\u53d1\u5149\u3002<\/p>\n<p>\u60a8\u53ef\u4ee5\u70b9\u51fb\u6a2a\u6761\u67e5\u770b\u6240\u6709\u6251\u514b\u724c\u578b\u5217\u8868\uff0c\u5176\u4e2d\u60a8\u5f53\u524d\u7684\u724c\u578b\u5f3a\u5ea6\u4f1a\u7a81\u51fa\u663e\u793a\u3002<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bce7269-collapse-20\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bce7269-collapse-20\"\n                        id=\"accordion-6a03d8bce7269-heading-20\">\n                    <div class=\"cp-accordion-heading-text\">\u6211\u53ef\u4ee5\u5728\u54ea\u91cc\u542f\u7528\u6216\u7981\u7528\u624b\u724c\u5f3a\u5ea6\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bce7269-collapse-20\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bce7269-heading-20\"\n                     data-cp-parent=\"#accordion-6a03d8bce7269\">\n                    <div class=\"cp-accordion-body\">\n                        <ul>\n<li>\u70b9\u51fb\u201c\u724c\u684c\u8bbe\u7f6e\u201d\uff0c\u7136\u540e\u70b9\u51fb\u201c\u624b\u724c\u5f3a\u5ea6\u201d\u3002<\/li>\n<li>\u6839\u636e\u4e2a\u4eba\u559c\u597d\u542f\u7528\u6216\u7981\u7528\u624b\u724c\u5f3a\u5ea6\u3002<\/li>\n<li>\u5982\u679c\u5f00\u542f\u6b64\u529f\u80fd\uff0c\u60a8\u6700\u597d\u7684\u4e94\u5f20\u724c\u5c06\u88ab\u9ad8\u4eae\u663e\u793a\uff0c\u60a8\u7684\u624b\u724c\u5f3a\u5ea6\u5c06\u663e\u793a\u5728\u60a8\u7684\u5934\u50cf\u65c1\u8fb9\u3002<\/li>\n<li>\u5982\u679c\u5f00\u5173\u5173\u95ed\uff0c\u60a8\u7684\u6700\u4f73\u4e94\u5f20\u724c\u65e2\u4e0d\u4f1a\u9ad8\u4eae\u663e\u793a\uff0c\u4e5f\u4e0d\u4f1a\u5728\u60a8\u7684\u5934\u50cf\u65c1\u8fb9\u663e\u793a\u60a8\u7684\u624b\u724c\u5f3a\u5ea6\u3002<\/li>\n<\/ul>\n                    <\/div>\n                <\/div>\n            <\/div>\n                <\/div>\n<\/div>\n\n\n\n<p><\/p>\n\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_redirections_enabled":"","_seopress_redirections_type":"","_seopress_redirections_value":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","editor_notices":[],"_cpsm_do_not_sync":false,"_cpsm_partial_sync":false,"footnotes":""},"topic-category":[457],"class_list":["post-166724","help","type-help","status-publish","hentry","topic-category-gameplay-navigation"],"acf":{"card_image":null,"help_view":["post_login"],"in_app_mode_link":""},"_links":{"self":[{"href":"https:\/\/coinpoker.com\/cn\/wp-json\/wp\/v2\/help\/166724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coinpoker.com\/cn\/wp-json\/wp\/v2\/help"}],"about":[{"href":"https:\/\/coinpoker.com\/cn\/wp-json\/wp\/v2\/types\/help"}],"version-history":[{"count":1,"href":"https:\/\/coinpoker.com\/cn\/wp-json\/wp\/v2\/help\/166724\/revisions"}],"predecessor-version":[{"id":166725,"href":"https:\/\/coinpoker.com\/cn\/wp-json\/wp\/v2\/help\/166724\/revisions\/166725"}],"wp:attachment":[{"href":"https:\/\/coinpoker.com\/cn\/wp-json\/wp\/v2\/media?parent=166724"}],"wp:term":[{"taxonomy":"topic-category","embeddable":true,"href":"https:\/\/coinpoker.com\/cn\/wp-json\/wp\/v2\/topic-category?post=166724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}