{"id":166720,"date":"2026-05-12T11:59:04","date_gmt":"2026-05-12T11:59:04","guid":{"rendered":"https:\/\/coinpoker.com\/cn\/help\/coinpoker-%e8%b4%a6%e6%88%b7%e5%b8%b8%e8%a7%81%e9%97%ae%e9%a2%98%e8%a7%a3%e7%ad%94\/"},"modified":"2026-05-12T12:09:44","modified_gmt":"2026-05-12T12:09:44","slug":"coinpoker-account-faq","status":"publish","type":"help","link":"https:\/\/coinpoker.com\/cn\/help\/coinpoker-account-faq\/","title":{"rendered":"CoinPoker \u8d26\u6237\u5e38\u89c1\u95ee\u9898\u89e3\u7b54"},"content":{"rendered":"\n<div id=\"coinpoker-accordion-block_aeeef056be1869bc8a97a22317af0332\" class=\"coinpoker-accordion\" role=\"region\" aria-label=\"Accordion content\">\n        <div class=\"cp-accordion\" id=\"accordion-6a03d8bd35a9b\">\n                    <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bd35a9b-collapse-1\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bd35a9b-collapse-1\"\n                        id=\"accordion-6a03d8bd35a9b-heading-1\">\n                    <div class=\"cp-accordion-heading-text\">\u5982\u4f55\u8054\u7cfb\u5230 CoinPoker\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bd35a9b-collapse-1\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bd35a9b-heading-1\"\n                     data-cp-parent=\"#accordion-6a03d8bd35a9b\">\n                    <div class=\"cp-accordion-body\">\n                        <p>\u60a8\u53ef\u4ee5\u968f\u65f6\u901a\u8fc7\u7535\u5b50\u90ae\u4ef6 support@coinpoker.com \u4e0e\u6211\u4eec\u8054\u7cfb\u3002<\/p>\n<p>\u5982\u6709\u4efb\u4f55\u5b89\u5168\u76f8\u5173\u4e8b\u5b9c\uff0c\u8bf7\u53d1\u9001\u7535\u5b50\u90ae\u4ef6\u81f3 security@coinpoker.com\u3002<\/p>\n<p>\u5982\u9700\u8fdb\u4e00\u6b65\u4e86\u89e3 CoinPoker\uff0c\u8bf7\u8bbf\u95ee\u6211\u4eec\u7684\u7f51\u7ad9 <a href=\"https:\/\/coinpoker.com\/cn\/\">www.CoinPoker.com<\/a>\u3002<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bd35a9b-collapse-2\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bd35a9b-collapse-2\"\n                        id=\"accordion-6a03d8bd35a9b-heading-2\">\n                    <div class=\"cp-accordion-heading-text\">\u6211\u5fd8\u8bb0\u5bc6\u7801\u4e86\u3002\u6211\u8be5\u5982\u4f55\u91cd\u7f6e\u5b83\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bd35a9b-collapse-2\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bd35a9b-heading-2\"\n                     data-cp-parent=\"#accordion-6a03d8bd35a9b\">\n                    <div class=\"cp-accordion-body\">\n                        <p>\u60a8\u53ef\u4ee5\u6309\u7167\u4ee5\u4e0b\u6b65\u9aa4\u91cd\u7f6e\u60a8\u7684 CoinPoker \u8d26\u6237\u5bc6\u7801\uff1a<\/p>\n<ul>\n<li>\u901a\u8fc7\u684c\u9762\u8f6f\u4ef6\u6216\u79fb\u52a8\u5e94\u7528\u767b\u5f55 CoinPoker\u3002<\/li>\n<li>\u70b9\u51fb\u767b\u5f55\u9875\u9762\u4e0b\u65b9\u7684<strong>\u201c\u5fd8\u8bb0\u5bc6\u7801\uff1f\u201d<\/strong>\u9009\u9879\u3002<\/li>\n<li>\u8bf7\u8f93\u5165\u60a8\u7684\u6ce8\u518c\u90ae\u7bb1\u5730\u5740\uff0c\u7136\u540e\u70b9\u51fb\u201c\u7ee7\u7eed\u201d\u3002<\/li>\n<li>\u5982\u679c\u8be5\u90ae\u7bb1\u5730\u5740\u4e0e CoinPoker \u8d26\u6237\u5339\u914d\uff0c\u6211\u4eec\u5c06\u5411\u8be5\u5730\u5740\u53d1\u9001\u4e00\u5c01\u5305\u542b\u9a8c\u8bc1\u7801\uff08OTP\uff09\u7684\u90ae\u4ef6\u3002<\/li>\n<li>\u8bf7\u8f93\u5165\u65b0\u5bc6\u7801\uff0c\u5e76\u8f93\u5165\u60a8\u6ce8\u518c\u90ae\u7bb1\u4e2d\u6536\u5230\u7684\u9a8c\u8bc1\u7801\uff08OTP\uff09\u3002<\/li>\n<li>\u70b9\u51fb\u201c\u91cd\u7f6e\u5bc6\u7801\u201d\u6309\u94ae\u8fdb\u884c\u91cd\u7f6e\u3002<\/li>\n<\/ul>\n<p>\u8bf7\u7559\u610f\uff1a\u4e3a\u4e86\u786e\u4fdd\u8d26\u6237\u5b89\u5168\uff0c\u6211\u4eec\u5efa\u8bae\u60a8\u5b9a\u671f\u66f4\u6539 CoinPoker \u8d26\u6237\u7684\u5bc6\u7801\u3002\u4e3a\u4e86\u5b89\u5168\u8d77\u89c1\uff0c\u5efa\u8bae\u60a8\u6bcf\u9694\u51e0\u4e2a\u6708\u66f4\u6539\u4e00\u6b21\u5bc6\u7801\u3002<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bd35a9b-collapse-3\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bd35a9b-collapse-3\"\n                        id=\"accordion-6a03d8bd35a9b-heading-3\">\n                    <div class=\"cp-accordion-heading-text\">\u6211\u53ef\u4ee5\u66f4\u6539\u6211\u7684\u7528\u6237\u540d\u5417\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bd35a9b-collapse-3\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bd35a9b-heading-3\"\n                     data-cp-parent=\"#accordion-6a03d8bd35a9b\">\n                    <div class=\"cp-accordion-body\">\n                        <p>\u4e0d\uff0c\u7528\u6237\u540d\u65e0\u6cd5\u66f4\u6539\u3002<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bd35a9b-collapse-4\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bd35a9b-collapse-4\"\n                        id=\"accordion-6a03d8bd35a9b-heading-4\">\n                    <div class=\"cp-accordion-heading-text\">\u6211\u53ef\u4ee5\u66f4\u6539\u6211\u7684\u7535\u5b50\u90ae\u4ef6\u5730\u5740\u5417\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bd35a9b-collapse-4\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bd35a9b-heading-4\"\n                     data-cp-parent=\"#accordion-6a03d8bd35a9b\">\n                    <div class=\"cp-accordion-body\">\n                        <p>\u5982\u679c\u60a8\u9700\u8981\u66f4\u6539\u7535\u5b50\u90ae\u7bb1\u5730\u5740\uff0c\u8bf7\u8054\u7cfb <a href=\"mailto:support@coinpoker.com\">support@coinpoker.com<\/a>\u3002<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bd35a9b-collapse-5\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bd35a9b-collapse-5\"\n                        id=\"accordion-6a03d8bd35a9b-heading-5\">\n                    <div class=\"cp-accordion-heading-text\">\u5982\u4f55\u67e5\u770b\u6211\u7d2f\u8ba1\u83b7\u5f97\u4e86\u591a\u5c11 Coins\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bd35a9b-collapse-5\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bd35a9b-heading-5\"\n                     data-cp-parent=\"#accordion-6a03d8bd35a9b\">\n                    <div class=\"cp-accordion-body\">\n                        <p>\u60a8\u53ef\u4ee5\u6309\u7167\u4ee5\u4e0b\u6b65\u9aa4\u67e5\u770b\u60a8\u7684 Coins\uff1a<\/p>\n<ul>\n<li>\u70b9\u51fb CoinPoker \u5ba2\u6237\u7aef\uff08\u684c\u9762\u7248\u6216\u79fb\u52a8\u7248\uff09\u53f3\u4e0a\u89d2\u7684\u94b1\u5305\u56fe\u6807\u3002<\/li>\n<li>\u70b9\u51fb<strong>\u201cCoins \u8ffd\u8e2a\u201d<\/strong>\u3002\u5728\u8fd9\u91cc\uff0c\u60a8\u53ef\u4ee5\u67e5\u770b\u5728\u6307\u5b9a\u65f6\u95f4\u6bb5\u5185\u73a9\u6251\u514b\u6e38\u620f\u6240\u83b7\u5f97\u7684\u603b Coins \u6570\u3002<\/li>\n<\/ul>\n<p><strong>\u8bf7\u7559\u610f<\/strong>\uff1a\u60a8\u53ef\u4ee5\u70b9\u51fb\u5de6\u4e0a\u89d2\u7684\u7b5b\u9009\u5668\uff0c\u6309\u6e38\u620f\u548c\u65e5\u671f\u8fdb\u884c\u7b5b\u9009\u3002\u8bf7\u6ce8\u610f\uff0c\u60a8\u53ea\u80fd\u67e5\u8be2\u8fc7\u53bb 3 \u4e2a\u6708\u5185\u751f\u6210\u7684 Coins\u3002<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bd35a9b-collapse-6\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bd35a9b-collapse-6\"\n                        id=\"accordion-6a03d8bd35a9b-heading-6\">\n                    <div class=\"cp-accordion-heading-text\">\u6211\u6536\u5230\u4e86\u4fc3\u9500\u90ae\u4ef6\uff0c\u5982\u4f55\u53d6\u6d88\u8ba2\u9605\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bd35a9b-collapse-6\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bd35a9b-heading-6\"\n                     data-cp-parent=\"#accordion-6a03d8bd35a9b\">\n                    <div class=\"cp-accordion-body\">\n                        <p>\u5982\u9700\u53d6\u6d88\u8ba2\u9605\u4fc3\u9500\u90ae\u4ef6\uff0c\u8bf7\u70b9\u51fb\u90ae\u4ef6\u4e2d\u7684<strong>\u201c\u53d6\u6d88\u8ba2\u9605\u201d<\/strong>\u9009\u9879\u3002\u82e5\u8981\u5173\u95ed\u5e94\u7528\u63a8\u9001\u901a\u77e5\uff0c\u8bf7\u8fdb\u5165\u624b\u673a\u8bbe\u7f6e\u5e76\u5173\u95ed\u5e94\u7528\u63a8\u9001\u901a\u77e5\u3002<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bd35a9b-collapse-7\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bd35a9b-collapse-7\"\n                        id=\"accordion-6a03d8bd35a9b-heading-7\">\n                    <div class=\"cp-accordion-heading-text\">\u6211\u5fd8\u8bb0\u4e86 CoinPoker \u7684\u7528\u6237\u540d\uff0c\u8be5\u5982\u4f55\u627e\u56de\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bd35a9b-collapse-7\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bd35a9b-heading-7\"\n                     data-cp-parent=\"#accordion-6a03d8bd35a9b\">\n                    <div class=\"cp-accordion-body\">\n                        <p>\u60a8\u53ef\u4ee5\u901a\u8fc7\u67e5\u770b\u6ce8\u518c\u90ae\u7bb1\u6765\u627e\u56de\u60a8\u7684 CoinPoker \u8d26\u6237\u7528\u6237\u540d\u3002\u6211\u4eec\u53d1\u9001\u7ed9\u60a8\u7684\u4efb\u4f55\u5173\u4e8e\u5956\u52b1\u8f6c\u79fb\u6216\u5145\u503c\u7684\u7535\u5b50\u90ae\u4ef6\u90fd\u4f1a\u6ce8\u660e\u60a8\u7684\u7528\u6237\u540d\u3002<\/p>\n<p>\u6216\u8005\uff0c\u60a8\u53ef\u4ee5\u91cd\u7f6e\u5bc6\u7801\uff0c\u6211\u4eec\u4f1a\u5411\u60a8\u53d1\u9001\u4e00\u5c01\u65b0\u90ae\u4ef6\u3002\u8fd9\u610f\u5473\u7740\u60a8\u5c06\u770b\u5230\u60a8\u7684\u7528\u6237\u540d\uff0c\u4f46\u60a8\u8fd8\u9700\u8981\u91cd\u7f6e\u5bc6\u7801\u3002<\/p>\n<ul>\n<li>\u901a\u8fc7\u684c\u9762\u8f6f\u4ef6\u6216\u79fb\u52a8\u5e94\u7528\u767b\u5f55 CoinPoker\u3002<\/li>\n<li>\u70b9\u51fb\u767b\u5f55\u9875\u9762\u4e0b\u65b9\u7684<strong>\u201c\u5fd8\u8bb0\u5bc6\u7801\uff1f\u201d<\/strong>\u9009\u9879\u3002<\/li>\n<li>\u8bf7\u8f93\u5165\u60a8\u7684\u6ce8\u518c\u90ae\u7bb1\u5730\u5740\uff0c\u7136\u540e\u70b9\u51fb\u201c\u7ee7\u7eed\u201d\u3002<\/li>\n<li>\u5982\u679c\u8be5\u90ae\u7bb1\u5730\u5740\u4e0e CoinPoker \u8d26\u6237\u5339\u914d\uff0c\u6211\u4eec\u5c06\u5411\u8be5\u5730\u5740\u53d1\u9001\u4e00\u5c01\u5305\u542b\u9a8c\u8bc1\u7801\uff08OTP\uff09\u7684\u90ae\u4ef6\u3002<\/li>\n<li>\u8bf7\u8f93\u5165\u65b0\u5bc6\u7801\uff0c\u5e76\u8f93\u5165\u60a8\u6ce8\u518c\u90ae\u7bb1\u4e2d\u6536\u5230\u7684\u9a8c\u8bc1\u7801\uff08OTP\uff09\u3002<\/li>\n<li>\u70b9\u51fb\u201c\u91cd\u7f6e\u5bc6\u7801\u201d\u6309\u94ae\u8fdb\u884c\u91cd\u7f6e\u3002<\/li>\n<\/ul>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bd35a9b-collapse-8\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bd35a9b-collapse-8\"\n                        id=\"accordion-6a03d8bd35a9b-heading-8\">\n                    <div class=\"cp-accordion-heading-text\">\u6211\u53ef\u4ee5\u628a\u5bc6\u7801\u5206\u4eab\u7ed9\u5176\u4ed6\u4eba\u4e00\u8d77\u73a9\u5417\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bd35a9b-collapse-8\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bd35a9b-heading-8\"\n                     data-cp-parent=\"#accordion-6a03d8bd35a9b\">\n                    <div class=\"cp-accordion-body\">\n                        <p>\u4e25\u7981\u5c06\u5bc6\u7801\u5206\u4eab\u6216\u900f\u9732\u7ed9\u4efb\u4f55\u5176\u4ed6\u7528\u6237\u3001\u4e2a\u4eba\u3001\u56e2\u4f53\u6216\u4efb\u4f55\u7b2c\u4e09\u65b9\u3002\u82e5\u4ed6\u4eba\u4f7f\u7528\u60a8\u7684\u5bc6\u7801\u8bbf\u95ee\u6216\u5f00\u542f\u60a8\u7684\u8d26\u6237\uff0cCoinPoker \u6982\u4e0d\u8d1f\u8d23\u3002<\/p>\n<p>\u60a8\u9700\u5bf9\u901a\u8fc7\u60a8\u7684\u8d26\u6237\u5728\u5e73\u53f0\u4e0a\u8fdb\u884c\u7684\u6240\u6709\u6d3b\u52a8\u627f\u62c5\u6cd5\u5f8b\u8d23\u4efb\uff0c\u65e0\u8bba\u8fd9\u4e9b\u6d3b\u52a8\u662f\u5426\u7531\u60a8\u672c\u4eba\u5b9e\u65bd\u3002<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bd35a9b-collapse-9\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bd35a9b-collapse-9\"\n                        id=\"accordion-6a03d8bd35a9b-heading-9\">\n                    <div class=\"cp-accordion-heading-text\">\u5982\u4f55\u66f4\u6539\u5bc6\u7801\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bd35a9b-collapse-9\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bd35a9b-heading-9\"\n                     data-cp-parent=\"#accordion-6a03d8bd35a9b\">\n                    <div class=\"cp-accordion-body\">\n                        <p>\u8bf7\u6309\u7167\u4ee5\u4e0b\u6b65\u9aa4\u66f4\u6539\u5bc6\u7801\uff1a<\/p>\n<ul>\n<li>\u5728\u79fb\u52a8\u7aef\u6216\u684c\u9762\u7aef\u5e94\u7528\u4e2d\uff0c\u70b9\u51fb\u60a8\u7684\u5934\u50cf\u5e76\u6253\u5f00<strong>\u201c\u6211\u7684\u8d44\u6599\u201d<\/strong>\uff0c\u5728\u968f\u540e\u51fa\u73b0\u7684\u9875\u9762\u4e0a\uff0c\u70b9\u51fb<strong>\u201c\u8d26\u6237\u5b89\u5168\u201d<\/strong>\u3002<\/li>\n<li>\u70b9\u51fb<strong>\u201c\u66f4\u6539\u5bc6\u7801\u201d<\/strong>\u3002<\/li>\n<li>\u6211\u4eec\u5c06\u5411\u60a8\u6ce8\u518c\u7684\u7535\u5b50\u90ae\u7bb1\u53d1\u9001\u9a8c\u8bc1\u7801\u3002\u8f93\u5165\u9a8c\u8bc1\u7801\uff0c\u7136\u540e\u8f93\u5165\u65b0\u5bc6\u7801\u3002<\/li>\n<li>\u63a5\u4e0b\u6765\uff0c\u70b9\u51fb<strong>\u201c\u7ee7\u7eed\u201d<\/strong>\u6309\u94ae\u91cd\u7f6e\u5bc6\u7801\u3002<\/li>\n<\/ul>\n<p>\u8bf7\u7559\u610f\uff1a\u4e3a\u4e86\u786e\u4fdd\u8d26\u6237\u5b89\u5168\uff0c\u6211\u4eec\u5efa\u8bae\u60a8\u5b9a\u671f\u66f4\u6539 CoinPoker \u8d26\u6237\u7684\u5bc6\u7801\u3002\u4e3a\u4e86\u5b89\u5168\u8d77\u89c1\uff0c\u5efa\u8bae\u60a8\u6bcf\u9694\u51e0\u4e2a\u6708\u66f4\u6539\u4e00\u6b21\u5bc6\u7801\u3002<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bd35a9b-collapse-10\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bd35a9b-collapse-10\"\n                        id=\"accordion-6a03d8bd35a9b-heading-10\">\n                    <div class=\"cp-accordion-heading-text\">\u5982\u4f55\u542f\u7528\u53cc\u91cd\u9a8c\u8bc1\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bd35a9b-collapse-10\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bd35a9b-heading-10\"\n                     data-cp-parent=\"#accordion-6a03d8bd35a9b\">\n                    <div class=\"cp-accordion-body\">\n                        <p>\u8bf7\u6309\u7167\u4ee5\u4e0b\u6b65\u9aa4\u542f\u7528\u53cc\u91cd\u9a8c\u8bc1\uff1a<\/p>\n<ul>\n<li>\u767b\u5f55 CoinPoker\u3002<\/li>\n<li>\u4ece\u9009\u5355\u4e2d\u9009\u62e9<strong>\u201c\u6211\u7684\u4e2a\u4eba\u8d44\u6599\u201d<\/strong>\uff0c\u7136\u540e\u70b9\u51fb<strong>\u201c\u8d26\u6237\u5b89\u5168\u201d<\/strong>\u3002<\/li>\n<li>\u70b9\u51fb\u201c\u5b89\u5168\u5bc6\u7801\u201d\u4ee5\u521b\u5efa\u6216\u4fee\u6539 4 \u4f4d\u6570\u7684\u5bc6\u7801\u3002<\/li>\n<\/ul>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bd35a9b-collapse-11\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bd35a9b-collapse-11\"\n                        id=\"accordion-6a03d8bd35a9b-heading-11\">\n                    <div class=\"cp-accordion-heading-text\">\u5982\u4f55\u66f4\u6539\u6211\u7684\u5934\u50cf\u6216\u4e2a\u4eba\u8d44\u6599\u7167\u7247\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bd35a9b-collapse-11\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bd35a9b-heading-11\"\n                     data-cp-parent=\"#accordion-6a03d8bd35a9b\">\n                    <div class=\"cp-accordion-body\">\n                        <p>\u60a8\u53ef\u4ee5\u6309\u7167\u4ee5\u4e0b\u6b65\u9aa4\u66f4\u6539\u5934\u50cf\uff1a<\/p>\n<ul>\n<li>\u5728CoinPoker\u4e0a\u8fdb\u884c\u6e38\u620f\u65f6\uff0c\u8bf7\u9009\u62e9<strong>\u201c\u724c\u684c\u8bbe\u7f6e\u201d<\/strong>\u3002<\/li>\n<li>\u5728<strong>\u201c\u4e3b\u9898\u201d<\/strong>\u4e0b\u65b9\uff0c\u60a8\u4f1a\u770b\u5230<strong>\u201c\u5934\u50cf\u201d<\/strong>\u3002<\/li>\n<li>\u4ece\u5934\u50cf\u5217\u8868\u4e2d\u6311\u9009\uff0c\u627e\u5230\u60a8\u559c\u6b22\u7684\u6b3e\u5f0f\u3002<\/li>\n<\/ul>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bd35a9b-collapse-12\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bd35a9b-collapse-12\"\n                        id=\"accordion-6a03d8bd35a9b-heading-12\">\n                    <div class=\"cp-accordion-heading-text\">\u4ec0\u4e48\u662f\u7ec3\u4e60\u7b79\u7801\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bd35a9b-collapse-12\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bd35a9b-heading-12\"\n                     data-cp-parent=\"#accordion-6a03d8bd35a9b\">\n                    <div class=\"cp-accordion-body\">\n                        <p>\u7ec3\u4e60\u7b79\u7801\u4e0d\u5177\u5907\u4efb\u4f55\u8d27\u5e01\u4ef7\u503c\uff0c\u4ec5\u7528\u4e8e\u5728\u6e38\u620f\u5927\u5385\u7684\u201c\u6e38\u620f\u5e01\u201d\u4e13\u533a\u7ec3\u4e60\u6251\u514b\u3002<\/p>\n<p>\u60a8\u53ef\u4ee5\u6bcf\u5929\u8865\u5145\u7ec3\u4e60\u7b79\u7801\u3002<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bd35a9b-collapse-13\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bd35a9b-collapse-13\"\n                        id=\"accordion-6a03d8bd35a9b-heading-13\">\n                    <div class=\"cp-accordion-heading-text\">\u5982\u4f55\u67e5\u770b\u6211\u7684\u9526\u6807\u8d5b\u95e8\u7968\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bd35a9b-collapse-13\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bd35a9b-heading-13\"\n                     data-cp-parent=\"#accordion-6a03d8bd35a9b\">\n                    <div class=\"cp-accordion-body\">\n                        <p>\u9002\u7528\u4e8e\u79fb\u52a8\u5e94\u7528\uff1a<\/p>\n<ul>\n<li>\u70b9\u51fb\u5de6\u4e0a\u89d2\u7684\u5934\u50cf\uff0c\u7136\u540e\u70b9\u51fb<strong>\u201c\u6211\u7684\u7968\u52a1\u201d<\/strong>\u3002<\/li>\n<li>\u5728\u8fd9\u91cc\uff0c\u60a8\u5c06\u770b\u5230\u201c\u5f53\u524d\u7968\u5238\u201d\uff0c\u5176\u4e2d\u663e\u793a\u60a8\u7684\u672a\u4f7f\u7528\u7968\u5238\uff1b\u4ee5\u53ca\u201c\u5386\u53f2\u7968\u5238\u201d\uff0c\u5176\u4e2d\u663e\u793a\u60a8\u7684\u5df2\u4f7f\u7528\u548c\u5df2\u8fc7\u671f\u7968\u5238\u3002<\/li>\n<\/ul>\n<p>\u9002\u7528\u4e8e\u684c\u9762\u5ba2\u6237\u7aef\uff1a<\/p>\n<ul>\n<li>\u70b9\u51fb\u53f3\u4e0a\u89d2\u7684\u7528\u6237\u540d\uff0c\u7136\u540e\u70b9\u51fb<strong>\u201c\u6211\u7684\u4e2a\u4eba\u8d44\u6599\u201d<\/strong>\u3002<\/li>\n<li>\u5728\u5de6\u4fa7\u9009\u5355\u4e2d\u70b9\u51fb<strong>\u201c\u6211\u7684\u7968\u52a1\u201d<\/strong>\uff0c\u5373\u53ef\u67e5\u770b\u60a8\u5f53\u524d\u6301\u6709\u7684\u7968\u52a1\u548c\u8fc7\u5f80\u7968\u52a1\u3002<\/li>\n<\/ul>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bd35a9b-collapse-14\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bd35a9b-collapse-14\"\n                        id=\"accordion-6a03d8bd35a9b-heading-14\">\n                    <div class=\"cp-accordion-heading-text\">\u6211\u60f3\u4e86\u89e3\u6211\u7684\u4f59\u989d\u660e\u7ec6\u3002\u6211\u8be5\u5982\u4f55\u67e5\u770b\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bd35a9b-collapse-14\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bd35a9b-heading-14\"\n                     data-cp-parent=\"#accordion-6a03d8bd35a9b\">\n                    <div class=\"cp-accordion-body\">\n                        <p>\u60a8\u53ef\u4ee5\u5728\u5e94\u7528\u7684\u201c\u94b1\u5305\u201d\u680f\u76ee\u4e2d\u67e5\u770b\u4f59\u989d\u660e\u7ec6\u3002\u8fd9\u4e2a\u7ec4\u5408\u5305\u62ec\uff1a<\/p>\n<ol>\n<li><strong>\u603b\u4f59\u989d<\/strong>\uff1a\u8be5\u4f59\u989d\u53ef\u7528\u4e8e\u6240\u6709\u6e38\u620f\u6a21\u5f0f\uff08\u5e76\u5305\u542b\u60a8\u7684\u5145\u503c\u91d1\u989d\uff09\u3002\u6e38\u620f\u7ed3\u675f\u540e\uff0c\u8fd9\u7b14\u91d1\u989d\u53ef\u5168\u989d\u8f6c\u6362\u4e3a\u53ef\u63d0\u73b0\u4f59\u989d\u3002<\/li>\n<li><strong>\u53ef\u63d0\u73b0\u4f59\u989d<\/strong>\uff1a\u6b64\u91d1\u989d\u5305\u542b\u60a8\u7684\u8d62\u5229\u91d1\u989d\uff0c\u4ee5\u53ca\u4ece\u201c\u672a\u4f7f\u7528\u4f59\u989d\u201d\u3001\u201c\u5956\u52b1\u201d\u548c\u201c\u53ef\u91ca\u653e\u5956\u91d1\u201d\u4e2d\u8f6c\u6362\u800c\u6765\u7684\u91d1\u989d\u3002<\/li>\n<li><strong>\u5956\u52b1\u4f59\u989d<\/strong>:\u8fd9\u4ee3\u8868\u4ee5\u4efb\u4f55\u5f62\u5f0f\u83b7\u5f97\u7684\u5956\u52b1\uff0c\u5305\u62ec\u73b0\u91d1\u6392\u884c\u699c\u5956\u54c1\u548c\u201c\u63a8\u8350\u597d\u53cb\u201d\u6d3b\u52a8\u5956\u54c1\u3002\u8fd9\u7b14\u6b3e\u9879\u53ef\u7acb\u5373\u8f6c\u5165\u60a8\u7684\u53ef\u63d0\u73b0\u4f59\u989d\u3002<\/li>\n<li><strong>\u53ef\u89e3\u9501\u5956\u52b1<\/strong>\uff1a\u8be5\u5956\u52b1\u5c06\u6839\u636e\u60a8\u7684\u6e38\u620f\u8fdb\u5ea6\u548c Coins \u83b7\u53d6\u60c5\u51b5\uff0c\u5206\u6279\u8ba1\u5165\u60a8\u7684\u53ef\u63d0\u73b0\u4f59\u989d\u3002<\/li>\n<\/ol>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bd35a9b-collapse-15\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bd35a9b-collapse-15\"\n                        id=\"accordion-6a03d8bd35a9b-heading-15\">\n                    <div class=\"cp-accordion-heading-text\">\u5982\u4f55\u67e5\u770b\u6211\u7684\u4ea4\u6613\u8bb0\u5f55\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bd35a9b-collapse-15\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bd35a9b-heading-15\"\n                     data-cp-parent=\"#accordion-6a03d8bd35a9b\">\n                    <div class=\"cp-accordion-body\">\n                        <p>\u5728\u5ba2\u6237\u7aef\u4e2d\uff0c\u70b9\u51fb\u201c\u94b1\u5305\u201d\u56fe\u6807\uff0c\u7136\u540e\u70b9\u51fb<strong>\u201c\u6211\u7684\u4ea4\u6613\u8bb0\u5f55\u201d<\/strong>\u3002\u5728\u8fd9\u91cc\uff0c\u60a8\u53ef\u4ee5\u67e5\u770b\u5728 CoinPoker \u4e0a\u8fdb\u884c\u7684\u6240\u6709\u4ea4\u6613\u8bb0\u5f55\u3002<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bd35a9b-collapse-16\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bd35a9b-collapse-16\"\n                        id=\"accordion-6a03d8bd35a9b-heading-16\">\n                    <div class=\"cp-accordion-heading-text\">\u5982\u4f55\u67e5\u770b\u6211\u7684\u724c\u5c40\u8bb0\u5f55\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bd35a9b-collapse-16\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bd35a9b-heading-16\"\n                     data-cp-parent=\"#accordion-6a03d8bd35a9b\">\n                    <div class=\"cp-accordion-body\">\n                        <p>\u70b9\u51fb\u5de6\u4e0a\u89d2\u7684\u5934\u50cf\uff0c\u7136\u540e\u70b9\u51fb\u201c<strong>\u6e38\u620f\u8bb0\u5f55<\/strong>\u201d\u3002\u5728\u8fd9\u91cc\uff0c\u60a8\u53ef\u4ee5\u67e5\u770b\u73b0\u91d1\u684c\u548c\u9526\u6807\u8d5b\u7684\u724c\u5c40\u8bb0\u5f55\u3002<\/p>\n<p><strong>\u8bf7\u7559\u610f<\/strong>\uff1a\u60a8\u53ef\u4ee5\u67e5\u770b\u8fc7\u53bb 30 \u5929\u7684\u724c\u5c40\u8bb0\u5f55\u3002<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                        <div class=\"cp-accordion-item\">\n                <button class=\"cp-accordion-button collapsed\"\n                        type=\"button\"\n                        data-cp-toggle=\"collapse\"\n                        data-cp-target=\"#accordion-6a03d8bd35a9b-collapse-17\"\n                        aria-expanded=\"false\"\n                        aria-controls=\"accordion-6a03d8bd35a9b-collapse-17\"\n                        id=\"accordion-6a03d8bd35a9b-heading-17\">\n                    <div class=\"cp-accordion-heading-text\">\u6211\u7684\u94b1\u5305\u4f59\u989d\u662f\u5982\u4f55\u4f7f\u7528\u7684\uff1f<\/div>                <\/button>\n                <div class=\"cp-accordion-border\"><\/div>\n                <div id=\"accordion-6a03d8bd35a9b-collapse-17\"\n                     class=\"cp-accordion-collapse collapse\"\n                     aria-labelledby=\"accordion-6a03d8bd35a9b-heading-17\"\n                     data-cp-parent=\"#accordion-6a03d8bd35a9b\">\n                    <div class=\"cp-accordion-body\">\n                        <p>\u5982\u679c\u60a8\u5728\u201c\u53ef\u63d0\u73b0\u4f59\u989d\u201d\u548c\u201c\u603b\u4f59\u989d\u201d\u4e2d\u5747\u6709\u8d44\u91d1\uff0c\u5f53\u60a8\u8fdb\u5165\u73b0\u91d1\u684c\u6216\u9526\u6807\u8d5b\u724c\u684c\u65f6\uff0c\u7cfb\u7edf\u5c06\u9996\u5148\u4ece\u201c\u53ef\u63d0\u73b0\u4f59\u989d\u201d\u4e2d\u6263\u9664\u76f8\u5e94\u91d1\u989d\uff0c\u7136\u540e\u624d\u4ece\u201c\u603b\u4f59\u989d\u201d\u4e2d\u6263\u9664\u3002<\/p>\n                    <\/div>\n                <\/div>\n            <\/div>\n                <\/div>\n<\/div>\n\n\n\n<p><\/p>\n\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_redirections_enabled":"","_seopress_redirections_type":"","_seopress_redirections_value":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","editor_notices":[],"_cpsm_do_not_sync":false,"_cpsm_partial_sync":false,"footnotes":""},"topic-category":[451],"class_list":["post-166720","help","type-help","status-publish","hentry","topic-category-coinpoker-account"],"acf":{"card_image":null,"help_view":"","in_app_mode_link":""},"_links":{"self":[{"href":"https:\/\/coinpoker.com\/cn\/wp-json\/wp\/v2\/help\/166720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coinpoker.com\/cn\/wp-json\/wp\/v2\/help"}],"about":[{"href":"https:\/\/coinpoker.com\/cn\/wp-json\/wp\/v2\/types\/help"}],"version-history":[{"count":1,"href":"https:\/\/coinpoker.com\/cn\/wp-json\/wp\/v2\/help\/166720\/revisions"}],"predecessor-version":[{"id":166721,"href":"https:\/\/coinpoker.com\/cn\/wp-json\/wp\/v2\/help\/166720\/revisions\/166721"}],"wp:attachment":[{"href":"https:\/\/coinpoker.com\/cn\/wp-json\/wp\/v2\/media?parent=166720"}],"wp:term":[{"taxonomy":"topic-category","embeddable":true,"href":"https:\/\/coinpoker.com\/cn\/wp-json\/wp\/v2\/topic-category?post=166720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}